{"id":121930,"date":"2019-12-27T10:28:42","date_gmt":"2019-12-27T09:28:42","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/spiaggia-di-grotticelle-sequestrate-opere-abusive-con-eternit-e-denunciati-i-proprietari\/"},"modified":"2023-01-16T18:41:09","modified_gmt":"2023-01-16T17:41:09","slug":"331858-spiaggia-di-grotticelle-sequestrate-opere-abusive-con-eternit-e-denunciati-i-proprietari","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/331858-spiaggia-di-grotticelle-sequestrate-opere-abusive-con-eternit-e-denunciati-i-proprietari\/","title":{"rendered":"Spiaggia di Grotticelle: sequestrate opere abusive con eternit e denunciati i proprietari"},"content":{"rendered":"<h4>L<strong>e costruzioni realizzate non erano in possesso di alcuno tipo di certificazione dal punto di vista urbanistico o edilizio<\/strong> e carenti di qualsivoglia autorizzazione paesaggistica e ambientale<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>VIBO VALENTIA &#8211; Continua incessante l\u2019attivit\u00e0 di vigilanza degli uomini e le donne della Guardia Costiera di Vibo Valentia. Nell\u2019ambito dell\u2019attivit\u00e0 di contrasto all\u2019abusivismo demaniale e ambientale, \u00e8 stata condotta una rilevante attivit\u00e0 di indagine durata svariati mesi al fine di verificare la regolarit\u00e0 di alcuni immobili presenti su <strong>una delle spiagge pi\u00f9 suggestive e frequentate della \u201cCosta degli Dei\u201d, precisamente la spiaggia di Grotticelle<\/strong> nel Comune di Ricadi a Vibo. L\u2019attivit\u00e0 condotta dalla Guardia Costiera ha portato ad individuare, e porre sotto sequestro penale, <strong>un gruppo di immobili realizzati senza alcun titolo<\/strong> ed in totale spregio delle pertinenti norme vigenti in un\u2019area, tra l\u2019altro, sottoposta al vincolo paesaggistico-ambientale. L\u2019indagine ha permesso di accertare che <strong>le costruzioni realizzate non erano in possesso di alcuno tipo di certificazione dal punto di vista urbanistico o edilizio<\/strong> e carenti di qualsivoglia autorizzazione paesaggistica e ambientale.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-331861 size-full\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/12\/Grotticelle3.jpg\" alt=\"\" width=\"900\" height=\"581\" title=\"\"><\/p>\n<p>Nel corso delle indagini la Guardia Costiera ha altres\u00ec accertato che alcuni immobili presentavano <strong>coperture in eternit, in pi\u00f9 punti deteriorato e frantumato, pertanto pericoloso per la pubblica salute<\/strong>; eternit quest\u2019ultimo non rimosso dagli interessati bench\u00e9 ne fosse gi\u00e0 stata intimata la rimozione. <strong>I proprietari sono stati denunciati penalmente<\/strong> alla competente Procura della Repubblica di Vibo Valentia per i reati di cui all\u2019art. 54 e 55 del codice navigazione per aver realizzato nuove opere entro la zona dei trenta metri dal confine con il demanio, per violazione dell\u2019art. 734 del codice penale per<strong> deturpamento di bellezze naturali<\/strong>, per violazione del decreto legislativo n. 42\/2004 in materia di tutela dei beni paesaggistici e per la violazione dell\u2019art 650 del codice penale per la mancata rimozione dell\u2019eternit.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-331860 size-full\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/12\/Grotticelle2.jpg\" alt=\"\" width=\"900\" height=\"539\" title=\"\"><\/p>\n<p>L\u2019intervento condotto dai militari della Guardia Costiera ha quindi consentito l\u2019accertamento dell\u2019ennesimo reato commesso ai <strong>danni dell\u2019ambiente costiero in una area di altissimo pregio paesaggistico<\/strong> ed altamente frequentata nel corso della stagione balneare. Tale attivit\u00e0 rappresenta un ulteriore epilogo di quella gi\u00e0 effettuata nel mese di giugno sulla medesima area, finalizzata alla tutela dell\u2019ambiente costiero calabrese minacciato da condotte indiscriminate e senza scrupoli da parte <strong>dei &#8220;nemici&#8221; dell\u2019ambiente.<\/strong> L\u2019attivit\u00e0 di tutela dell\u2019ambiente da parte della Guardia Costiera, proseguir\u00e0 senza soluzione di continuit\u00e0 al fine di salvaguardare e preservare lo stesso garantendone la fruibilit\u00e0 per la collettivit\u00e0.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le costruzioni realizzate non erano in possesso di alcuno tipo di certificazione dal punto di vista urbanistico o edilizio e carenti di qualsivoglia autorizzazione paesaggistica e ambientale<\/p>\n","protected":false},"author":22,"featured_media":121931,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-121930","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/121930","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=121930"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/121930\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/121931"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=121930"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=121930"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=121930"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}