{"id":122085,"date":"2019-12-30T13:07:03","date_gmt":"2019-12-30T12:07:03","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/cariati-filomena-greco-ritira-le-dimissioni-mi-giudichi-un-tribunale-e-non-la-piazza\/"},"modified":"2023-01-16T18:41:20","modified_gmt":"2023-01-16T17:41:20","slug":"332285-cariati-filomena-greco-ritira-le-dimissioni-mi-giudichi-un-tribunale-e-non-la-piazza","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/332285-cariati-filomena-greco-ritira-le-dimissioni-mi-giudichi-un-tribunale-e-non-la-piazza\/","title":{"rendered":"Cariati, Filomena Greco ritira le dimissioni &#8220;mi giudichi un tribunale e non la piazza&#8221;"},"content":{"rendered":"<h4>Con una lettera aperta il sindaco di Cariati ha annunciato di aver ritirato le dimissioni chiedendo di essere giudicata nei tribunali e non nelle piazze, soprattutto quelle virtuali. E fa suo l&#8217;appello lanciato da Gratteri &#8220;non voglio che le mie dimissioni vengano ancora strumentalizzate dagli sciacalli e portatori d&#8217;odio&#8221; <!--more--><u><\/u><\/h4>\n<p style=\"font-weight: 400;\"><span style=\"color: #ffffff;\"><strong>.<\/strong><\/span><\/p>\n<p style=\"font-weight: 400;\">CARIATI (CS) \u2013 Lettera aperta del Sindaco Filomena Greco protocollata oggi, luned\u00ec 30 dicembre, e i<strong>ndirizzata al Presidente del Consiglio Comunale di Cariati, al Segretario Comunale di Cariati e al Prefetto di Cosenza<\/strong>.<\/p>\n<p style=\"font-weight: 400;\">&#8220;Io sottoscritta Filomena Greco con la presente comunico formalmente alle SS.LL. che le mie dimissioni dalla carica di Sindaco del Comune di Cariati protocollate in data 10 dicembre 2019<strong> sono da intendersi con la presente annullate e revocate<\/strong>; da ci\u00f2 consegue la loro assoluta e totale inefficacia ai sensi di legge.\u00a0Ho assunto tale decisione a seguito dei numerosi appelli da parte della comunit\u00e0 che per ben due volte mi ha voluta Sindaco di questa Citt\u00e0 ma soprattutto a seguito delle parole pronunciate nei giorni scorsi dal magistrato Nicola Gratteri, del quale ogni calabrese pu\u00f2 andare fiero ed orgoglioso, parole che sono state la goccia positiva e straordinaria che ha fatto traboccare in me il vaso simbolico di riflessioni, di motivazioni e della voglia di legalit\u00e0, trasparenza e di riscatto che non riesco n\u00e9 frenare n\u00e9 tanto meno a zittire&#8221;.<\/p>\n<p style=\"font-weight: 400;\">&#8220;Potevamo essere in altri posti pi\u00f9 prestigiosi &#8211; si legge ancora nella missiva &#8211; , ma abbiamo detto no perch\u00e9 vogliamo cambiare la Calabria, perch\u00e9 i nostri figli sono fuori dalla Calabria e non torneranno, perch\u00e9 non hanno speranze, e questo \u00e8 un fallimento per noi calabresi. Non possiamo pi\u00f9 consentire queste cose: e allora, fino all&#8217;ultimo dei nostri giorni dobbiamo lottare e non rassegnarci, bisogna dire basta.\u00a0<strong>Faccio, quindi, mio quell&#8217;appello, chiedendo anzi tutto e pubblicamente di essere immediatamente sottoposta a processo<\/strong>; perch\u00e9 in quella sede,<strong> non certo nelle piazze mediatiche messe in piedi dai protagonisti del fallimento sociale, culturale, politico ed economico della nostra comunit\u00e0<\/strong>, voglio dimostrare la mia totale estraneit\u00e0 a tutto ci\u00f2 che mi viene contestato. Ma soprattutto perch\u00e9 n<strong>on voglio che le mie dimissioni vengano ancora strumentalizzate dagli sciacalli e portatori d&#8217;odio<\/strong> che Cariati conosce ormai da pi\u00f9 generazioni&#8221;.<\/p>\n<p><a href=\"https:\/\/quicosenza.it\/news\/8699\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-324840\" src=\"https:\/\/quicosenza.it\/news\/8699\" alt=\"\" width=\"530\" height=\"344\" title=\"\"><\/a><\/p>\n<p style=\"font-weight: 400;\">&#8220;Non riesco a contare<strong> le telefonate ed i messaggi di affetto, di stima, di sostegno, di amicizia e di incoraggiamento ad andare avanti<\/strong> &#8211; sottolinea la Greco &#8211;\u00a0 che in queste settimane mi sono giunte da tutti coloro che mi conoscono e dalle tantissime concittadine e concittadini che non vogliono perdere la speranza di contribuire insieme al cambiamento avviato.\u00a0 La stessa speranza di rappresentare una seria alternativa di sviluppo e progresso per Cariati che mi \u00e8 stata testimoniata, con passione, volont\u00e0, spirito e prospettiva unanime, sia dalla maggioranza consiliare che ha sostenuto fino ad oggi la squadra di governo, e chiunque di questo sostegno deve farsene definitivamente una ragione, senza se e senza ma; sia del popolo delle donne della mia citt\u00e0 che mi hanno destinato nei giorni scorsi un appello accorato, intriso e carico di emozioni e di lucidit\u00e0, chiedendomi\u00a0 di proseguire insieme a loro il percorso virtuoso e di rottura condiviso fino ad oggi, pur tra mille difficolt\u00e0, interferenze ed ostruzionismi di ogni natura; sia dell&#8217;intero popolo de l&#8217;Alternativa che per ben\u00a0 due volte mi ha voluto alla guida di Cariati&#8221;.<\/p>\n<p style=\"font-weight: 400;\">&#8220;<strong>Non possiamo lasciare Cariati ed il suo avvenire nelle mani di quanti, negli ultimi 50 anni, lo hanno distrutto e ridotto nelle condizioni in cui lo abbiamo ereditato<\/strong>. N\u00e9 possiamo lasciarlo nelle mani dei quei burocrati che dall&#8217;interno hanno contribuito a far sprofondare la macchina comunale e l&#8217;intera comunit\u00e0.\u00a0\u00c8 per queste ragioni che continueremo a chiedere pubblicamente a tutte le istituzioni sovra comunali, in primis al Ministero dell&#8217;Interno, di sostenere il complicato processo di cambiamento, di efficientamento, di risanamento, di ammodernamento, di rotazione e quindi di trasparenza e di legalit\u00e0 dei piccoli comuni come il nostro. Senza lo Stato al fianco le autonomie locali non riusciranno e disincrostare il peggio accumulatosi nei cassetti e dietro le scrivanie di gente che ha lavorato per se stessa, contro lo Stato e contro le loro stesse comunit\u00e0.\u00a0<strong>Non possiamo pi\u00f9 tollerare che resti in piedi quel muro di gomma che i cariatesi hanno subito fino ad oggi sulla somma di nefandezze, illegalit\u00e0, soprusi, privilegi, ruberie, illegittimit\u00e0 amministrative e palesi violazioni<\/strong> di cui si sono resi attori protagonisti la quasi totalit\u00e0 degli amministratori del passato, insieme a lacch\u00e8, parenti e raccomandati del cerchio magico. Bisogna far sapere tutto ed i responsabili dovranno pagare di tasca propria per i danni economici arrecati alla casse comunali. Questo \u00e8 ci\u00f2 che chiedono i cittadini di Cariati\u00a0 &#8211; scrive la Greco &#8211; ed \u00e8 ci\u00f2 per cui continueremo a combattere: legalit\u00e0 e trasparenza. Effettivamente occorre fare chiarezza su molti, tanti, perch\u00e9 ancora senza risposta. <strong>C&#8217;\u00e8 una popolazione intera che ha manifestato la volont\u00e0 di riprendere in mano la vita ed il destino di Cariati<\/strong>, con lo stesso entusiasmo che ha caratterizzato il popolo de L&#8217;Alternativa qualche anno fa ed il cui programma che si \u00e8 cercato in tutti i modi di frenare resta comunque l&#8217;unico in grado di restituire fiducia, speranza e protagonismo civico alla comunit\u00e0. <strong>Lo devo anzi tutto alle mie concittadine e ai miei concittadini ma anche ai valori ed ai principi che mi hanno trasmesso i miei genitori&#8221;<\/strong>.<\/p>\n<p style=\"font-weight: 400;\">&#8221; Per tutti questi motivi &#8211; conclude la lettera &#8211; sui quali ho lungamente riflettuto insieme alla mia citt\u00e0 in queste settimane, ritiro le mie dimissioni da Sindaco, c<strong>onfido nella giustizia e nell&#8217;attivit\u00e0 della magistratura e vado avanti con il popolo di Cariati<\/strong> per continuare ad essere a servizio della legalit\u00e0, della trasparenza, della correttezza amministrativa, della tutela dei diritti fondamentali e di cittadinanza e dello sviluppo ordinato, virtuoso ed eco-sostenibile della nostra Citt\u00e0, del territorio e della nostra terra&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con una lettera aperta il sindaco di Cariati ha annunciato di aver ritirato le dimissioni chiedendo di essere giudicata nei tribunali e non nelle piazze, soprattutto quelle virtuali. E fa suo l&#8217;appello lanciato da Gratteri &#8220;non voglio che le mie dimissioni vengano ancora strumentalizzate dagli sciacalli e portatori d&#8217;odio&#8221;<\/p>\n","protected":false},"author":55,"featured_media":122086,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[572,28],"tags":[],"class_list":["post-122085","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ionio","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/122085","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=122085"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/122085\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/122086"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=122085"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=122085"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=122085"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}