{"id":122178,"date":"2020-01-02T12:09:27","date_gmt":"2020-01-02T11:09:27","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/il-prefetto-di-cosenza-finisce-agli-arresti-domiciliari\/"},"modified":"2023-01-16T17:50:20","modified_gmt":"2023-01-16T16:50:20","slug":"332623-il-prefetto-di-cosenza-finisce-agli-arresti-domiciliari","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/332623-il-prefetto-di-cosenza-finisce-agli-arresti-domiciliari\/","title":{"rendered":"Il prefetto di Cosenza Paola Galeone finisce agli arresti domiciliari"},"content":{"rendered":"<h4>Il ministro dell&#8217;Interno Luciana Lamorgese ha disposto la sospensione dal servizio del prefetto di Cosenza Paola Galeone ai sensi dell&#8217;articolo 91 del decreto del Presidente della Repubblica 10 gennaio 1957, n. 3. Lo rende noto il Viminale<br \/>\n<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; Sar\u00e0 ristretta in regime di arresti domiciliari nella sua abitazione di Taranto, in Puglia, l&#8217;ormai ex prefetto di Cosenza Paola Galeone, per &#8220;<strong>induzione indebita a dare o promettere utilit\u00e0<\/strong>&#8220;. La vicenda \u00e8 relativa ad <span style=\"color: #0000ff;\"><strong><a style=\"color: #0000ff;\" href=\"https:\/\/quicosenza.it\/news\/9149\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color: #0000ff;\">una mazzetta ricevuta<\/span><\/a><\/strong><\/span> pochi giorni dopo Natale dall&#8217;imprenditrice cosentina Cinzia Falcone. Secondo fonti accreditate al momento Paola Galeone sarebbe stata fatta rientrare in <strong>Prefettura a Cosenza<\/strong>, alla quale la Polizia di Stato ha notificato la misura cautelare e nelle prossime ore <strong>avverr\u00e0 il trasferimento nel proprio appartamento che si trova a Taranto<\/strong>.\u00a0La conferma \u00e8 arrivata dopo la <strong>nostra anticipazione pochi minuti fa<\/strong> con una nota della Procura della Repubblica di Cosenza, guidata da Mario Spagnuolo nella quale si evidenzia che oggi, la Squadra mobile di Cosenza ha eseguito la misura cautelare degli arresti domiciliari, emessa dal Gip.<\/p>\n<p>Paola Galeone, prefetto di Cosenza, \u00e8 accusata del reato di cui <strong>all&#8217;art. 319 quater c.p.<\/strong>, commesso tra il\u00a0 23 e il 28 dicembre scorsi. &#8220;Il procedimento penale \u00e8 stato iscritto a seguito di una denuncia presentata alla Squadra mobile di Cosenza presentata lo scorso 23 dicembre da un privato cittadino. La procura &#8211; riporta la nota &#8211; nell&#8217;assumere nell&#8217;immediatezza la direzione delle indagini, ha disposto una <strong>serie di riscontri<\/strong>, operati con prontezza e professionalit\u00e0 dalla Squadra mobile che hanno positivamente confermato l&#8217;ipotesi di accusa. L&#8217;indagine &#8211; fanno sapere dalla Procura &#8211; prosegue al fine di accertare eventuali ulteriori fatti penalmente rilevanti&#8221;.<\/p>\n<p>Il ministro dell&#8217;Interno Luciana Lamorgese ha disposto la sospensione dal servizio del prefetto di Cosenza Paola Galeone ai sensi dell&#8217;articolo 91 del decreto del Presidente della Repubblica 10 gennaio 1957, n. 3. Lo rende noto il Viminale.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il ministro dell&#8217;Interno Luciana Lamorgese ha disposto la sospensione dal servizio del prefetto di Cosenza Paola Galeone ai sensi dell&#8217;articolo 91 del decreto del Presidente della Repubblica 10 gennaio 1957, n. 3. Lo rende noto il Viminale<\/p>\n","protected":false},"author":42,"featured_media":122179,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[42],"tags":[],"class_list":["post-122178","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/122178","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=122178"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/122178\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/122179"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=122178"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=122178"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=122178"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}