{"id":122257,"date":"2020-01-05T17:00:28","date_gmt":"2020-01-05T16:00:28","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/aiello-ha-scelto-il-cielo-di-roma-per-debuttare-nel-2020\/"},"modified":"2023-01-16T17:50:26","modified_gmt":"2023-01-16T16:50:26","slug":"332839-aiello-ha-scelto-il-cielo-di-roma-per-debuttare-nel-2020","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/332839-aiello-ha-scelto-il-cielo-di-roma-per-debuttare-nel-2020\/","title":{"rendered":"Aiello ha scelto &#8216;il cielo&#8217; di Roma per debuttare nel 2020"},"content":{"rendered":"<h4>Aiello il nuovo singolo \u00e8 estratto dall&#8217;album Ex Voto. Il tour riprender\u00e0 il 21 marzo dal Fabrique di Milano<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; Aiello inizia il nuovo anno con \u201cIl cielo di Roma\u201d, il singolo estratto dal suo album d\u2019esordio \u201cEx Voto\u201d, dal 1\u00b0 gennaio 2020 in rotazione radiofonica. Un brano dedicato alla citt\u00e0 eterna che racconta l\u2019intimo legame che unisce l\u2019artista alla capitale. Fissare la notte, salire su un tetto, toccare le stelle, contemplare le lucciole, tutto questo accade sotto il cielo pi\u00f9 ispirazionale del mondo. Il brano \u00e8 forse il pi\u00f9 evocativo dell\u2019intero disco, senza dubbio una fotografia inedita della citt\u00e0 eterna.<\/p>\n<div id=\"attachment_332843\" style=\"width: 601px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-332843\" class=\"wp-image-332843 size-large\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2020\/01\/Aiello-591x400.jpg\" alt=\"Aiello\" width=\"591\" height=\"400\" title=\"\"><p id=\"caption-attachment-332843\" class=\"wp-caption-text\">La svolta nel 2016, quando Antonio comincia a dedicarsi al canto, fondendo alle note della sua musica il ritmo variegato della sua voce.<\/p><\/div>\n<p>Dopo il tutto esaurito della data di Napoli dell\u2019Ex Voto Tour 2020, i numerosi successi del 2019, i sold out delle anteprime di Milano e Roma registrate in meno di 48 ore, aver superato 11,5 milioni di stream su Spotify e6 milioni di visualizzazioni su YouTube con \u201cArsenico\u201d, collezionato oltre 7 milioni di stream con \u201cLa mia ultima storia&#8221;, <a href=\"https:\/\/quicosenza.it\/news\/9177\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color: #3366ff;\">Aiello torna in radio<\/span><\/a> con un brano in grado di mostrare un nuovo lato della sua scrittura della sua anima. Questo singolo \u00e8 il primo passo che il <a href=\"https:\/\/quicosenza.it\/news\/9099\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color: #3366ff;\">cantautore cosentino<\/span><\/a> muove in un 2020 gi\u00e0 ricco di impegni ed emozioni, dal 21 marzo, infatti, partir\u00e0 da Milano il tour che lo porter\u00e0 nei club delle maggiori citt\u00e0 italiane.<\/p>\n<p><strong>CALENDARIO DATE<\/strong><br \/>\nSabato 21 marzo 2020 | MILANO @ Fabrique<br \/>\nMercoled\u00ec 25 marzo 2020 | Venaria Reale (TO) @ Teatro della Concordia<br \/>\nDomenica 29 marzo 2020 | Nonantola (MO) @ Vox<br \/>\nGioved\u00ec 02 aprile 2020 | FIRENZE @ Tuscany Hall<br \/>\nLuned\u00ec 06 aprile 2020 | NAPOLI @ Casa della Musica \u2013 SOLD OUT<br \/>\nGioved\u00ec 09 aprile 2020 | ROMA @ Atlantico Live<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aiello il nuovo singolo \u00e8 estratto dall&#8217;album Ex Voto. Il tour riprender\u00e0 il 21 marzo dal Fabrique di Milano<\/p>\n","protected":false},"author":20,"featured_media":122258,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[40],"tags":[],"class_list":["post-122257","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura-spettacolo"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/122257","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=122257"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/122257\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/122258"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=122257"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=122257"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=122257"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}