{"id":122491,"date":"2020-01-08T19:34:38","date_gmt":"2020-01-08T18:34:38","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/aree-pedonali-nei-pressi-degli-edifici-scolastici-bando-per-tutti-i-comuni-calabresi\/"},"modified":"2023-01-16T17:50:41","modified_gmt":"2023-01-16T16:50:41","slug":"333533-aree-pedonali-nei-pressi-degli-edifici-scolastici-bando-per-tutti-i-comuni-calabresi","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/333533-aree-pedonali-nei-pressi-degli-edifici-scolastici-bando-per-tutti-i-comuni-calabresi\/","title":{"rendered":"Aree pedonali nei pressi degli edifici scolastici. Bando per tutti i comuni calabresi"},"content":{"rendered":"<h4 class=\"entry-title\"><strong> L&#8217;obiettivo \u00e8 migliorare in maniera significativa la vivibilit\u00e0 dei centri urbani attraverso la riduzione o l\u2019azzeramento del traffico in prossimit\u00e0 delle scuole e aumentare anche la sicurezza<\/strong><\/h4>\n<p><!--more--><\/p>\n<p><span style=\"color: #ffffff;\">.<\/span><\/p>\n<p>COSENZA &#8211; <span class=\"primamaiuscola\">C<\/span>on Decreto dirigenziale n. 16275 del 18\/12\/2019 \u00e8 stata approvata la manifestazione di interesse per la concessione di <strong>contributi finalizzati alla realizzazione di aree in prossimit\u00e0 degli edifici scolastici<\/strong> (zone a traffico limitato). Si tratta di un avviso aperto a tutti i Comuni calabresi che punta all\u2019attuazione dell\u2019azione 2.4 del Piano regionale dei trasporti (trasporto individuale non motorizzato e zone controllate). La manifestazione di interesse \u00e8 pubblicata sul Burc del 30.12.2019 ed \u00e8 consultabile al <span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/quicosenza.it\/news\/9217\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>seguente link<\/strong><\/a><\/span>).<\/p>\n<p>L\u2019azione mira a<strong> realizzare aree pedonalizzate nelle aree limitrofe agli edifici scolastici<\/strong>, con l\u2019obiettivo di migliorare la vivibilit\u00e0 e la fruibilit\u00e0 dei centri urbani. Essa costituisce una<strong> estensione a livello di scala di isolato o di quartiere degli interventi di messa in sicurezza degli edifici scolastici<\/strong>, gi\u00e0 avviati nell\u2019ambito del programma \u201cscuola sicura\u201d. Per i Comuni di maggiori dimensione questa azione, integrata con l\u2019azione sulla city logistics per cui \u00e8 in atto una manifestazione di interesse di prossima scadenza (consultabile a <span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/quicosenza.it\/news\/9218\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>questo link<\/strong><\/a><\/span> ) consente di <strong>migliorare in maniera significativa la vivibilit\u00e0 dei centri urbani attraverso la riduzione o l\u2019azzeramento del traffico al fine di abbattere l\u2019inquinamento in prossimit\u00e0 delle scuole e aumentare la sicurezza<\/strong>. I Comuni potranno presentare istanze (entro il 28 febbraio 2020) per interventi in aree limitrofe ad edifici scolastici gi\u00e0 adeguati ai sensi delle norme tecniche delle costruzioni NTC 2008 o NTC 2018 o per gli edifici che saranno adeguati entro il 31 dicembre 2020.<\/p>\n<p>Si tratta degli <strong>edifici gi\u00e0 adeguati o in corso di adeguamento<\/strong> per i quali con questa azione pu\u00f2 essere significativamente migliorata l\u2019accessibilit\u00e0 e la vivibilit\u00e0 dell\u2019area esterna.La manifestazione di interesse deve essere corredata della condivisione della proposta con il Consiglio di istituto della scuola interessata e pertanto \u00e8 necessario un coinvolgimento significativo dei genitori degli alunni , del corpo docente, del personale amministrativo e del dirigente scolastico. La condivisione costituisce un elemento fondamentale per la riuscita di interventi di questo tipo. Si tratta infatti di interventi che, in qualche caso, modificano significativamente le abitudini giornaliere in quanto provocano un cambiamento nella modalit\u00e0 di accesso e di fruizione del servizio scolastico e degli altri eventuali servizi erogati all\u2019interno dell\u2019edificio scolastico. <strong>Per chiarimenti sui contenuti del bando, oltre che per eventuale supporto nella predisposizione dell\u2019istanza di partecipazione, il Dipartimento Regionale Infrastrutture, Lavori Pubblici e Mobilit\u00e0 ha attivato un servizio di affiancamento per i Comuni, che pu\u00f2 essere richiesto via e-mail all\u2019indirizzo<\/strong> <span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"mailto:logisticaurbana@regione.calabria.it\" target=\"_blank\" rel=\"noopener noreferrer\">logisticaurbana@regione.calabria.it<\/a><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;obiettivo \u00e8 migliorare in maniera significativa la vivibilit\u00e0 dei centri urbani attraverso la riduzione o l\u2019azzeramento del traffico in prossimit\u00e0 delle scuole e aumentare anche la sicurezza<\/p>\n","protected":false},"author":55,"featured_media":122492,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-122491","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/122491","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=122491"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/122491\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/122492"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=122491"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=122491"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=122491"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}