{"id":122542,"date":"2020-01-12T09:00:46","date_gmt":"2020-01-12T08:00:46","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/mormanno-cantabimbo-come-biglietto-da-visita-del-borgo\/"},"modified":"2023-01-16T17:50:44","modified_gmt":"2023-01-16T16:50:44","slug":"333653-mormanno-cantabimbo-come-biglietto-da-visita-del-borgo","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/333653-mormanno-cantabimbo-come-biglietto-da-visita-del-borgo\/","title":{"rendered":"Mormanno, &#8216;Cantabimbo&#8217; come biglietto da visita del borgo"},"content":{"rendered":"<h4>Erre &amp; Friends e l&#8217;associazione musicale &#8216;Heartsoul&#8217; hanno organizzato ancora una volta la kermesse <em>&#8216;Cantabimbo&#8217;<\/em>, storica rassegna dedicata ai pi\u00f9 piccoli. &#8220;La musica ci aiuta a far conoscere le nostre bellezze&#8221;. <!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; A Mormanno sono gi\u00e0 pronti per i preparativi della nuova edizione di Cantabimbo.\u00a0Renato Leone ha manifestato orgoglio per l&#8217;edizione appena conclusa: <em>&#8220;E&#8217; una manifestazione che ogni anno porta nel nostro borgo tantissime persone ricche di entusiasmo. Mormanno \u00e8 tutta da scoprire&#8221;. <\/em>Rlb \u00e8 da anni radio partner dell&#8217;evento.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-333679 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2020\/01\/mormanno-1024x682-601x400.jpg\" alt=\"\" width=\"601\" height=\"400\" title=\"\"><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h2>Mormanno<\/h2>\n<p>L&#8217;antigo borgo di Mormanno, accanto al confine naturale del Parco Nazionale del Pollino, \u00e8 caratterizzato per il suo impianto tipicamente medioevale. Una passeggiata che riempie gli occhi e la mente. A 840 metri di altitudine, un intreccio di angoli suggestivi che incanta. Fondato in et\u00e0 longobarda come presidio tra il ducato di Benevento e il territorio soggetto all&#8217;impero bizantino, \u00e8 ricco di cappelle votive, i numerosi palazzi signorili in pietra locale e soprattutto le tantissime chiese. Il Faro Votivo \u00e8 un <span style=\"color: #00ccff;\"><span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/quicosenza.it\/news\/9223\" target=\"_blank\" rel=\"noopener noreferrer\">simbolo della bellezza<\/a><\/span>,<\/span> del valore storico, artistico e culturale della nostra regione ed il simbolo della cittadina.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-333678 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2020\/01\/bambino-cantare-620x350.jpg\" alt=\"\" width=\"620\" height=\"350\" title=\"\"><\/p>\n<p>&nbsp;<\/p>\n<h2>Cantabimbo<\/h2>\n<p>Cantabimbo non \u00e8 un concorso ma una rassegna musicale. Sabrina Armentano della &#8216;Hertsoul&#8217; sottolinea la differenza: <em>&#8220;Si i nostri piccoli protagonisti sono tutti vincitori. Non \u00e8 assolutamente facile per un bambino affrontare il pubblico, le luci di scena. Il piccolo deve essere stimolato e non messo sotto pressione&#8221;. <\/em>Tutta la macchina organizzativa \u00e8 gi\u00e0 pronta per l&#8217;edizione 2020<em>. <\/em>Anche la direttrice dell&#8217;associazione ha mosso i suoi primi passi cos\u00ec<em>: &#8220;Verissimo, avevo solo tre anni ed oggi per me vivere la rassegna in supporto ai bambini \u00e8 un orgoglio, credo molto nel progetto. Qui tutti ci crediamo tanto&#8221;.\u00a0<\/em><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Erre &amp; Friends e l&#8217;associazione musicale &#8216;Heartsoul&#8217; hanno organizzato ancora una volta la kermesse &#8216;Cantabimbo&#8217;, storica rassegna dedicata ai pi\u00f9 piccoli. &#8220;La musica ci aiuta a far conoscere le nostre bellezze&#8221;.<\/p>\n","protected":false},"author":20,"featured_media":122543,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[40],"tags":[],"class_list":["post-122542","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura-spettacolo"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/122542","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=122542"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/122542\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/122543"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=122542"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=122542"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=122542"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}