{"id":122911,"date":"2020-01-16T05:09:03","date_gmt":"2020-01-16T04:09:03","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/regionali-pastore-ascolto-e-sostegno-alle-piccole-e-medie-imprese\/"},"modified":"2023-01-16T17:51:09","modified_gmt":"2023-01-16T16:51:09","slug":"334764-regionali-pastore-ascolto-e-sostegno-alle-piccole-e-medie-imprese","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/334764-regionali-pastore-ascolto-e-sostegno-alle-piccole-e-medie-imprese\/","title":{"rendered":"Regionali, Pastore: &#8220;ascolto e sostegno alle piccole e medie imprese&#8221;"},"content":{"rendered":"<h4>Incontro con gli esponenti del movimento \u201cLa Calabria che vogliamo\u201d dell\u2019assessore alla Crescita economica e alle Attivit\u00e0 produttive del Comune di Cosenza, candidata nella lista \u201cSantelli presidente\u201d<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; All\u2019incontro anche il presidente della commissione trasporti di Palazzo dei Bruzi, Gisberto Spadafora, il referente del Movimento, l\u2019imprenditore Giuseppe Nucera e, in qualit\u00e0 di economista del territorio e giornalista della stampa estera, il docente universitario prof. Mauro Alvisi. L\u2019occasione \u00e8 stata utile per un confronto serrato sui temi dello sviluppo in Calabria.<\/p>\n<p>Al centro il sostegno alle piccole e medie imprese locali, l\u2019impegno nel migliorare l\u2019immagine e la reputazione della Calabria per arrivare allo sviluppo del settore agroalimentare e turistico quali componenti principali per il rilancio del territorio. Il movimento sostiene l\u2019assessore Pastore alla quale ha dato appuntamento dopo le elezioni per discutere, vista la convergenza su diversi temi, di un percorso futuro comune.<\/p>\n<p>\u201cSono molto soddisfatta da questo incontro \u2013 ha dichiarato l\u2019assessore Pastore \u2013 Stimo molto Nucera come imprenditore e molte delle sue istanze sono simili all\u2019attivit\u00e0 che in questi anni abbiamo portato avanti su Cosenza. Le piccole e medie imprese hanno bisogno del giusto ascolto e sostegno, dobbiamo promuovere le tante eccellenze che abbiamo nel settore agroalimentare, dell\u2019artigianato e delle start up scientifiche dobbiamo trasformare il turismo in una industria dove non c\u2019\u00e8 spazio per l\u2019improvvisazione, dobbiamo lavorare molto sul brand Calabria per invertire gli stereotipi che la frenano. Sono sicura che con il Movimento ci saranno altre occasioni di confronto e lavoro comune\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Incontro con gli esponenti del movimento \u201cLa Calabria che vogliamo\u201d dell\u2019assessore alla Crescita economica e alle Attivit\u00e0 produttive del Comune di Cosenza, candidata nella lista \u201cSantelli presidente\u201d<\/p>\n","protected":false},"author":42,"featured_media":122912,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-122911","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/122911","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=122911"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/122911\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/122912"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=122911"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=122911"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=122911"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}