{"id":122917,"date":"2020-01-16T07:32:00","date_gmt":"2020-01-16T06:32:00","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/il-sesso-orientava-i-processi-petrini-e-i-rapporti-nel-suo-studio-con-le-avvocatesse\/"},"modified":"2023-01-16T17:51:09","modified_gmt":"2023-01-16T16:51:09","slug":"334784-il-sesso-orientava-i-processi-petrini-e-i-rapporti-nel-suo-studio-con-le-avvocatesse","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/334784-il-sesso-orientava-i-processi-petrini-e-i-rapporti-nel-suo-studio-con-le-avvocatesse\/","title":{"rendered":"Il sesso orientava i processi, Petrini e i rapporti nel suo ufficio con le avvocatesse"},"content":{"rendered":"<h4>Orientava i processi in cambio di soldi, utilit\u00e0 e di sesso. Il vizietto di Marco Petrini lo ha portato in carcere nell&#8217;ambito dell&#8217;inchiesta Genesi compiuta ieri<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>CATANZARO &#8211; Gli inquirenti ne hanno documentati una ventina. Rapporti sessuali che il magistrato Petrini aveva con un&#8217;avvocatessa in particolare mentre un&#8217;altra era proprio la sua amante. Rapporti che si consumavano nell&#8217;ufficio del presidente della sezione della Corte d&#8217;Appello di Catanzaro. <strong>Se non era sesso, erano soldi, preziosi, orologi, cene, vacanze<\/strong>. Tutto per &#8216;truccare&#8217; gli esiti dei processi. Marco Petrini nel suo ufficio riceveva e faceva di tutto ed \u00e8 tutto immortalato dalle telecamere: dalle scene degli scambi di soldi a quelle di sesso.<\/p>\n<p>A finire in cella dunque, Marco Petrini per corruzione in atti giudiziari; anche Emilio Santoro detto \u00abMario\u00bb, Luigi Falzetta, l&#8217;ex consigliere regionale Giuseppe Prato Tursi, Francesco Saraco, Vincenzo Arcuri, Giuseppe Caligiuri. La Tassone una delle tre avvocatesse indagate per l&#8217;ipotesi di corruzione sessuale \u00e8 ai domiciliari. <strong>Almeno 16 i rapporti documentati di cui scrive il Gip<\/strong>. Per la posizione di un&#8217;altra avvocatessa, S.P., ripresa in almeno due circostanze in rapporti con il giudice &#8220;la prestazione intima \u00e8 stata usata come una sorta di contropartita rispetto alle sentenze favorevoli adottate dal giudice poich\u00e9 il Petrini, quale presidente della commissione Tributaria provinciale di Catanzaro, intrattenendo relazioni sessuali abituali con l&#8217;avvocato P.S., omettendo di astenersi dal comporre il collegio giudicante nei ricorsi tributari assegnati al suo collegio, nei quali il ricorrente parte privata era patrocinato dall&#8217;avvocato P.S., ha adottato sentenze di accoglimento dei ricorsi presentati dalla summensionata professionista&#8221;.<\/p>\n<p><iframe loading=\"lazy\" title=\"Petrini, sesso e soldi per aggiustare i processi\" width=\"740\" height=\"416\" src=\"https:\/\/www.youtube.com\/embed\/lcD0_o4TDKo?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>L&#8217;avvocatessa Tassone, definita dagli inquirenti l&#8217;amante di Petrini, nella stanza del giudice avrebbe offerto<strong> tre prestazioni sessuali in cambio di un intervento del magistrato su importanti vicende giudiziarie <\/strong>come il rigetto della richiesta della Procura generale di utilizzare il verbale del pentito Emanuele Mancuso, ritenendo &#8220;irrilevanti e inconferenti rispetto ai capi di imputazioni le dichiarazioni\u00bb, in un processo in cui era presente, tra gli altri, l&#8217;avvocatessa Tassone in uno dei collegi difensivi. E ancora &#8220;lo scorso 7 marzo &#8211; scrive la Procura di Salerno &#8211; il giudice Petrini avrebbe promesso di aiutare l&#8217;avvocato Tassone per la difesa di Giuseppe Gualtieri, a sua volta imputato in un duplice omicidio in danno di Francesca Petrolini e Rocco Bava, avvenuto a Davoli nel 2018&#8221;.<\/p>\n<p>L&#8217;ex consigliere regionale calabrese Pino Prato Tursi, riesce a vincere un ricorso per riavere il vitalizio che gli era stato sospeso dopo una condanna. Proprio da questo episodio sarebbero partite le indagini, le intercettazioni, gli appostamenti e il monitoraggio con le telecamere. E del ruolo di Petrini avrebbe parlato anche il pentito Andrea Mantella lo avrebbe definito &#8220;il porco&#8221;, questo per il suo vizietto del sesso ma non solo. Intanto Petrini sar\u00e0 interrogato nel carcere salernitano di Fuorni dove \u00e8 stato portato dopo l&#8217;arresto.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Orientava i processi in cambio di soldi, utilit\u00e0 e di sesso. Il vizietto di Marco Petrini lo ha portato in carcere nell&#8217;ambito dell&#8217;inchiesta Genesi compiuta ieri<\/p>\n","protected":false},"author":42,"featured_media":122918,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-122917","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/122917","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=122917"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/122917\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/122918"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=122917"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=122917"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=122917"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}