{"id":123304,"date":"2020-01-22T16:35:00","date_gmt":"2020-01-22T15:35:00","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/sorical-approvati-i-bilanci-2017-e-2018-dopo-la-ristrutturazione-del-debito\/"},"modified":"2023-01-16T17:51:36","modified_gmt":"2023-01-16T16:51:36","slug":"336035-sorical-approvati-i-bilanci-2017-e-2018-dopo-la-ristrutturazione-del-debito","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/336035-sorical-approvati-i-bilanci-2017-e-2018-dopo-la-ristrutturazione-del-debito\/","title":{"rendered":"Sorical, approvati i bilanci 2017 e 2018 dopo la ristrutturazione del debito"},"content":{"rendered":"<h4>L&#8217;assemblea dei soci ha approvato i bilanci 2017 e 2018 della societ\u00e0 regionale che gestisce gli acquedotti regionali<!--more--><\/h4>\n<p style=\"font-weight: 400;\"><span style=\"color: #ffffff;\">.<\/span><\/p>\n<p style=\"font-weight: 400;\">CATANZARO &#8211;\u00a0L&#8217;assemblea dei soci di Sorical ha <strong>approvato i bilanci 2017 e 2018 della societ\u00e0 regionale<\/strong> che gestisce\u00a0 gli acquedotti regionali.\u00a0L&#8217;approvazione \u00e8 avvenuta a seguito della conclusione dell&#8217;iter di modifica dell&#8217;<strong>accordo di ristrutturazione del debito<\/strong> (Art 182 bis della legge fallimentare). Tale modifica si era resa necessaria a <strong>causa della contrazione degli incassi da parte dei Comuni e per l&#8217;insorgere di alcuni fattori esogeni alla gestione della societ\u00e0<\/strong>, ed in particolare l&#8217;in<strong>cremento del numero dei Comuni calabresi in dissesto finanziario<\/strong>, e il generale peggioramento della situazione finanziaria che ha coinvolto tutte le amministrazioni locali clienti della societ\u00e0.<\/p>\n<p style=\"font-weight: 400;\">L&#8217;Assemblea, nel prendere atto della<strong> ricostituzione dei presupposti per la continuit\u00e0 aziendale<\/strong>, ha approvato, i Bilanci relativi agli anni 2017 e 2018 \u00a0i quali si sono chiusi positivamente evidenziando un utile di esercizio.\u00a0Il socio Regione, in assemblea, ha ribadito la necessit\u00e0 di procedere alla pubblicizzazione della societ\u00e0, aspetto imprescindibile per l&#8217;organizzazione del servizio idrico integrato nell&#8217;intero territorio regionale. I<strong>l socio privato si \u00e8 associato a questa necessit\u00e0, ribadendo \u00a0la volont\u00e0 di cedere la azioni<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;assemblea dei soci ha approvato i bilanci 2017 e 2018 della societ\u00e0 regionale che gestisce gli acquedotti regionali<\/p>\n","protected":false},"author":55,"featured_media":123305,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-123304","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/123304","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=123304"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/123304\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/123305"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=123304"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=123304"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=123304"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}