{"id":123373,"date":"2020-01-23T17:12:14","date_gmt":"2020-01-23T16:12:14","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/tallini-fi-durissimo-e-una-meschina-vendetta-di-morra-ne-rispondera-in-tutte-sedi\/"},"modified":"2023-01-16T17:51:39","modified_gmt":"2023-01-16T16:51:39","slug":"336304-tallini-fi-durissimo-e-una-meschina-vendetta-di-morra-ne-rispondera-in-tutte-sedi","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/336304-tallini-fi-durissimo-e-una-meschina-vendetta-di-morra-ne-rispondera-in-tutte-sedi\/","title":{"rendered":"Tallini (Fi) durissimo &#8220;\u00e8 una meschina vendetta di Morra. Ne risponder\u00e0 in tutte le sedi&#8221;"},"content":{"rendered":"<h4>Non usa mezzi termini Domenico Tallini che attacca Nicola Morra dopo la presentazione delle liste con i cosiddetti &#8220;impresentabili&#8221; nel quale figura il nome del consigliere uscente &#8220;<strong>non \u00e8 la prima volta che questo giacobino di periferia utilizza le istituzioni per demolire i suoi avversari&#8221;<\/strong><!--more--><\/h4>\n<p><span style=\"color: #ffffff;\">.<\/span><\/p>\n<p>COSENZA &#8211; Domenico Tallini, consigliere regionale uscente e candidato alle elezioni di domenica 26 gennaio non ci sta e attacca duramente, con <strong>parole al vetriolo<\/strong>, il presidente della commissione antimafia Nicola Morra dopo la pubblicazione della <span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/quicosenza.it\/news\/9370\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>lista degli&#8221;impresentabili&#8221;<\/strong><\/a><\/span>\u00a0in Emilia e Calabria e nella quale sono finiti Giuseppe Raffa e appunto Tallini<strong>,<\/strong> entrambi di Forza Italia.<\/p>\n<p>&#8220;Il senatore Morra &#8211; scrive in un lungo comunicato Tallini &#8211; <strong>consuma nei miei confronti una meschina vendetta personale<\/strong> per le critiche da me rivoltegli in merito alle sue farneticanti dichiarazioni sul &#8216;rosario&#8217; quale simbolo della mafia.<strong> Non \u00e8 la prima volta che questo giacobino di periferia utilizza le istituzioni per demolire i suoi avversari<\/strong>. E&#8217; ancora fresco il ricordo della trappola indegna ordita contro Mario Occhiuto (sindaco di Cosenza, ndr) e ancora pi\u00f9 fresco l&#8217;agguato contro il candidato Cinquestelle Aiello. <strong>Se c&#8217;\u00e9 un impresentabile in Calabria \u00e8 proprio il senatore Morra<\/strong>, che risponder\u00e0 in tutte le sedi di questa vergognosa manovra ai miei danni. Ha utilizzato un procedimento appena aperto, per reati che nulla hanno a che vedere con la funzione della sua commissione, per una vendetta postuma. Un nemico della Calabria e dei calabresi<strong>,<\/strong> non a caso isolato da tutto il suo partito per i suoi deliranti atteggiamenti&#8221;.<\/p>\n<p>&#8220;<strong>Non sono accusato di nessuna ipotesi di corruzione nel processo in cui sono stato rinviato a giudizio<\/strong> &#8211; scrive ancora Tallini -, ma l&#8217;ipotesi di reato che mi viene contestata \u00e8 &#8216;induzione indebita a dare o promettere utilit\u00e0&#8217; relativamente a delle contravvenzioni al codice della strada per importi irrilevanti, elevati da vigili urbani e per le quali il dibattimento che si sta celebrando dimostrer\u00e0 la totale infondatezza dell&#8217;accusa, cos\u00ec come gi\u00e0 avvenuto con la piena assoluzione da parte della Corte dei conti. In ogni caso<strong> il reato che mi viene contestato non ha nulla a che fare con il reato di corruzione<\/strong>. Pertanto non si comprende l&#8217;attenzione del presidente della Commissione antimafia, che dovrebbe occuparsi dei fenomeni di criminalit\u00e0 organizzat<strong>a<\/strong>&#8220;.<\/p>\n<p>&#8220;Faccio presente &#8211; dice ancora Tallini &#8211; che <strong>nella mia lunga attivit\u00e0 politica, in cui ho ricoperto incarichi istituzionali particolarmente importanti, non sono stato mai neppure sfiorato da ipotesi di reato infamanti<\/strong> quali quelli relativi alla criminalit\u00e0 organizzata. E&#8217; indegno, pertanto, che il Presidente della Commissione <strong>utilizzi strumentalmente la sua carica a soli tre giorni dalle elezioni per infangare la mia persona<\/strong>, marchiandomi di &#8216;rappresentabilit\u00e0&#8217;. Il comunicato diffuso dalla Commissione antimafia concernente la mia posizione di candidato &#8211; conclude &#8211;\u00a0 \u00e8 andato al di l\u00e0 di quelle che sono le competenze e le attribuzioni riconosciute alla stessa commissione ed al suo presidente. Pertanto<strong>, agir\u00f2 con ogni azione di legge verso il senatore Morra a tutela della mia immagine e della mia onorabilit\u00e0<\/strong>&#8220;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Non usa mezzi termini Domenico Tallini che attacca Nicola Morra dopo la presentazione delle liste con i cosiddetti &#8220;impresentabili&#8221; nel quale figura il nome del consigliere uscente &#8220;non \u00e8 la prima volta che questo giacobino di periferia utilizza le istituzioni per demolire i suoi avversari&#8221;<\/p>\n","protected":false},"author":55,"featured_media":123374,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[667],"class_list":["post-123373","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","tag-regionali-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/123373","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=123373"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/123373\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/123374"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=123373"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=123373"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=123373"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}