{"id":123671,"date":"2020-01-29T17:17:33","date_gmt":"2020-01-29T16:17:33","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/botta-e-risposta-su-facebook-tra-la-presidente-jole-santelli-e-lescluso-carlo-tansi\/"},"modified":"2023-01-16T17:52:00","modified_gmt":"2023-01-16T16:52:00","slug":"337241-botta-e-risposta-su-facebook-tra-la-presidente-jole-santelli-e-lescluso-carlo-tansi","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/337241-botta-e-risposta-su-facebook-tra-la-presidente-jole-santelli-e-lescluso-carlo-tansi\/","title":{"rendered":"Botta e risposta su Facebook tra la presidente Jole Santelli e l&#8217;escluso Carlo Tansi"},"content":{"rendered":"<h4>Polemiche tra la presidente della Regione e Carlo Tansi che scrive pubblicamente di &#8220;non avere alcuna stima della Santelli&#8221;<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; Nell&#8217;era post moderna \u00e8 Facebook a farla da padrone anche in campagna elettorale e in politica. Post di accuse, promozione e divulgazione dei programmi elettorali e dirette degli incontri pubblici hanno raccontato questi venti giorni appena trascorsi; ma non \u00e8 finita qui. La Santelli \u00e8 stata eletta presidente e <strong>le prime diatribe con i candidati esclusi arrivano a meno di 24 ore<\/strong> dall&#8217;elezione e sempre, e rigorosamente, sui social. A finire nella querelle di queste ore \u00e8 l&#8217;invito, lanciato in conferenza stampa dalla Santelli ad un incontro con gli altri candidati presidenti. Immediata la risposta su Facebook di Carlo Tansi che declina l&#8217;invito e scrive &#8220;la Santelli mi ha invitato insieme agli altri candidati non eletti ad un incontro per parlare dei nostri programmi. Io declino l&#8217;invito perch\u00e9 non ho nessuna stima della Santelli&#8221;. Sotto il post di Tansi oltre 700 i commenti che hanno fatto cambiare idea all&#8217;ex capo della Protezione civile, che in serata rettifica e annuncia la sua presenza, rimarcando per\u00f2, la sua disistima nei riguardi della presidente.<\/p>\n<p><iframe loading=\"lazy\" style=\"border: none; overflow: hidden;\" src=\"https:\/\/www.facebook.com\/plugins\/post.php?href=https%3A%2F%2Fwww.facebook.com%2Fcarlotansipresidente%2Fposts%2F2508740476121786&amp;width=500\" width=\"500\" height=\"198\" frameborder=\"0\" scrolling=\"no\"><\/iframe><br \/>\n<strong>Oggi sul profilo social della Santelli appare la risposta a Tansi<\/strong>. &#8220;Nell\u2019ambito di una conferenza stampa\u00a0 &#8211; si legge sul post -ho detto che avrei invitato ad una discussione sulla Calabria i miei avversari. Per correttezza devo dire che L\u2019unico che ho sentito per gli <span id=\"u_ps_fetchstream_12_4_2\" class=\"_ezo\">auguri<\/span> \u00e8 stato Francesco Aiello, questione di stile! Un altro candidato ha scritto subito che non avrebbe accettato l\u2019invito per mancanza di stima personale nei miei confronti, poi ha corretto, in parte, il tiro dicendo che avrebbe presenziato solo per correttezza istituzionale, rib<span class=\"text_exposed_show\">adendo la Sua disistima, infine che non accetter\u00e0 ruoli o incarichi. Premesso che un invito si riceve formalmente prima di rifiutarlo, che non mi \u00e8 mai passato per la mente di offrire incarichi&#8230;il Cav Callipo \u00e8 il Capo dell\u2019Opposizione, il Prof Aielllo, ordinario di Politica Economica, ha tutto il mio rispetto. Personalmente ritengo si possa imparare da tutti e detesto tre cose: l\u2019arroganza, la presunzione e la cattiva educazione&#8221;.<\/span><\/p>\n<p><iframe loading=\"lazy\" style=\"border: none; overflow: hidden;\" src=\"https:\/\/www.facebook.com\/plugins\/post.php?href=https%3A%2F%2Fwww.facebook.com%2Fjaja.santelli%2Fposts%2F1742745645860764&amp;width=500\" width=\"500\" height=\"268\" frameborder=\"0\" scrolling=\"no\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Polemiche tra la presidente della Regione e Carlo Tansi che scrive pubblicamente di &#8220;non avere alcuna stima della Santelli&#8221;<\/p>\n","protected":false},"author":53,"featured_media":123672,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-123671","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/123671","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/53"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=123671"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/123671\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/123672"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=123671"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=123671"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=123671"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}