{"id":123811,"date":"2020-01-31T16:01:24","date_gmt":"2020-01-31T15:01:24","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/concorso-polizia-di-stato-2020-bando-per-lassunzione-di-1-650-agenti\/"},"modified":"2023-01-16T17:52:09","modified_gmt":"2023-01-16T16:52:09","slug":"337633-concorso-polizia-di-stato-2020-bando-per-lassunzione-di-1-650-agenti","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/337633-concorso-polizia-di-stato-2020-bando-per-lassunzione-di-1-650-agenti\/","title":{"rendered":"Concorso Polizia di Stato 2020. Bando per l&#8217;assunzione di 1.650 agenti"},"content":{"rendered":"<h4>Pubblicato in Gazzetta Ufficiale il concorso pubblico, per esame, per l\u2019assunzione di 1650 allievi agenti della Polizia di Stato aperto ai cittadini italiani. Le domande di partecipazione potranno essere presentate dal 1\u00b0 febbraio 2020 alle ore 23.59 del 2 marzo 2020.<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>Dopo l&#8217;<span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/quicosenza.it\/news\/8455\">arma dei Carabinieri<\/a><\/span>, anche per la Polizia di Stato \u00e8 tempo di concorsi. \u00c8 stato pubblicato nella Gazzetta Ufficiale della Repubblica italiana (4^ Serie speciale \u201cConcorsi ed esami\u201d del 31 gennaio 2020), <strong>il bando di concorso, aperto ai civili, per l&#8217;assunzione di 1650 posti allievi agenti della Polizia di Stato aperto ai cittadini italiani in possesso dei requisiti prescritti e<\/strong> indetto con decreto del Capo della Polizia &#8211; Direttore Generale della Pubblica Sicurezza del 29 gennaio 2020. I posti riservati invece ai VFP1\/VFP4 saranno 1350.<\/p>\n<h4>Domande solo on-line<\/h4>\n<p><strong>Le domande di partecipazione potranno essere presentate dalle ore 00.00 del 1\u00b0 febbraio 2020 alle ore 23.59 del 2 marzo 2020, <\/strong>utilizzando esclusivamente la procedura informatica disponibile all\u2019indirizzo<strong><span style=\"color: #0000ff;\"> <a style=\"color: #0000ff;\" href=\"https:\/\/quicosenza.it\/news\/9452\" target=\"_blank\" rel=\"noopener noreferrer\">corsionline.poliziadistato.it<\/a> <\/span><\/strong>(<strong>cliccando sull\u2019icona \u201cConcorso pubblico\u201d<\/strong>).<\/p>\n<p>Il candidato potr\u00e0 accedere attraverso i seguenti strumenti di autenticazione: S<strong>istema Pubblico di Identit\u00e0 Digitale (SPID), con le relative credenziali (username e password),<\/strong> che dovr\u00e0 previamente ottenere rivolgendosi a uno degli identity provider accreditati presso l\u2019Agenzia per l\u2019Italia Digitale (A.G.I.D.), come da informazioni presenti sul sito istituzionale <span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/quicosenza.it\/news\/8444\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>www.spid.gov.it<\/strong><\/a><\/span> CIE (Carta di Identit\u00e0 Elettronica) rilasciata dal Comune di residenza.\u00a0Per utilizzare la carta di identit\u00e0 elettronica \u00e8 necessario installare il software disponibile <span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/quicosenza.it\/news\/9453\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>a questo indirizzo<\/strong><\/a><\/span>:\u00a0 sul proprio PC e dotarsi di lettore di smart card del tipo \u201c<strong>contactless reader<\/strong>\u201d.<\/p>\n<p><strong>Per partecipare bisogna non aver compiuto 26 anni<\/strong>. Come titolo di studio \u00e8 richiesto Il diploma per i civili, mentre per per i militari sar\u00e0 invece sufficiente la licenza media.<strong> Il candidato dovr\u00e0 inoltre essere in possesso di un indirizzo di posta elettronica certificata (PEC)<\/strong> a lui personalmente intestato, per l\u2019invio e la ricezione delle comunicazioni relative al concorso. Come indicato nel bando, dopo la prova scritta il concorso si svolger\u00e0 in base alle seguenti fasi:\u00a0 accertamento dell\u2019efficienza fisica, accertamenti psico-fisici e accertamenti attitudinali.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/quicosenza.it\/news\/9454\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>QUI IL BANDO<\/strong><\/a><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/quicosenza.it\/news\/9455\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>QUI LA GUIDA ALLA COMPILAZIONE DELLA DOMANDA<\/strong><\/a><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pubblicato in Gazzetta Ufficiale il concorso pubblico, per esame, per l\u2019assunzione di 1650 allievi agenti della Polizia di Stato aperto ai cittadini italiani. Le domande di partecipazione potranno essere presentate dal 1\u00b0 febbraio 2020 alle ore 23.59 del 2 marzo 2020.<\/p>\n","protected":false},"author":55,"featured_media":123812,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16],"tags":[],"class_list":["post-123811","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-italia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/123811","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=123811"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/123811\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/123812"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=123811"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=123811"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=123811"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}