{"id":123931,"date":"2020-02-04T12:00:31","date_gmt":"2020-02-04T11:00:31","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/cosenza-la-doppia-lotta-di-una-madre-la-malattia-della-figlia-e-i-diritti-negati\/"},"modified":"2023-01-16T17:52:17","modified_gmt":"2023-01-16T16:52:17","slug":"337985-cosenza-la-doppia-lotta-di-una-madre-la-malattia-della-figlia-e-i-diritti-negati","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/337985-cosenza-la-doppia-lotta-di-una-madre-la-malattia-della-figlia-e-i-diritti-negati\/","title":{"rendered":"Cosenza, la doppia lotta di una madre: la malattia della figlia e i diritti negati"},"content":{"rendered":"<h4><strong>Vi raccontiamo la forza e il coraggio di una donna, una mamma<\/strong><strong> che si \u00e8 trovata ad affrontare la malattia della figlia di soli 17 anni<\/strong> e nello stesso tempo la brutta vicenda, conclusasi con un licenziamento ingiustificato e una riassunzione nel luogo in cui lavorava<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; Ogni vita \u00e8 unica e irripetibile, nel bene e nel male. Non possiamo fare altro che accoglierla cos\u00ec come ci viene, affinch\u00e9 possa essere goduta in ogni istante. Ma a volte ci pone davanti tante sfide, fatte di dolore e rabbia. <strong>La malattia di una figlia \u00e8 quella pi\u00f9 grande<\/strong>, con tutte le difficolt\u00e0 che ne conseguono. Se a queste si aggiungono i diritti negati sul piano lavorativo, la situazione diventa insostenibile. <strong>Forse la salvezza e la saggezza passano attraverso le sofferenze<\/strong> e tutto ci\u00f2 che riesce, da quel momento traumatico in poi a farci guardare avanti con grande vitalit\u00e0, \u00e8 un processo di adattamento, di chi ha una struttura interiore forte e sana.<\/p>\n<p>Ed \u00e8 proprio <strong>la forza e il coraggio di una donna, una mamma, la storia che vogliamo raccontarvi.<\/strong> Si tratta della <strong>signora A.P. che si \u00e8 trovata ad affrontare la malattia della figlia di soli 17 anni<\/strong> e nello stesso tempo la brutta vicenda, conclusasi con un <strong>licenziamento ingiustificato<\/strong> nel luogo in cui lavorava.<\/p>\n<p>Questa madre, ormai esausta e sfinita, ha deciso di raccontarci la sua vita negli ultimi tempi, con un unico e solo obiettivo principale: <strong>la felicit\u00e0 di sua figlia.<\/strong><\/p>\n<h3>La scoperta del &#8220;Linfoma di Hodgkin&#8221;<\/h3>\n<p>&#8220;Ho iniziato a lavorare &#8211; dichiara A.P. &#8211; da un parrucchiere centro estetico di Rende a dicembre 2018. Ero assunta come responsabile con un regolare contratto a tempo indeterminato. Sono separata e madre di una splendida ragazza di 17 anni. Il padre viveva negli Stati Uniti. <strong>Mia figlia \u00e8 stata una bravissima ballerina, faceva ginnastica artistica partecipando anche a gare internazionali.<\/strong> Fino a quando sono apparsi i primi sintomi:<strong> stanchezza continua e febbre<\/strong>. Una febbre strana, andava a veniva soprattutto la notte. Abbiamo pensato ad una normale influenza ma la persistenza ci ha fatto preoccupare. Cos\u00ec il medico di famiglia ci ha fatto fare varie analisi. La febbre continuava a salire a 38\u00b0 e poi scendeva ripetutamente. Abbiamo deciso di effettuare un&#8217;ecografia e ho sentito pronunciare dal medico <strong>quelle parole che hanno dato inizio al nostro calvario: &#8220;Domani devi portare tua figlia in ospedale&#8221;.<\/strong><\/p>\n<p>Era il 14 febbraio 2019. Il giorno stesso che ho portato la ragazza in ospedale hanno fatto la Tac e gi\u00e0 in serata abbiamo saputo che era affetta dal Linfoma di Hodgkin. Subito abbiamo fatto una biopsia per capire a che stadio fosse. Era gi\u00e0 al quarto stadio b&#8221;.<\/p>\n<p>Il\u00a0<strong>Linfoma di Hodgkin (LH)<\/strong>\u00a0\u00e8 una forma di tumore che si origina dalle\u00a0<strong>cellule linfoidi<\/strong> normalmente presenti nel sangue, nel midollo osseo, nei linfonodi e in molti altri organi. Come per altre malattie del sangue <strong>non \u00e8 ancora chiaro quali siano le\u00a0cause<\/strong> alla base della malattia e non sono identificati specifici fattori di rischio. Ogni anno circa 4 persone ogni 100.000 abitanti contraggono un Linfoma di Hodgkin che, quindi, \u00e8 considerato una\u00a0<strong>malattia abbastanza rara<\/strong>. Non bisogna per\u00f2 dimenticare che nell\u2019ambito della popolazione di et\u00e0 compresa fra i 15 e i 35 anni rappresenta <strong>una delle pi\u00f9 frequenti forme tumorali.<\/strong> E proprio questo brutto male \u00e8 quello che ha colpito <strong>la piccola, una ragazza speciale, solare e vitale nonostante la malattia.<\/strong> Che ha affrontato tutto con il sorriso sulle labbra, lottando per sconfiggere questo grande mostro.<\/p>\n<p>&#8220;Appena appresa la notizia mi sono sentita cadere il mondo addosso. &#8211; Continua la mamma &#8211; <strong>Pensi di non potercela fare e ti domandi perch\u00e8 sia capitato proprio a te.<\/strong> E poi subentra la <strong>forza<\/strong> che necessariamente <strong>devi avere per tua figlia<\/strong>, per infonderle ottimismo e farle capire che si affronta e si supera. Ci siamo recati a Bologna dove \u00e8 stata operata al Sant&#8217;Orsola. Le hanno tolto un terzo dell&#8217;ovaio e impiantato il port. Ovviamente non sono pi\u00f9 andata a lavoro. Il padre \u00e8 dovuto necessariamente venire qui a firmare il consenso per la chemioterapia. Poi \u00e8 subito ripartito&#8221;.<\/p>\n<h3>La questione lavorativa<\/h3>\n<p>&#8220;Nel frattempo ho chiesto<strong> il congedo, accettato dall&#8217;Inps per 376 giorni tutto secondo legge.<\/strong> Mia figlia essendo minorenne necessita di assistenza continua. A maggio la mia responsabile viene a trovarmi a casa e inizia a minacciarmi nel darmi solo il 50% dello stipendio. Io le dico che mi spetta il saldo completo. Mia figlia a causa della chemio sta male, molto male. Non riesce a muovere le gambe, le cadono i capelli, \u00e8 debole, ecc. <strong>Lo stipendio non arriva, sporgo denuncia all&#8217;Ispettorato del Lavoro<\/strong> perch\u00e8 la responsabile si ostinava a non pagare, nonostante l&#8217;Inps avesse erogato la somma del congedo&#8221;.<\/p>\n<p>&#8220;A giugno, dopo 20 giorni dalla denuncia, viene stabilita la conciliazione, dove si presenta il legale e viene saldato da febbraio a maggio. Ad agosto per\u00f2 &#8211; racconta ancora &#8211;\u00a0 si accumulano nuovi ritardi e ho ho deciso di rivolgermi ad altri legali perch\u00e8 la situazione era immobile e <strong>da maggio in poi non ho ricevuto alcun saldo.<\/strong> Vi \u00e8 stata un&#8217;altra conciliazione ma non hanno voluto pagare. Il loro legale ha affermato che mia figlia non avesse bisogno di assistenza. <strong>Ho denunciato nuovamente all&#8217;Ispettorato, ai carabinieri di Rende e alla Finanza<\/strong> per appropriazione indebita e per le minacce subite. Ogni ciclo di chemio la mia bimba ha avuto bisogno di sangue e abbiamo fatto le trasfusioni&#8221;.<\/p>\n<h3>Licenziata e riassunta nonostante il congedo: &#8220;non ho nulla&#8221;<\/h3>\n<p>Nel luogo dove lavoravo, dopo le denunce \u00e8 andata l&#8217;ispezione e subito dopo <strong>mi \u00e8 arrivato il licenziamento per giusta causa (fatto inspiegabile dato il congedo).<\/strong> Poi nuovamente assunta. Ad oggi non ho nulla: <strong>n\u00e8 busta paga, n\u00e8 soldi<\/strong> io <strong>vado avanti solo con l&#8217;invalidit\u00e0 di mia figlia<\/strong> che sono circa 500 euro che se ne vanno tra spese mediche e affitto. <strong>Dopo aver affrontato la malattia ora ho il problema economico.<\/strong> Certo<strong> la gente buona esiste, ho avuto tanti aiuti in primis la famiglia, i cittadini di Castrolibero mi ha dato una mano e amici veri.<\/strong> Ma io ho bisogno dei miei stipendi, di ci\u00f2 che mi spetta per diritto, non posso contare sulla solidariet\u00e0 degli altri. Mia figlia ha dovuto abbandonare il suo sogno della danza. Ora ha terminato il ciclo di chemio, porta una parrucca che ha fatto fatica ad accettare, ma alla fine si \u00e8 &#8216;rassegnata&#8217; anche a questo. <strong>Il prossimo 22 febbraio compir\u00e0 18 anni e non potr\u00f2 neanche organizzarle la festa che ha sempre desiderato.<\/strong> Non ne ho la possibilit\u00e0, mi sento triste e stanca e la mia autostima sta svanendo. <strong>Mi auguro che giustizia venga fatta al pi\u00f9 presto&#8221;.<\/strong><\/p>\n<p>Un desiderio che condividono madre e figlia, e che speriamo si trasformi presto in realt\u00e0, perch\u00e8 <strong>appare inconcepibile in una societ\u00e0 evoluta che si lucri persino sulla malattia di una ragazza.<\/strong> L&#8217;umanit\u00e0 esiste ma a volte ci si dimentica che fa parte di ognuno di noi. La giustizia altrettanto ma a volte arriva lentamente. <strong>In questa storia ci\u00f2 che conta principalmente \u00e8 la felicit\u00e0 di una ragazza costretta a combattere contro un mostro<\/strong> che ora attende solo che umanit\u00e0 e giustizia si concilino e gli permettano di festeggiare nel migliore dei modi il suo <strong>18esimo compleanno<\/strong>.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-338136 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2020\/02\/mano2--413x280.jpg\" alt=\"\" width=\"413\" height=\"280\" title=\"\"><\/p>\n<h3>La dedica alla sua mamma<\/h3>\n<p>&#8220;Gli ultimi 6 mesi non sono stati i migliori della nostra vita, anzi, veramente nulla c\u2019\u00e8 mai andato bene. <strong>La vita ci ha sempre messo alla prova e abbiamo superato sempre tutto io e te.<\/strong> Siamo state messe alla prova e ce l\u2019abbiamo fatta anche questa volta. Devo dire che senza di te tutto questo non l\u2019avrei affrontato cos\u00ec serenamente come l&#8217;ho affrontato, non avrei avuto la forza, la <strong>forza che tu hai e che mi hai trasmesso.<\/strong> Mi hai sostenuta quando volevo rinunciare a tutto, mi se<span class=\"text_exposed_show\">i stata accanto sempre rinunciando anche tu a tante cose, hai fatto con me tutti i digiuni che ero costretta a fare, mi hai dato la mano quando ne avevo bisogno, hai dormito con me quando non stavo per niente bene, <strong>hai sofferto con me.<\/strong> Penso che non \u00e8 da tutti affrontare quello che abbiamo affrontato noi, non lo si pu\u00f2 capire, neanche immaginare. <strong>Per questo sono qui a ringraziarti mamma, perch\u00e9 senza di te non c\u2019\u00e8 l\u2019avrei fatta.<\/strong><\/span><\/p>\n<div class=\"text_exposed_show\">\n<p>Ringrazio anche <strong>le mie zie e mia nonna<\/strong> che mi hanno fatto compagnia in quelle settimane che non passavano mai chiusa in ospedale, che mi hanno sempre sostenuta ed erano presenti quando ne avevamo bisogno, vi voglio bene. Ringrazio mio padre che nonostante l\u2019assenza ha aiutato me e mia madre. <strong>Ringrazio tutti quelli che mi sono stati vicini<\/strong> e che si sono sempre interessati a me. Per ora, posso dire, dopo tanta sofferenza, \u00e8 finito tutto!&#8221;<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Vi raccontiamo la forza e il coraggio di una donna, una mamma che si \u00e8 trovata ad affrontare la malattia della figlia di soli 17 anni e nello stesso tempo la brutta vicenda, conclusasi con un licenziamento ingiustificato e una riassunzione nel luogo in cui lavorava<\/p>\n","protected":false},"author":22,"featured_media":123932,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[42],"tags":[],"class_list":["post-123931","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/123931","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=123931"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/123931\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/123932"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=123931"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=123931"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=123931"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}