{"id":124103,"date":"2020-02-06T10:03:26","date_gmt":"2020-02-06T09:03:26","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/disastro-ferroviario-a-lodi-e-calabrese-uno-dei-macchinisti-deceduti\/"},"modified":"2023-01-16T17:52:30","modified_gmt":"2023-01-16T16:52:30","slug":"338481-disastro-ferroviario-a-lodi-e-calabrese-uno-dei-macchinisti-deceduti","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/338481-disastro-ferroviario-a-lodi-e-calabrese-uno-dei-macchinisti-deceduti\/","title":{"rendered":"Disastro ferroviario a Lodi, \u00e8 calabrese uno dei macchinisti deceduti"},"content":{"rendered":"<h4>Il bilancio del deragliamento avvenuto questa mattina \u00e8 di due vittime e 31 persone ferite. Morti i due macchinisti, uno dei quali \u00e8 calabrese<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>LODI (MI) &#8211; Era originario di <strong>Reggio Calabria Giuseppe Cicci\u00f9<\/strong> uno dei due macchinisti, insieme a Mario Di Cuonzo, deceduti questa mattina a seguito del deragliamento di un Frecciarossa ad Ospedaletto Lodigiano nei pressi del casello A1, in zona cascina Griona. Il bilancio del grave incidente \u00e8 di <strong>due vittime e 31 persone ferite<\/strong>. Il treno ad alta velocit\u00e0 era partito da Milano ed era diretto a Salerno.<\/p>\n<p>Secondo i primi riscontri la motrice del Frecciarossa, in corrispondenza di uno scambio elettronico, si sarebbe staccata dal treno, andando verso la zona dei depositi e, dopo aver urtato un carrello merci sui binari e &#8211; dopo aver percorso trecento o quattrocento metri fuori dalle rotaie, si sarebbe schiantata su un casotto delle Ferrovie dello Stato. Il resto del treno ha invece continuato la sua corsa sull&#8217;altro binario, la prima carrozza si \u00e8 ribaltata e le altre carrozze sono pi\u00f9 pi\u00f9 o meno intatte.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-338485 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2020\/02\/frecciarossa-deragliato-lodi.jpg\" alt=\"\" width=\"510\" height=\"320\" title=\"\"><\/p>\n<p><strong>Giuseppe Cicci\u00f9, era nato a Reggio Calabria, e aveva 51 anni.<\/strong> Del sud anche Mario Di Cuonzo, nato a Capua, di 59 anni. &#8220;Il bilancio definitivo del deragliamento del treno Alta Velocita&#8217; Frecciarossa avvenuto alle 5.35 all&#8217;altezza di Ospedaletto Lodigiano, in localita&#8217; Cascina Griona, e&#8217; di 2 persone decedute, 31 feriti&#8221;. Cos\u00ec l&#8217;assessore al Welfare della Regione Lombardia, Giulio Gallera. Tra i feriti &#8220;4 ricoverati in codice giallo a Lodi (2), Cremona e Pavia, e 27 in codice verde negli ospedali di Lodi (8), Melegnano (4), Crema (3), Humanitas (3), Codogno (2), Piacenza (3) e Castel San Giovanni (4)&#8221;.<\/p>\n<p>Per Gallera e&#8217; stata &#8220;straordinaria la capacita&#8217; di intervento e di coordinamento dell&#8217;Azienda Regionale per l&#8217;Emergenza Urgenza (AREU) di Regione Lombardia che ha messo immediatamente in campo l&#8217;attivita&#8217; di Consolle Maxiemergenza, 2 elicotteri dotati di dispositivi per il volo notturno, 2 automediche, 12 ambulanze e 1 veicolo da 9 posti. Ringrazio tutti gli operatori e i volontari intervenuti con grande tempestivit\u00e0 e professionalit\u00e0&#8221;.<\/p>\n<p>L&#8217;ultimo post su Facebook di Giuseppe Cicci\u00f9: <strong>&#8220;La prevenzione \u00e8 da sempre l&#8217;arma migliore!&#8221;<\/strong>. Lo aveva scritto lo scorso ottobre da uno dei due macchinisti morti questa mattina nel deragliamento del treno nel lodigiano.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-338490 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2020\/02\/giuseppe-cicciu.jpg\" alt=\"\" width=\"416\" height=\"592\" title=\"\"><\/p>\n<p>&nbsp;<\/p>\n<h3>Sindacati: &#8220;Fatto gravissimo, domani sciopero di due ore di tutti i ferrovieri&#8221;<\/h3>\n<p>Un fatto gravissimo e inaccettabile l&#8217;incidente di stamattina vicino Lodi. Lo affermano <strong>Filt-Cgil, Fit-Cisl, Uiltrasporti, Fast-Confsal, Ugl Taf e Orsa<\/strong> in merito al deragliamento avvenuto stamattina alle 5.30 del treno ad alta velocit\u00e0 9595 partito alle 5.10 da Milano e diretto a Salerno. \u201cLa notizia della<strong> perdita di due colleghi e del ferimento di altri due e di 25 passeggeri<\/strong> ci addolora profondamente. &#8211; scrivono in una nota congiunta &#8211; esprimiamo vicinanza e cordoglio alle famiglie dei due colleghi deceduti e auguriamo pronta guarigione ai colleghi e ai passeggeri feriti\u201d. E per domani <strong>proclamano due ore di sciopero di tutti i ferrovieri<\/strong> dipendenti da tutte le aziende di settore operanti sulla rete nazionale e locale a partire dalle 12.<\/p>\n<h4>Fortunato Foti: &#8220;Cicci\u00f9 amava il suo lavoro&#8221;<\/h4>\n<p>Lo conoscevo da 25 anni, era una persona senza ipocrisie, ben voluto da tutti, solare, disponibile. Gli piaceva questo mestiere, amava questo lavoro, lo svolgeva con seriet\u00e0 impeccabile ed era molto attento alla sicurezza&#8221;: cos\u00ec Fortunato Foti, ferroviere e membro della segreteria lombarda della Fit Cisl, ha ricordato Giuseppe Cicci\u00f9, uno due macchinisti morti nel deragliamento avvenuto questa mattina nel Lodigiano. <strong>Cicci\u00f9 si era trasferito da molti anni in Lombardia<\/strong>, dove <strong>viveva con la moglie e un figlio,<\/strong> ma &#8220;era attaccatissimo&#8221; alla sua citt\u00e0 natale, cio\u00e8 <strong>Reggio Calabria, dove tornava appena poteva per far visita alla madre. <\/strong><\/p>\n<p>&#8220;Sono talmente amareggiato e triste che faccio fatica a credere che sia morto&#8221;, ha detto Foti. &#8220;Era una persona disponibile &#8211; ha proseguito &#8211; si prendeva in carico qualsiasi problema dei colleghi e andava fino in fondo. Abbiamo iniziato insieme nella Rsu e, quando passava in stazione Centrale a Milano, ci vedevamo sempre&#8221;.<\/p>\n<h4><strong>L&#8217;ipotesi al vaglio<\/strong> degli inquirenti<\/h4>\n<p>&#8220;<strong>Stiamo verificando l&#8217;ipotesi dell&#8217;errore umano<\/strong>&#8220;. E&#8217; quanto ha detto il Procuratore della Repubblica di Lodi Domenico Chiaro non precisando se sia stato gi\u00e0 ascoltato personale coinvolto nell&#8217;incidente dell&#8217;alta velocit\u00e0. Una delle cause del deragliamento del Frecciarossa potrebbe essere stato un problema a uno scambio dove ieri sarebbe stato sostituito un &#8216;deviatoio&#8217;, ovvero un pezzo dello scambio stesso.\u00a0&#8220;Escludo qualsiasi riferimento a un&#8217;attivit\u00e0 volontaria, l&#8217;ipotesi di attentato \u00e8 destituita di ogni fondamento&#8221;, ha detto il Procuratore. &#8220;Sapete che ci sono state attivit\u00e0 di manutenzione in quel tratto,<strong>\u00a0stiamo cercando di capire quali attivit\u00e0 sono state svolte<\/strong>\u00a0e che tipo di nesso ci sia tra questa attivit\u00e0 e il verificarsi del disastro. Questa \u00e8 una delle ipotesi, le verifichiamo tutte&#8221;. Chiaro ha precisato che &#8220;lo scambio sembrerebbe avere una qualche connessione con il verificarsi del fatto&#8221;.\u00a0&#8220;I lavori di manutenzione vengono fatti perch\u00e9\u00a0<strong>qualcosa si \u00e8 rotto<\/strong>, se no non c&#8217;\u00e8 motivo per essere l\u00ec alle 4 e mezza del mattino&#8221;, ha osservato. &#8220;Se lo scambio fosse stato dritto per dritto &#8211; ha aggiunto &#8211; il treno non sarebbe deragliato, non \u00e8 difficile da capire.\u00a0<strong>Non era nella posizione che doveva garantire la libera percorrenza del treno<\/strong>&#8220;. Chiaro ha precisato che &#8220;era una parte dello scambio interessato dai lavori di manutenzione&#8221;.\u00a0&#8220;Le societ\u00e0 coinvolte hanno gi\u00e0 avviato una\u00a0<strong>commissione d&#8217;inchiesta e danno la massima disponibilit\u00e0 agli organi competenti per collaborare&#8221;<\/strong>: ha detto l&#8217;ad di Rfi Maurizio Gentili ai giornalisti sul luogo del deragliamento del Frecciarossa. &#8220;Noi oggi &#8211; ha aggiunto &#8211; vogliamo esprimere grande vicinanza alle famiglie dei nostri due colleghi ferrovieri ai quali siamo molto vicini e a tutti i feriti, e ringraziare i soccorritori&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il bilancio del deragliamento avvenuto questa mattina \u00e8 di due vittime e 31 persone ferite. Morti i due macchinisti, uno dei quali \u00e8 calabrese<\/p>\n","protected":false},"author":42,"featured_media":124104,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17,16],"tags":[],"class_list":["post-124103","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","category-italia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/124103","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=124103"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/124103\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/124104"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=124103"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=124103"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=124103"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}