{"id":124513,"date":"2020-02-13T17:22:54","date_gmt":"2020-02-13T16:22:54","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/uccise-lex-compagna-e-ne-brucio-il-corpo-condannato-a-16-anni-stefan-valea\/"},"modified":"2023-01-16T17:52:56","modified_gmt":"2023-01-16T16:52:56","slug":"339702-uccise-lex-compagna-e-ne-brucio-il-corpo-condannato-a-16-anni-stefan-valea","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/339702-uccise-lex-compagna-e-ne-brucio-il-corpo-condannato-a-16-anni-stefan-valea\/","title":{"rendered":"Uccise l&#8217;ex compagna e ne bruci\u00f2 il corpo. Condannato a 16 anni Stefan Valea"},"content":{"rendered":"<h4>Si conclude un lunghissimo iter processuale con una condanna in primo grado, un&#8217;assoluzione in appello poi annullata dalla Cassazione fino alla definitiva sentenza di oggi che ha condannato Stefan Valea<!--more--><\/h4>\n<p><span style=\"color: #ffffff;\">.<\/span><\/p>\n<p>CATANZARO &#8211; <strong>Sedici anni di reclusione sono stati inflitti dalla Corte d&#8217;assise d&#8217;appello di Catanzaro a Stefan Valea, di 48 anni, romeno<\/strong>, riconosciuto colpevole di <strong>avere ucciso la donna con cui aveva avuto una relazione, Monica Alexandrescu (37)<\/strong>\u00a0e di averne poi<strong> bruciato il cadavere<\/strong>. La donna, secondo l&#8217;accusa, fu uccisa da Valea l&#8217;8 settembre 2008 con due colpi di pistola alla testa al culmine di una discussione nata perch\u00e9 lei aveva deciso di interrompere la relazione. Quindi l&#8217;uomo &#8211; arrestato dai carabinieri a maggio 2010 &#8211; <strong>bruci\u00f2 il cadavere all&#8217;interno di un&#8217;auto<\/strong> che poi spinse nel greto di un fiume nelle campagne di San Gregorio D&#8217;Ippona. Il corpo venne poi trovato il 14 settembre dopo che il marito, un settantenne di Vazzano, ne denunci\u00f2 la scomparsa. La vittima, infatti, <strong>voleva assicurare al suo bambino una vita lontana dalle sofferenze e dalla fame che lei stessa aveva patito<\/strong> e per questo aveva conosciuto altri uomini e il settantenne di Vazzano. Una relazione sentimentale osteggiata da Stefan Valea che ha poi commesso l\u2019omicidio della donna. La sentenza di oggi giunge a conclusione di un <strong>lunghissimo iter processuale<\/strong>. Valea, infatti, era stato condannato a 24 anni in primo grado e poi assolto in appello. Sentenza, quest&#8217;ultima, annullata dalla Cassazione che aveva disposto un nuovo processo d&#8217;appello.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si conclude un lunghissimo iter processuale con una condanna in primo grado, un&#8217;assoluzione in appello poi annullata dalla Cassazione fino alla definitiva sentenza di oggi che ha condannato Stefan Valea<\/p>\n","protected":false},"author":55,"featured_media":124514,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-124513","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/124513","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=124513"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/124513\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/124514"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=124513"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=124513"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=124513"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}