{"id":124654,"date":"2020-02-16T12:15:04","date_gmt":"2020-02-16T11:15:04","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/enoteche-italiane-in-cinque-anni-segnano-piu-4\/"},"modified":"2023-01-16T17:53:06","modified_gmt":"2023-01-16T16:53:06","slug":"340144-enoteche-italiane-in-cinque-anni-segnano-piu-4","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/340144-enoteche-italiane-in-cinque-anni-segnano-piu-4\/","title":{"rendered":"Enoteche italiane, in cinque anni segnano pi\u00f9 4%"},"content":{"rendered":"<h4>In tutto il Paese sono 7.209. Gli addetti sono quasi 8 mila\u00a0<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>Aumentano del 4% in cinque anni le enoteche in Italia per un totale di 7.209 attivit\u00e0. Nell&#8217;ultimo anno sono stabili. Lo rileva la Camera di commercio di Milano, Monza, Brianza, Lodi e Coldiretti Lombardia su <strong>dati dei primi nove mesi del 2019<\/strong>. Dal report economico emerge che gli impiegati sono quasi 8 mila, &#8220;un numero &#8211; si spiega in una nota &#8211; che si mantiene stabile in un anno e in crescita del 10% in cinque anni&#8221;. Nelle singole citt\u00e0, i primi 10 comuni in Italia per numero di enoteche attive sono: Roma, al primo posto, con 345 enoteche (+1,5% in un anno e +35% in dieci anni), Napoli con 221 attivit\u00e0 (-1% in cinque e dieci anni), Milano con 141 (+ 5% in un anno, + 72% in dieci anni), Torino con 121 (+ 5% in un anno e + 64% in dieci anni), Firenze con 91 (+2% in un anno e + 7% in dieci), Genova con 80 enoteche, Venezia con 68, Palermo con 62, Bologna con 57 e infine Bari con 50. <strong>A livello di provincia \u00e8 in testa Napoli<\/strong> (528, +3% in 5 anni), Roma (480, +3%) e Milano (259, +9%). Segue Torino (235, +6%), Bari (192), Firenze (172, + 5% in un anno), Brescia (166, stabile), Venezia (158, +7% in cinque anni), Padova (138, stabili). Tra le prime crescono di pi\u00f9 nell&#8217;ultimo anno Firenze (+5% con 172), Palermo (+4% con 100), Catania (+7% con 91), Torino e Treviso (+2,6%, con 235 e 78 rispettivamente). Nella Lombardia le enoteche complessive nel 2019 sono 982 (+8,7% in cinque anni rispetto alle 903 attive nel 2014). Registrati oltre mille addetti, in crescita del +8,6% nel quinquennio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>In tutto il Paese sono 7.209. Gli addetti sono quasi 8 mila\u00a0<\/p>\n","protected":false},"author":56,"featured_media":124655,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16],"tags":[],"class_list":["post-124654","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-italia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/124654","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/56"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=124654"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/124654\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/124655"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=124654"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=124654"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=124654"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}