{"id":124934,"date":"2020-02-21T09:36:13","date_gmt":"2020-02-21T08:36:13","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/larazzo-di-raffaello-di-roberto-bilotti-in-mostra-a-palazzo-arnone-e-a-gerace\/"},"modified":"2023-01-16T17:53:24","modified_gmt":"2023-01-16T16:53:24","slug":"340958-larazzo-di-raffaello-di-roberto-bilotti-in-mostra-a-palazzo-arnone-e-a-gerace","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/340958-larazzo-di-raffaello-di-roberto-bilotti-in-mostra-a-palazzo-arnone-e-a-gerace\/","title":{"rendered":"L&#8217;Arazzo di Raffaello di Roberto Bilotti in mostra a Palazzo Arnone e a Gerace"},"content":{"rendered":"<h4>Il magnifico <strong>arazzo di Raffaello della collezione Roberto Bilotti Ruggi d&#8217;Aragona sar\u00e0 esposto a Cosenza<\/strong>, alla Galleria Nazionale di palazzo Arnone e poi a Gerace Museo Diocesano<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; Un&#8217;occasione straordinaria e irripetibile per ammirare un Raffaello poco noto al grande pubblico. In occasione del quinto centenario della morte di Raffaello Sanzio (1483-1520), il magnifico <strong>arazzo della collezione Roberto Bilotti Ruggi d&#8217;Aragona, con cui lo Stato italiano apre le celebrazioni raffaellesche all&#8217;Istituto Nazionale per la Grafica sar\u00e0 esposto a Cosenza<\/strong>, alla Galleria Nazionale di palazzo Arnone e poi a Gerace Museo Diocesano. Un sovraccarico di bellezza che quasi stordisce, soprattutto grazie alla maestria non solo formale ma anche narrativa di Raffaello, per la sua capacit\u00e0 di tradurre<strong> la fede in ogni singola scena spettacolare, capace di attirare l\u2019attenzione e l\u2019anima pi\u00f9 segreta di qualsiasi visitatore.<\/strong><\/p>\n<p>L&#8217;itinerario tracciato proseguir\u00e0 con le due tappe in Calabria per rievocare il ruolo della Regione e i rapporti con Raffaello e i suoi arazzi. <strong>Montalto Uffugo e Gerace<\/strong> erano all&#8217;epoca dell&#8217;urbinate rispettivamente infeudati a due rami naturali d&#8217;Aragona sovrani di Napoli. A Giovanna d&#8217;Aragona duchessa di Montalto (1502-1575), celebrata come modello di bellezza nel trattato <strong>De pulchro et amore del filosofo Agostino Nifo<\/strong>, si riconduce tradizionalmente il ritratto di Raffaello al Louvre. Il Cardinale Luigi d&#8217;Aragona (1474-1519), figlio del marchese di Gerace, dal luglio 1517 \u00e8 a Bruxelles a seguire nella bottega di Pieter van Aelst la tessitura degli arazzi che nel 1519 arriveranno a Roma per essere esposti solennemente il giorno di Santo Stefano in Sistina.<\/p>\n<p>Nel 2014 l&#8217;arazzo che rappresenta la <strong>morte di Anania,<\/strong> fu esposto al Museo Civico di Rende a sostegno della riqualificazione del Borgo dei Musei. Un ampio progetto integrato di aggregazione, relazione e <strong>valorizzazione del territorio<\/strong>, una cittadella dell&#8217;arte che collega le diverse risorse culturali locali con i quattro musei, dall&#8217;antico al contemporaneo, a pochi passi dall&#8217;Universit\u00e0 della Calabria, uno dei pi\u00f9 grandi atenei d&#8217;Italia.<\/p>\n\n<p><strong>L'&#8221;anno Sanzio&#8221;<\/strong> \u00e8 stato l&#8217;occasione per approfondire gli studi sugli arazzi derivati dalle composizioni di Raffaello. <strong>Anna Maria de Strobel e Cecilia Mazzetti di Pietralata<\/strong>, nel loro volume Leone X e Raffaello in Sistina, gli arazzi degli Atti degli Apostoli ne hanno inquadrato le varie serie: oltre l&#8217;edizione vaticana, quella di Loreto e di Tolosa e la serie iconologica commissionata dal Cardinale Ercole Gonzaga nel 1548 ad arazzieri fiamminghi in Italia. Le opere sottratte da Napoleone furono poi restituite al palazzo gonzaghesco di Mantova. <strong>Le studiose hanno ricondotto l&#8217;arazzo Bilotti alla manifattura di Enrico Mattens, una serie di cui, fino ad ora, si conosceva solo la &#8220;Lapidazione di Santo Stefano&#8221; nel castello du Plessis-Bourr\u00e8, Angers<\/strong>. Corredato da questa nuova lettura storico-artistica, che ne conferma l&#8217;attribuzione raffaellesca, l&#8217;arazzo sar\u00e0 donato ad un Museo del Sud. &#8220;Gli arazzi &#8211; si legge nel volume &#8211; furono da subito celebri per la bellezza e la ricchezza dei materiali e nel corso dei secoli successivi vennero pi\u00f9 volte replicati in arazzo su richiesta delle principali corti europee e di committenti privati. <strong>Nelle scene principali i soggetti sono tratti dal Nuovo Testamento e rappresentano le storie di San Pietro<\/strong>, il pastore vicario di Cristo, e quelle di San Paolo, l\u2019apostolo delle genti, collegate sotto il profilo narrativo dalla Lapidazione di Santo Stefano. Tutte le storie sono concluse lungo il bordo inferiore da alti zoccoli a monocromo, assenti nelle repliche eseguite successivamente. <strong>L\u2019arazzo della collezione Bilotti presenta molte legami con la serie di repliche degli Atti degli Apostoli,<\/strong> eseguita all\u2019inizio del XVII secolo e conservata nella cattedrale di Tolosa che non presenta fili di argento dorato come anche l\u2019arazzo in questione. Rispetto alla serie vaticana gli arazzi di Tolosa e quello Bilotti presentano sfondi, ambientazioni e abiti modificati e in parte, come nel caso in esame, anche le figure sono ridotte di numero.&#8221;<\/p>\n\n<p>Altre tappe dell&#8217;esposizione dell&#8217;arazzo di Raffaello Bilotti, durante l&#8217;Anno Sanzio, saranno: Palermo, Verona, Firenze, Urbino casa di Raffaello, Rio e S. Paolo.<\/p>\n<p>Lo Stato Italiano celebra Raffaello in collaborazione con i privati, l&#8217;esposizione itinerante sul territorio nazionale del prezioso arazzo del mecenate Roberto Bilotti Ruggi d&#8217;Aragona in parallelo alle celebrazioni vaticane nella<strong> Cappella sistina esponendo gli arazzi<\/strong>, nel luogo per il quale sono stati concepiti. La Cappella Sistina \u00e8 tra i pi\u00f9 famosi tesori culturali e artistici al mondo, realizzata nel 1475 da papa Sisto IV della Rovere da cui prese il nome. Tra i luoghi pi\u00f9 sacri e significativi della cristianit\u00e0, qui si tiene il Conclave e le altre cerimonie ufficiali del papa, in passato anche le incoronazioni papali. <strong>E&#8217; decorata con un ciclo di opere d&#8217;arte pi\u00f9 conosciute e celebrate della civilt\u00e0 artistica occidentale,<\/strong> gli affreschi di Michelangelo commissionati da papa Giulio II della Rovere, al di sopra degli gli affreschi della Rovere di Botticelli, Perugino, Ghirlandaio, Signorelli, di Cosimo, che costituiscono la pi\u00f9 completa ed importante &#8220;teologia visiva&#8221;. Nel primi del &#8216;500 fu arricchita dai magnifici arazzi degli Atti degli Apostoli a completamento della narrazione iconografica. <strong>Monumentalit\u00e0 delle due storie di Pietro e Paolo una maestria non solo formale ma anche narrativa di Raffaello<\/strong>, dalla sua capacit\u00e0 di tradurre la Fede in ogni singola scena spettacolare, capace di attirare l&#8217;attenzione e l&#8217;anima pi\u00f9 segreta di qualsiasi visitatore.<\/p>\n<p>Oggi \u00e8 proprio la discendente dei due papi della Rovere, Sisto IV e Giulio II, che si occupa di condividere con la collettivit\u00e0 uno degli arazzi di Raffaello di famiglia, <strong>Viviana Bilotti Ruggi d&#8217;Aragona Odescalchi<\/strong> la cui nonna Amelia Lante Montefeltro della Rovere \u00e8 parte della famiglia papale a cui si deve la Sistina. L&#8217;esposizione nel palazzo Poli \u00e8 resa possibile all&#8217;impegno congiunto della rampolla con<strong> il fidanzato Damiano Fianco<\/strong>, noto fotografo d&#8217;Arte, che con il <strong>&#8220;Progetto Arte Poli&#8221;<\/strong> sostiene il recupero delle testimonianze artistiche del passato creando per i nuovi edifici di culto apparati artistici di assoluta qualit\u00e0, attualizzando la grande tradizione culturale italiana.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-340966 \" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2020\/02\/Viviana-Bilotti-R-dAragona-Odescalchi-ed-il-fidanzato-Damiano-Fianco-.jpg\" alt=\"\" width=\"527\" height=\"926\" title=\"\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il magnifico arazzo di Raffaello della collezione Roberto Bilotti Ruggi d&#8217;Aragona sar\u00e0 esposto a Cosenza, alla Galleria Nazionale di palazzo Arnone e poi a Gerace Museo Diocesano<\/p>\n","protected":false},"author":22,"featured_media":124935,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[42,40],"tags":[],"class_list":["post-124934","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cosenza","category-cultura-spettacolo"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/124934","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=124934"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/124934\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/124935"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=124934"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=124934"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=124934"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}