{"id":125141,"date":"2020-03-01T07:00:54","date_gmt":"2020-03-01T06:00:54","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/amore-opera-show-la-lirica-calabrese-in-concerto\/"},"modified":"2023-01-16T17:53:38","modified_gmt":"2023-01-16T16:53:38","slug":"341534-amore-opera-show-la-lirica-calabrese-in-concerto","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/341534-amore-opera-show-la-lirica-calabrese-in-concerto\/","title":{"rendered":"&#8216;Amore Opera Show&#8217; : la lirica calabrese in concerto"},"content":{"rendered":"<h4><b>La musica lirica \u00e8<\/b> una forma d&#8217;arte di origini antiche, che riscontra anche in Calabria molto interesse.<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; &#8216;Amore Opera Show&#8217; sar\u00e0 il <strong>13 marzo sul palco del Teatro Garden di Rende. <\/strong>La nostra regione \u00e8 carica di talento, di artisti, di eccellenze. Personaggi che in diversi ambiti hanno avuto il prestigio di calcare importanti palcoscenici, scenari di primo ordine e contesti degni di nota. Questo \u00e8 il caso di tre giovani cosentini \u2013 due cantanti lirici e un pianista \u2013 con un curriculum importantissimo. Si tratta di <strong>Stefano Tanzillo, Andrea Tanzillo<\/strong> e <strong>Andrea Bauleo<\/strong>. Cosenza li unisce, e ad unirli, non \u00e8 solo la loro citt\u00e0 natale, ma il loro amore per la musica: una carriera che li porta in giro per il mondo ad esibirsi in contesti di primo ordine.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-341536 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2020\/02\/86970418_2836106976410214_7134970388475281408_o-400x400.jpg\" alt=\"\" width=\"400\" height=\"400\" title=\"\"><\/p>\n<h2>I protagonisti<\/h2>\n<p>Il tenore <strong>Stefano Tanzillo<\/strong> \u00e8 un giovane cantante del panorama lirico, con all\u2019attivo presenze nei pi\u00f9 importanti teatri internazionali. Collabora con la Fondazione Luciano Pavarotti dal 2013 cantando per i vari memorial del Maestro. Vincitore del premio new generation agli Oscar della lirica e di diversi concorsi internazionali. Molteplici i debutti di opere di Verdi, Mascagni, Mozart e l\u2019attivit\u00e0 concertistica. <strong>Andrea Tanzillo<\/strong>, a soli 23 anni prende parte alle produzioni di Traviata, Rigoletto e Nabucco, all\u2019Aida di Franco Zeffirelli in Cina nel 2017. Nell\u2019ultimo anno \u00e8 protagonista dello spettacolo itinerante \u201cLe sette parole di Maria\u201d. Nel luglio 2019 \u00e8 protagonista nello spettacolo della RAI proposto per i cinquant\u2019anni dell\u2019allunaggio. <strong>Andrea Bauleo<\/strong> ha all\u2019attivo diverse partecipazioni a rassegne pianistiche, eseguendo numerosi concerti tra cui quelli per le Associazioni Musicali: \u201cM. Quintieri\u201d, \u201cICAMS\u201d, \u201cFoyer des Arts\u201d, \u201cF.I.D.A.P.A\u201d, \u201cAssociazioneBach\u201d di San Calogero. Dal Luglio 2014 collabora con l\u2019Associazione \u201cArs Lab\u201d, ente parallelo alla Fondazione Pavarotti, per il quale ha tenuto concerti in giro per il mondo. <em>&#8220;Nel nostro cuore<\/em> &#8211; dichiarano fieri &#8211;<em> non per campanilismo, portiamo le nostre origini e l&#8217;amore per la Calabria&#8221;<\/em>.\u00a0La produzione \u00e8 della <strong>Lp Production<\/strong>.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-341537 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2020\/02\/84309053_2822035541150691_2598063586077048832_o-400x400.jpg\" alt=\"\" width=\"400\" height=\"400\" title=\"\"><\/p>\n<h2>Un&#8217;opera &#8216;rock&#8217;<\/h2>\n<p>Il titolo dello spettacolo sembra al quanto appropriato:<strong> \u201cAmore\u2013Opera Show\u201d<\/strong> perch\u00e9 in fondo &#8220;<em>l\u2019amore \u00e8 un\u2019opera&#8221;. <\/em>Oltre i tre artisti, si esibiranno talenti dello scenario musicale calabrese e special guest non ancora svelati. <strong>Sar\u00e0 un\u2019opera rock, tra canto lirico e chitarre graffianti.<\/strong> Un concerto evento che vuole essere la prima tappa di un possibile tour in giro per i teatri fuori regione. Iniziare dalla Calabria significa voler dimostrare amore verso questa terra. <em>\u201cAbbiamo il privilegio di calcare palcoscenici importantissimi. Sono tanti i contesti nei qualici siamo esibiti, da Broadway all\u2019Arena di Verona. Ma il piacere di esibirci nella nostra regione\u00e8 immenso. Ci emoziona tanto! Infatti abbiamo subito accettato la proposta della Lp Production. Porteremo un\u2019opera Lirica\/Rock.\u201d<\/em> Queste le parole di Andrea Bauleo pronte a spiegare una serata evento che regaler\u00e0 grandi sorprese ed emozioni.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La musica lirica \u00e8 una forma d&#8217;arte di origini antiche, che riscontra anche in Calabria molto interesse.<\/p>\n","protected":false},"author":45,"featured_media":125142,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[40],"tags":[],"class_list":["post-125141","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura-spettacolo"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/125141","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/45"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=125141"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/125141\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/125142"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=125141"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=125141"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=125141"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}