{"id":125406,"date":"2020-03-02T11:14:24","date_gmt":"2020-03-02T10:14:24","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/coronavirus-voli-per-litalia-cancellati-e-modificati-dalle-compagnie-aeree\/"},"modified":"2023-01-16T17:53:55","modified_gmt":"2023-01-16T16:53:55","slug":"342296-coronavirus-voli-per-litalia-cancellati-e-modificati-dalle-compagnie-aeree","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/342296-coronavirus-voli-per-litalia-cancellati-e-modificati-dalle-compagnie-aeree\/","title":{"rendered":"Coronavirus, voli per l&#8217;Italia cancellati e modificati dalle compagnie aeree"},"content":{"rendered":"<h4 class=\"article-subtitle\">Da Lufthansa a EasyJet decine di compagnie hanno rivisto i loro voli per l\u2019Italia. Ecco tutti i cambiamenti previsti e i blocchi sulle nostre rotte<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>La grande fuga dall&#8217;Italia per paura del Coronavirus fa <strong>moltiplicare le cancellazioni e le rimodulazioni dei voli aerei da e verso il nostro Paese.<\/strong> E anche Alitalia si adegua, eliminando i collegamenti su <strong>38 rotte<\/strong> a causa del gran numero di posti lasciati vuoti. Tra defezioni dei passeggeri e crollo delle prenotazioni, le compagnie aeree stanno di giorno in giorno ricalibrando i collegamenti &#8211; come nel caso di British Airways, Brussels Airline e anche EasyJet &#8211; e in alcuni casi hanno decretato il <strong>blocco sulle nostre rotte.\u00a0<\/strong><\/p>\n<h3><strong>L&#8217;ELENCO DELLE ULTIME MISURE<\/strong><\/h3>\n<p><strong>Lufthansa &#8220;ridurr\u00e0 la capacit\u00e0 dei voli verso l&#8217;Italia&#8221;<\/strong>. La decisione coinvolge i voli verso Milano, Venezia, Roma, Torino, Verona, Bologna, Ancona e Pisa. Lufthansa estende la sospensione dei voli verso la Cina continentale fino al 24 aprile e verso Teheran fino al 30 aprile.<\/p>\n<p><strong>L&#8217;Uzbekistan sospende il volo diretto con Roma &#8211;\u00a0<\/strong>L&#8217;Uzbekistan Airways ha sospeso i voli per Tokyo e Roma dal 1\u00b0 marzo. &#8220;L&#8217;Uzbekistan Airways sospende temporaneamente i voli regolari per Tokyo e Roma il 1\u00b0 marzo a causa dello scoppio del coronavirus in Giappone e in Italia&#8221;, ha dichiarato la compagnia aerea in un comunicato. Tutti coloro che arrivano da paesi che hanno registrato casi di coronavirus saranno messi in quarantena per 14 giorni. Come riportato domenica, i voli regolari per Seul saranno temporaneamente sospesi nella stessa data.<\/p>\n<p><strong>Delta sospende temporaneamente i voli N.Y.-Milano<\/strong>\u00a0&#8211;\u00a0Delta Airline ha annunciato che sospende tutti i voli per Milano sino al primo maggio. Proseguiranno invece i collegamenti<\/p>\n<p><strong>American Airlines sospende voli su Milano<\/strong>\u00a0&#8211;\u00a0American Airlines ha reso noto di aver sospeso sino al 24 aprile tutti i voli da e per Milano, dall&#8217;aeroporto Jfk di New York e da quello di Miami<\/p>\n<p><strong>La Turchia sospende voli per l&#8217;Italia<\/strong>\u00a0&#8211; La Turchia ha deciso la sospensione a tempo indeterminato di tutti i collegamenti aerei con l&#8217;Italia.<\/p>\n<p><strong>Wizz air sospende volo Podgorica-Milano &#8211;\u00a0<\/strong>La compagnia low cost ungherese Wizz air ha annunciato la sospensione del collegamento aereo fra Podgorica e Milano fino al 2 aprile<\/p>\n<p><strong>Rep.Dominicana, sospesi un mese voli da Milano<\/strong>\u00a0&#8211;\u00a0La Repubblica Dominicana ha annunciato di avere deciso la sospensione per 30 giorni di quattro voli settimanali provenienti da Milano.<\/p>\n<p><strong>Il Libano vieta l&#8217;ingresso a chi arriva dall&#8217;Italia\u00a0<\/strong>&#8211; Il Libano vieta l&#8217;ingresso nel Paese a tutti i passeggeri di voli provenienti dall&#8217;Italia a meno che non siano cittadini libanesi o stranieri che abbiano un permesso di residenza nel paese.<\/p>\n<p><strong>British Airways e Iberia, ridotta capacit\u00e0 voli per Italia<\/strong>\u00a0&#8211;\u00a0&#8220;La capacit\u00e0 sulle rotte italiane per marzo \u00e8 stata significativamente ridotta attraverso un mix di cancellazioni e il cambiamento della dimensione degli aerei e ulteriori riduzioni di capacit\u00e0 saranno attivate nei prossimi giorni. Ci attendiamo di attuare una riduzione di capacit\u00e0 anche attraverso il nostro pi\u00f9 ampio network a corto raggio&#8221;. Lo afferma Iag, il gruppo che controlla British Airways e Iberia<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Da Lufthansa a EasyJet decine di compagnie hanno rivisto i loro voli per l\u2019Italia. Ecco tutti i cambiamenti previsti e i blocchi sulle nostre rotte<\/p>\n","protected":false},"author":22,"featured_media":125407,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[22,16],"tags":[],"class_list":["post-125406","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dal-mondo","category-italia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/125406","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=125406"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/125406\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/125407"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=125406"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=125406"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=125406"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}