{"id":125646,"date":"2020-03-06T08:23:59","date_gmt":"2020-03-06T07:23:59","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/evade-dai-domiciliari-individuato-e-arrestato-32enne-cosentino\/"},"modified":"2023-01-16T17:54:12","modified_gmt":"2023-01-16T16:54:12","slug":"342998-evade-dai-domiciliari-individuato-e-arrestato-32enne-cosentino","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/342998-evade-dai-domiciliari-individuato-e-arrestato-32enne-cosentino\/","title":{"rendered":"Evade dai domiciliari, individuato e arrestato 32enne cosentino"},"content":{"rendered":"<h4>L\u2019uomo si era allontanato dal proprio domicilio dove era ristretto in regime di arresti domiciliari per precedenti <strong>reati di estorsione e traffico di stupefacenti<\/strong>, fatti risalenti al 2016<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; Personale dell\u2019ufficio prevenzione generale e soccorso pubblico della Questura di Cosenza (Squadra Volante), durante i controlli del territorio hanno tratto in <strong>arresto F. A. cosentino di 32 anni.<\/strong> L\u2019uomo si era allontanato dal proprio domicilio dove era ristretto in regime di arresti domiciliari per precedenti <strong>reati di estorsione e traffico di stupefacenti<\/strong>, fatti risalenti al 2016.<\/p>\n<p>Alla richiesta di documenti, da parte del personale della Polizia di Stato, <strong>l\u2019evaso cercava di eludere il controllo<\/strong> ma a seguito di ulteriori accertamenti, emergeva che la persona era ristretto agli arresti domiciliari. Informata l\u2019Autorit\u00e0 giudiziaria competente fissava per l\u2019arrestato il giudizio per direttissima.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019uomo si era allontanato dal proprio domicilio dove era ristretto in regime di arresti domiciliari per precedenti reati di estorsione e traffico di stupefacenti, fatti risalenti al 2016<\/p>\n","protected":false},"author":22,"featured_media":125647,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[42],"tags":[],"class_list":["post-125646","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/125646","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=125646"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/125646\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/125647"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=125646"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=125646"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=125646"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}