{"id":125864,"date":"2020-03-10T13:47:55","date_gmt":"2020-03-10T12:47:55","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/decreto-iorestoacasa-il-governo-fa-ulteriore-chiarezza-spiegando-tutte-le-misure-adottate\/"},"modified":"2023-01-16T17:54:27","modified_gmt":"2023-01-16T16:54:27","slug":"343625-decreto-iorestoacasa-il-governo-fa-ulteriore-chiarezza-spiegando-tutte-le-misure-adottate","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/343625-decreto-iorestoacasa-il-governo-fa-ulteriore-chiarezza-spiegando-tutte-le-misure-adottate\/","title":{"rendered":"Decreto #IoRestoaCasa, il Governo fa ulteriore chiarezza spiegando tutte le misure adottate"},"content":{"rendered":"<h4>Palazzo Chigi ha fatto ulteriore chiarezza sulle misure adottate nel decreto firmato ieri dal Premier Conte, pubblicando una serie di domande (e risposte) frequenti sulle misure adottate e i comportamenti che i cittadini dovranno tenere ribadendo che <strong>si potr\u00e0 sempre uscire per acquistare generi alimentari che saranno sempre disponobili<\/strong><!--more--><\/h4>\n<p><span style=\"color: #ffffff;\">.<\/span><\/p>\n<p>COSENZA &#8211; Stop agli spostamenti, scuole chiuse fino al prossimo 3 aprile, blocco di ogni manifestazione sportiva, compresi i campionati di calcio. Da oggi \u00e8 in vigore in Italia la <span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/quicosenza.it\/news\/9767\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>zona protetta<\/strong><\/a><\/span>, con<strong> l&#8217;estensione a tutto il territorio nazionale delle misure gi\u00e0 previste dal Dpcm dello scorso 8 marzo<\/strong>. Il testo, dopo la firma del Presidente del Consiglio Conte, \u00e8 stato pubblicato in Gazzetta Ufficiale e le nuove misure sono gi\u00e0 operative. Dal Governo, viste anche le tantissime richieste di chiarimento e i dubbi dei cittadini, ha pubblicato un ulteriore approfondimento sulle misure del decreto <strong>#iorestoacasa<\/strong> per fugare ogni dubbio e dare risposta alle domande di tutti noi. Di seguito le risposte alle domande pi\u00f9 frequenti sulle misure adottate dal Governo che ha ribadito ancora una volta che <strong>si potr\u00e0 sempre uscire per acquistare generi alimentari<\/strong> <strong>e\u00a0non c&#8217;\u00e8 alcuna necessit\u00e0 di accaparrarseli ora<\/strong>\u00a0<strong>perch\u00e9 saranno sempre disponibili.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #ff0000;\"><strong>ZONE INTERESSATE DAL DECRETO<\/strong><\/span><\/p>\n<p><strong>1 Ci sono differenze all\u2019interno del territorio nazionale?<\/strong><br \/>\nNo, per effetto del dpcm del 9 marzo le regole sono uguali su tutto il territorio nazionale e sono efficaci dalla data del 10 marzo e sino al 3 aprile.<\/p>\n<p><strong>2 Sono ancora previste zone rosse?<\/strong><br \/>\nNo, non sono pi\u00f9 previste zone rosse. Le limitazioni che erano previste nel precedente dpcm del 1\u00b0 marzo (con l\u2019istituzione di specifiche zone rosse) sono cessate. Ormai, con il dpcm del 9 marzo, le regole sono uguali per tutti.<\/p>\n<p><span style=\"color: #ff0000;\"><strong>SPOSTAMENTI<\/strong><\/span><\/p>\n<p><strong>1 Cosa si intende per \u201cevitare ogni spostamento delle persone fisiche\u201d? Ci sono dei divieti? Si pu\u00f2 uscire per andare al lavoro? Chi \u00e8 sottoposto alla misura della quarantena, si pu\u00f2 spostare?<\/strong><br \/>\nSi deve evitare di uscire di casa. Si pu\u00f2 uscire per andare al lavoro \u00a0o per ragioni di salute o per altre necessit\u00e0, quali, per esempio, l\u2019acquisto di beni essenziali. Si deve comunque essere in grado di provarlo, anche mediante autodichiarazione (<span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/quicosenza.it\/news\/9768\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Si scarica qui<\/strong><\/a><\/span>) che potr\u00e0 essere resa su moduli prestampati gi\u00e0 in dotazione alle forze di polizia statali e locali. La veridicit\u00e0 delle autodichiarazioni sar\u00e0 oggetto di controlli successivi e la non veridicit\u00e0 costituisce reato. \u00c8 comunque consigliato lavorare a distanza, ove possibile, o prendere ferie o congedi. Senza una valida ragione, \u00e8 richiesto e necessario restare a casa, per il bene di tutti.<br \/>\n\u00c8\u00a0previsto anche il \u201cdivieto assoluto\u201d di uscire da casa per chi \u00e8 sottoposto a quarantena o risulti positivo al virus.<\/p>\n<p><strong>2 Se abito in un comune e lavoro in un altro, posso fare \u201cavanti e indietro\u201d?<\/strong><br \/>\nS\u00ec, \u00e8 uno spostamento giustificato per esigenze lavorative.<\/p>\n<p><strong>3 Ci sono limitazioni negli spostamenti per chi ha sintomi da infezione respiratoria e febbre superiore a 37,5?<\/strong><br \/>\nIn questo caso si raccomanda fortemente di rimanere a casa, contattare il proprio medico e limitare al massimo il contatto con altre persone.<\/p>\n<p><strong>4 Cosa significa \u201ccomprovate esigenze lavorative\u201d? I lavoratori autonomi come faranno a dimostrare le \u201ccomprovate esigenze lavorative\u201d?<\/strong><br \/>\n\u00c8 sempre possibile uscire per andare al lavoro, anche se \u00e8 consigliato lavorare a distanza, ove possibile, o prendere ferie o congedi. \u201cComprovate\u201d significa che si deve essere in grado di dimostrare che si sta andando (o tornando) al lavoro, anche tramite l\u2019autodichiarazione vincolante di cui alla FAQ n. \u00a01 o con ogni altro mezzo di prova , la cui non veridicit\u00e0 costituisce reato. In caso di controllo, si dovr\u00e0 dichiarare la propria necessit\u00e0 lavorativa. Sar\u00e0 cura poi delle Autorit\u00e0 verificare la veridicit\u00e0 della dichiarazione resa con l\u2019adozione delle conseguenti sanzioni in caso di false dichiarazioni.<\/p>\n<p><strong>5 Come si devono comportare i transfrontalieri?<\/strong><br \/>\nI transfrontalieri potranno entrare e uscire dai territori interessati per raggiungere il posto di lavoro e tornare a casa. Gli interessati potranno comprovare il motivo lavorativo dello spostamento con qualsiasi mezzo (vedi faq precedente).<\/p>\n<p><strong>6 Ci saranno posti di blocco per controllare il rispetto della misura?<\/strong><br \/>\nCi saranno controlli. In presenza di regole uniformi sull\u2019intero territorio nazionale, non ci saranno posti di blocco fissi per impedire alle persone di muoversi. La Polizia municipale e le forze di polizia, nell\u2019ambito della loro ordinaria attivit\u00e0 di controllo del territorio, vigileranno sull\u2019osservanza delle regole.<\/p>\n<p><strong>7 Chi si trova fuori dal proprio domicilio, abitazione o residenza potr\u00e0 rientrarvi?<\/strong><br \/>\nS\u00ec, chiunque ha diritto a rientrare presso il proprio domicilio, abitazione o residenza, fermo restando che poi si potr\u00e0 spostare solo per esigenze lavorative, situazioni di necessit\u00e0 o motivi di salute.<\/p>\n<p><strong>8 \u00c8 possibile uscire per andare ad acquistare generi alimentari? I generi alimentari saranno sempre disponibili?<\/strong><br \/>\nS\u00ec, si potr\u00e0 sempre uscire per acquistare generi alimentari e non c\u2019\u00e8 alcuna necessit\u00e0 di accaparrarseli ora perch\u00e9 saranno sempre disponibili.<\/p>\n<p><strong>9 \u00c8 consentito fare attivit\u00e0 motoria?<\/strong><br \/>\nS\u00ec, l\u2019attivit\u00e0 motoria all\u2019aperto \u00e8 consentita purch\u00e9 non in gruppo.<\/p>\n<p><strong>10 Si pu\u00f2 uscire per acquistare beni diversi da quelli alimentari?<\/strong><br \/>\nSi, ma solo in caso di stretta necessit\u00e0 (acquisto di beni necessari, come ad esempio le lampadine che si sono fulminate in casa).<\/p>\n<p><strong>11 Posso andare ad assistere i miei cari anziani non autosufficienti?<\/strong><br \/>\nS\u00ec, \u00e8 una condizione di necessit\u00e0. Ricordate per\u00f2 che gli anziani sono le persone pi\u00f9 vulnerabili e quindi cercate di proteggerle dai contatti il pi\u00f9 possibile.<\/p>\n<p><span style=\"color: #ff0000;\"><strong>TRASPORTI<\/strong><\/span><\/p>\n<p><strong>1 Sono previste limitazioni per il transito delle merci?<\/strong><br \/>\nNo, nessuna limitazione. Tutte le merci (quindi non solo quelle di prima necessit\u00e0) possono essere trasportate sul territorio nazionale. Il trasporto delle merci \u00e8 considerato come un\u2019esigenza lavorativa: il personale che conduce i mezzi di trasporto pu\u00f2 spostarsi, limitatamente alle esigenze di consegna o prelievo delle merci.<\/p>\n<p><strong>2 I corrieri merci possono circolare?<\/strong><br \/>\nS\u00ec, possono circolare.<\/p>\n<p><strong>3 Sono un autotrasportatore. Sono previste limitazioni alla mia attivit\u00e0 lavorativa?<\/strong><br \/>\nNo, non sono previste limitazioni al transito e all\u2019attivit\u00e0 di carico e scarico delle merci.<\/p>\n<p><strong>4 Esistono limitazioni per il trasporto pubblico non di linea?<\/strong><br \/>\nNo. Non esistono limitazioni per il trasporto pubblico non di linea. Il servizio taxi e di ncc non ha alcuna limitazione in quanto l\u2019attivit\u00e0 svolta \u00a0\u00e8 considerata esigenza lavorativa.<\/p>\n<p><span style=\"color: #ff0000;\"><strong>UFFICI E DIPENDENTI PUBBLICI<\/strong><\/span><\/p>\n<p><strong>1 Gli uffici pubblici rimangono aperti?<\/strong><br \/>\nS\u00ec, su tutto il territorio nazionale. L\u2019attivit\u00e0 amministrativa \u00e8 svolta regolarmente. In ogni caso quasi tutti i servizi sono fruibili on line. E\u2019 prevista comunque la sospensione delle attivit\u00e0 didattiche e formative in presenza di scuole, nidi, musei, biblioteche.<\/p>\n<p><strong>2 Il decreto dispone per addetti, utenti e visitatori degli uffici delle pubbliche amministrazioni, sull\u2019intero territorio nazionale, la messa a disposizione di soluzioni disinfettanti per l\u2019igiene delle mani. Nel caso di difficolt\u00e0 di approvvigionamento di tali soluzioni e conseguente loro indisponibilit\u00e0 temporanea, gli uffici devono rimanere comunque aperti?<\/strong><br \/>\nGli uffici devono rimanere comunque aperti. La presenza di soluzioni disinfettanti \u00e8 una misura di ulteriore precauzione ma la loro temporanea indisponibilit\u00e0 non giustifica la chiusura dell\u2019ufficio, ponendo in atto tutte le misure necessarie per reperirle.<\/p>\n<p><strong>3 Il dipendente pubblico che ha sintomi febbrili \u00e8 in regime di malattia ordinaria o ricade nel disposto del decreto-legge per cui non vengono decurtati i giorni di malattia?<\/strong><br \/>\nRientra nel regime di malattia ordinaria. Qualora fosse successivamente accertato che si tratta di un soggetto che rientra nella misura della quarantena o infetto da COVID-19, non si applicherebbe la decurtazione.<\/p>\n<p><strong>4 Sono un dipendente pubblico e vorrei lavorare in smart working. Che strumenti ho?<\/strong><br \/>\nLe nuove misure incentivano il ricorso allo smart working, semplificandone l\u2019accesso. Compete al datore di lavoro individuare le modalit\u00e0 organizzative che consentano di riconoscere lo smart working al maggior numero possibile di dipendenti. Il dipendente potr\u00e0 presentare un\u2019istanza che sar\u00e0 accolta sulla base delle modalit\u00e0 organizzative previste.<\/p>\n<p><span style=\"color: #ff0000;\"><strong>PUBBLICI ESERCIZI<\/strong><\/span><\/p>\n<p><strong>1 Bar e ristoranti possono aprire regolarmente?<\/strong><br \/>\n\u00c8 consentita l\u2019attivit\u00e0 di ristorazione e bar dalle 6.00 alle 18.00, con obbligo a carico del gestore di predisporre le condizioni per garantire la possibilit\u00e0 del rispetto della distanza di sicurezza interpersonale di almeno un metro, con sanzione della sospensione dell\u2019attivit\u00e0 in caso di violazione.<\/p>\n<p><strong>2\u00a0Si potranno comunque effettuare consegne a domicilio di cibi e bevande?<\/strong><br \/>\nIl limite orario dalle 6.00 alle 18.00 \u00e8 riferito solo all\u2019apertura al pubblico. L\u2019attivit\u00e0 pu\u00f2 comunque proseguire negli orari di chiusura al pubblico mediante consegne a domicilio. Sar\u00e0 cura di chi organizza l\u2019attivit\u00e0 di consegna a domicilio \u2013 lo stesso esercente ovvero una cosiddetta piattaforma \u2013 evitare che il momento della consegna preveda contatti personali.<\/p>\n<p><strong>3 Sono gestore di un pub. Posso continuare ad esercitare la mia attivit\u00e0?<\/strong><br \/>\nIl divieto previsto dal DPCM riguarda lo svolgimento nei pub di ogni attivit\u00e0 diversa dalla somministrazione di cibi e bevande. \u00c8 possibile quindi continuare a somministrare cibo e bevande nei pub, sospendendo attivit\u00e0 ludiche ed eventi aggregativi (come per esempio la musica dal vivo, proiezioni su schermi o altro), nel rispetto delle limitazioni orarie gi\u00e0 previste per le attivit\u00e0 di bar e ristoranti (dalle 6.00 alle 18.00) e, comunque, con l\u2019obbligo di far rispettare la distanza di sicurezza interpersonale di almeno un metro.<\/p>\n<p><strong>4 Cosa \u00e8 previsto per teatri, cinema, musei, archivi, biblioteche e altri luoghi della cultura?<\/strong><br \/>\nNe \u00e8 prevista la chiusura al pubblico su tutto il territorio nazionale.<\/p>\n<p><span style=\"color: #ff0000;\"><strong>SCUOLA<\/strong><\/span><\/p>\n<p><strong>1 Cosa prevede il decreto per le scuole?<\/strong><br \/>\nNel periodo sino al 3 aprile 2020, \u00e8 sospesa la frequenza delle scuole di ogni ordine e grado. Resta la possibilit\u00e0 di svolgimento di attivit\u00e0 didattiche a distanza, tenendo conto, in particolare, delle specifiche esigenze degli studenti con disabilit\u00e0.<\/p>\n<p><span style=\"color: #ff0000;\"><strong>UNIVERSIT<\/strong><b>\u00c0<\/b><\/span><\/p>\n<p><strong>1 Cosa prevede il decreto per le universit\u00e0?<\/strong><br \/>\nNel periodo sino al 3 aprile 2020, \u00e8 sospesa la frequenza delle attivit\u00e0 di formazione superiore, comprese le universit\u00e0 e le istituzioni di alta formazione artistica musicale e coreutica, di corsi professionali, master e universit\u00e0 per anziani. Resta la possibilit\u00e0 di svolgimento di attivit\u00e0 formative a distanza, tenendo conto, in particolare, delle specifiche esigenze degli studenti con disabilit\u00e0. Non \u00e8 sospesa l\u2019attivit\u00e0 di ricerca.<\/p>\n<p><strong>2 Si possono tenere le sessioni d\u2019esame e le sedute di laurea?<\/strong><br \/>\nS\u00ec, potranno essere svolti ricorrendo in via prioritaria alle modalit\u00e0 a distanza o comunque adottando le precauzioni di natura igienico sanitaria ed organizzative indicate dal dpcm del 4 marzo; nel caso di esami e sedute di laurea a distanza, dovranno comunque essere assicurate le misure necessarie a garantire la prescritta pubblicit\u00e0.<\/p>\n<p><strong>3 Si possono tenere il ricevimento degli studenti e le altre attivit\u00e0?<\/strong><br \/>\nS\u00ec. Corsi di dottorato, ricevimento studenti, test di immatricolazione, partecipazione a laboratori, etc., potranno essere erogati nel rispetto delle misure precauzionali igienico sanitarie, ricorrendo in via prioritaria alle modalit\u00e0 a distanza. Anche in questo caso particolare attenzione dovr\u00e0 essere data agli studenti con disabilit\u00e0.<\/p>\n<p><strong>4 Cosa si prevede per i corsi per le specializzazioni mediche?<\/strong><br \/>\nDalla sospensione sono esclusi i corsi post universitari connessi con l\u2019esercizio delle professioni sanitarie, inclusi quelli per i medici in formazione specialistica, e le attivit\u00e0 dei tirocinanti delle professioni sanitarie e medica. Non \u00e8 sospesa l\u2019attivit\u00e0 di ricerca.<\/p>\n<p><strong>5 Cosa succede a chi \u00e8 in Erasmus?<\/strong><br \/>\nPer quanto riguarda i progetti Erasmus+, occorre riferirsi alle indicazioni delle competenti Istituzioni europee, assicurando, comunque, ai partecipanti ogni informazione utile.<\/p>\n<p><span style=\"color: #ff0000;\"><strong>CERIMONIE ED EVENTI<\/strong><\/span><\/p>\n<p><strong>1 Cosa prevede il decreto su cerimonie, eventi e spettacoli?<\/strong><br \/>\nSu tutto il territorio nazionale sono sospese tutte le manifestazioni organizzate nonch\u00e9 gli eventi in luogo pubblico o privato, ivi compresi quelli di carattere culturale, ludico, sportivo, religioso e fieristico, anche se svolti in luoghi chiusi ma aperti al pubblico (quali, a titolo d\u2019esempio, cinema, teatri, pub, scuole di ballo, sale giochi, sale scommesse e sale bingo, discoteche e locali assimilati).<\/p>\n<p><strong>2 Si pu\u00f2 andare in chiesa o negli altri luoghi di culto? Si possono celebrare messe o altri riti religiosi?<\/strong><br \/>\nFino al 3 aprile sono sospese su tutto il territorio nazionale tutte le cerimonie civili e religiose, compresi i funerali. Pertanto \u00e8 sospesa anche la celebrazione della messa e degli altri riti religiosi, come la preghiera del venerd\u00ec mattina per la religione islamica.<br \/>\nSono consentiti l\u2019apertura e l\u2019accesso ai luoghi di culto, purch\u00e9 si evitino assembramenti e si assicuri la distanza tra i frequentatori non inferiore a un metro.<\/p>\n<p><span style=\"color: #ff0000;\"><strong>TURISMO<\/strong><\/span><\/p>\n<p><strong>1 Cosa prevede il decreto per gli spostamenti per turismo?<\/strong><br \/>\nSull\u2019intero territorio nazionale gli spostamenti per motivi di turismo sono assolutamente da evitare. I turisti italiani e stranieri che gi\u00e0 si trovano in vacanza debbono limitare gli spostamenti a quelli necessari per rientrare nei propri luoghi di residenza, abitazione o domicilio.<br \/>\nPoich\u00e9 gli aeroporti e le stazioni ferroviarie rimangono aperti, i turisti potranno recarvisi per prendere l&#8217;aereo o il treno e fare rientro nelle proprie case. Si raccomanda di verificare lo stato dei voli e dei mezzi di trasporto pubblico nei siti delle compagnie di trasporto terrestre, marittimo e aereo.<\/p>\n<p><strong>2 Come trova applicazione la limitazione relativa alle attivit\u00e0 di somministrazione e bar, alle strutture turistico ricettive?<\/strong><br \/>\nLe strutture ricettive possono svolgere attivit\u00e0 di somministrazione e bar anche nella fascia oraria dalle ore 18 alle ore 6, esclusivamente in favore dei propri clienti e nel rispetto di tutte le precauzioni di sicurezza di cui al dpcm dell\u20198 marzo.<\/p>\n<p><strong>3 Come si deve comportare la struttura turistico ricettiva rispetto ad un cliente? Deve verificare le ragioni del suo viaggio?<\/strong><br \/>\nNon compete alla struttura turistico ricettiva la verifica della sussistenza dei presupposti che consentono lo spostamento delle persone fisiche.<\/p>\n<p><span style=\"color: #ff0000;\"><strong>AGRICOLTURA<\/strong><\/span><\/p>\n<p><strong>1 Sono previste limitazioni per il trasporto di animali vivi, alimenti per animali e di prodotti agroalimentari e della pesca?<\/strong><br \/>\nNo, non sono previste limitazioni.<\/p>\n<p><strong>2 Se sono un imprenditore agricolo, un lavoratore agricolo, anche stagionale, sono previste limitazioni alla mia attivit\u00e0 lavorativa?<\/strong><br \/>\nNo, non sono previste limitazioni.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Palazzo Chigi ha fatto ulteriore chiarezza sulle misure adottate nel decreto firmato ieri dal Premier Conte, pubblicando una serie di domande (e risposte) frequenti sulle misure adottate e i comportamenti che i cittadini dovranno tenere ribadendo che si potr\u00e0 sempre uscire per acquistare generi alimentari che saranno sempre disponobili<\/p>\n","protected":false},"author":55,"featured_media":125865,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16],"tags":[],"class_list":["post-125864","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-italia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/125864","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=125864"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/125864\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/125865"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=125864"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=125864"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=125864"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}