{"id":126281,"date":"2020-03-16T20:00:45","date_gmt":"2020-03-16T19:00:45","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/comune-di-rende-dona-al-poliambulatorio-di-quattromiglia-un-termometro-a-raggi-infrarossi\/"},"modified":"2023-01-16T17:54:54","modified_gmt":"2023-01-16T16:54:54","slug":"344722-comune-di-rende-dona-al-poliambulatorio-di-quattromiglia-un-termometro-a-raggi-infrarossi","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/344722-comune-di-rende-dona-al-poliambulatorio-di-quattromiglia-un-termometro-a-raggi-infrarossi\/","title":{"rendered":"Comune di Rende dona al Poliambulatorio di Quattromiglia un termometro a raggi infrarossi"},"content":{"rendered":"<h4>Mirabelli: &#8220;Servir\u00e0, non solo per i nostri pazienti, ma anche per i dipendenti della struttura. <strong>\u00c8 molto importante in questo momento storico non lasciare nulla al caso&#8221;<\/strong> <!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>RENDE (CS) &#8211; Prosegue senza sosta il lavoro del sindaco di Rende Marcello Manna, massima autorit\u00e0 sanitaria e a capo della Protezione civile locale, in queste giornate di emergenza. Il primo cittadino anche stamane ha indetto in sala giunta la consueta <strong>riunione operativa<\/strong> con il comandante della polizia municipale <strong>Vincenzo Settino<\/strong>, gli assessori e i dirigenti <strong>Francesco Minutolo, Roberta Vercillo e Francesco Azzato.\u00a0\u00a0<\/strong>Il sindaco ha chiesto un ulteriore sforzo alla polizia municipale affinch\u00e9 siano seguite le disposizioni del Governo centrale disponendo controlli pi\u00f9 serrati e costanti sul territorio. Lo stesso Manna, dalle sue pagine social, ha invitato la popolazione a <strong>\u201crestare a casa\u201d<\/strong>, ribadendo che, come sottolineato dal presidente dell\u2019ISS Silvio Brusaferro: \u201c<strong>non ci sar\u00e0 esplosione al Sud se i cittadini saranno rigorosi.<\/strong> Per questo oggi pi\u00f9 che mai ribadisco il mio invito a restare a casa e uscire solo in casi di strettissima necessit\u00e0\u201d.<\/p>\n<p>Dal poliambulatorio di Quattromiglia, intanto, il direttore del distretto di Rende, <strong>Ottorino Zuccarelli<\/strong> e il responsabile del poliambulatorio <strong>Eugenio Mirabelli,<\/strong> hanno ringraziato l\u2019amministrazione comunale di Rende \u201cper aver donato alla struttura sanitaria di Quattromiglia un <strong>termometro a raggi infrarossi<\/strong> che servir\u00e0, non solo per i nostri pazienti, ma anche per i dipendenti della struttura. <strong>\u00c8 molto importante in questo momento storico non lasciare nulla al caso.<\/strong> L\u2019amministrazione comunale di Rende, ancora una volta, si \u00e8 dimostrata sensibile e vicina e di questo non possiamo che essere soddisfatti\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mirabelli: &#8220;Servir\u00e0, non solo per i nostri pazienti, ma anche per i dipendenti della struttura. \u00c8 molto importante in questo momento storico non lasciare nulla al caso&#8221;<\/p>\n","protected":false},"author":22,"featured_media":126282,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[44],"tags":[],"class_list":["post-126281","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rende"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/126281","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=126281"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/126281\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/126282"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=126281"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=126281"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=126281"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}