{"id":126325,"date":"2020-03-19T08:00:49","date_gmt":"2020-03-19T07:00:49","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/tutte-le-radio-unite-domani-per-linno-di-mameli\/"},"modified":"2023-01-16T17:54:58","modified_gmt":"2023-01-16T16:54:58","slug":"344839-tutte-le-radio-unite-domani-per-linno-di-mameli","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/344839-tutte-le-radio-unite-domani-per-linno-di-mameli\/","title":{"rendered":"Tutte le radio unite domani, per l&#8217;Inno di Mameli. Anche Rlb suoner\u00e0 per l&#8217;Italia"},"content":{"rendered":"<h4>Uno strumento di compagnia e di conforto, la cui voce si far\u00e0 sentire a frequenze unificate, domattina alle ore 11.<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; Era il 6 ottobre del 1924 quando con questo annuncio iniziavano le regolari trasmissioni radiofoniche in Italia. A quasi cento anni dal primo programma,<strong> per la prima volta in assoluto nella storia del nostro Paese<\/strong>, tutte le Radio Italiane, nazionali e locali, si uniranno. E&#8217; un\u2019iniziativa di diffusione comune senza precedenti. Uno strumento di compagnia e di conforto, la cui voce si far\u00e0 sentire a frequenze unificate. Domattina si trasmetter\u00e0 in contemporanea, anche su tutte le piattaforme Fm, Dab, in televisione e in streaming sui siti e sulle App delle radio, l\u2019<strong>Inno di Mameli e tre canzoni che hanno fatto la storia della musica nazionale<\/strong>. Un messaggio di unione, partecipazione e connessione, che ha l\u2019auspicio di riunire tutti nello stesso momento di condivisione.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-344842 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2020\/03\/download.jpg\" alt=\"\" width=\"275\" height=\"183\" title=\"\"><\/p>\n<p>Parteciperanno all\u2019iniziativa le emittenti radiofoniche nazionali: Rai Radio 1, Rai Radio 2, Rai Radio 3, Rai Isoradio, M2O, R101, Radio 105, Radio 24, Radio Capital, Radio Deejay, Radio Freccia, Radio Italia Solomusicaitaliana, Radio Kiss Kiss, Radio Maria, Radio Monte Carlo, Radio Radicale, Radio Zeta, RDS 100% grandi successi, RTL 102.5, Virgin Radio. Inoltre, parteciperanno anche le emittenti radiofoniche locali aderenti all\u2019Associazione Aeranti-Corallo ed all\u2019Associazione Radio Locali FRT-Confindustria Radio Tv.<\/p>\n<p><strong>Anche <span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/quicosenza.it\/news\/7776\" target=\"_blank\" rel=\"noopener noreferrer\">RLB<\/a><\/span> suoner\u00e0 questo momento di condivisione in musica e orgoglio nazionale!\u00a0<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-344840 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2020\/03\/how-to-shine-in-local-radio-interviews-388892920.jpg\" alt=\"\" width=\"463\" height=\"337\" title=\"\"><\/p>\n<p>Tutti sono invitati a sintonizzarsi sulla propria stazione radio preferita, quella che accompagna ognuno nella propria quotidianit\u00e0, ad alzare il volume, ad <strong>aprire le finestre e uscire sui balconi e <\/strong><strong>cantare insieme, sventolando il tricolore<\/strong> o mostrando un simbolo dell\u2019Italia, per un momento che sia di riflessione e buona speranza per tutti.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uno strumento di compagnia e di conforto, la cui voce si far\u00e0 sentire a frequenze unificate, domattina alle ore 11.<\/p>\n","protected":false},"author":20,"featured_media":126326,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[40],"tags":[],"class_list":["post-126325","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura-spettacolo"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/126325","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=126325"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/126325\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/126326"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=126325"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=126325"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=126325"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}