{"id":126665,"date":"2020-03-22T11:45:48","date_gmt":"2020-03-22T10:45:48","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/resto-a-casa-e-bevo-vino-in-crescita-le-vendite-online\/"},"modified":"2023-01-16T17:55:20","modified_gmt":"2023-01-16T16:55:20","slug":"345721-resto-a-casa-e-bevo-vino-in-crescita-le-vendite-online","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/345721-resto-a-casa-e-bevo-vino-in-crescita-le-vendite-online\/","title":{"rendered":"Resto a casa e bevo vino, in crescita le vendite online"},"content":{"rendered":"<h4>Dopo il decreto della Presidenza del Consiglio &#8216;Io resto a casa&#8217;, in forte crescita +300% le vendite online di vino e spumanti<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p><strong>L&#8217;invito a stare a casa per prevenzione da Covid-19 fa tornare sulla tavola degli italiani il vino.<\/strong> Al supermercato il corner-vineria registra, nelle ultime tre settimane, il pienone, secondo l&#8217;Associazione della Distribuzione moderna (Adm) e l&#8217;osservatorio Iri Infoscan che monitorano 27mila punti vendita della Gdo. &#8220;<strong>All&#8217;inizio dell&#8217;emergenza in Italia coronavirus<\/strong> &#8211; spiega Virgilio Romano, account director di Iri Infoscan &#8211; nella settimana 17-23 febbraio le vendite di vino registravano una flessione: -0,6%. La settimana successiva il giro d&#8217;affari \u00e8 tornato in terreno positivo: +1,9%. Nella settimana 2-8 marzo, quando si \u00e8 estesa la zona rossa a tutta Italia, le vendite di vino hanno fatto un balzo del 6,3%. E a correre sono stati in particolare i vini Doc e Docg (+11,9%), e il vino comune (+3,9%)&#8221;. Nel carrello della spesa sembrano prevalere le etichette di denominazioni note, i grandi classici, e le etichette con cui si ha pi\u00f9 familiarit\u00e0. In assenza di aperitivi e happy hour &#8220;gli spumanti &#8211; precisa ancora Romano &#8211; hanno vendite altalenanti ma comunque a due cifre e sempre in terreno positivo: fino al 23 febbraio +17,6%, crollo a 5,7% nella settimana successiva, e poi ripresa a 11,7%&#8221;. <strong>Mentre le vendite online del largo consumo<\/strong>, secondo dati del panel Iri Ecommerce, &#8220;vedono in forte crescita, oltre il 300%, il click&amp;collect che accelera ulteriormente nelle tre settimane di emergenza sanitaria&#8221;. Curiosamente, conclude il presidente Associazione Distribuzione Moderna Giorgio Santambrogio, in questo periodo casalingo e senza timori di perdere punti nella patente perch\u00e9 l&#8217;auto \u00e8 ferma in garage, &#8220;crollano i vini da meditazione e i liquorosi: Passito &amp; Marsala, produzioni di nicchia nei volumi Gdo, scendono del 15,7%. Mentre le vendite di Champagne crollano del 53,2%&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dopo il decreto della Presidenza del Consiglio &#8216;Io resto a casa&#8217;, in forte crescita +300% le vendite online di vino e spumanti<\/p>\n","protected":false},"author":56,"featured_media":126666,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16],"tags":[],"class_list":["post-126665","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-italia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/126665","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/56"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=126665"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/126665\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/126666"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=126665"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=126665"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=126665"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}