{"id":126918,"date":"2020-03-26T14:00:14","date_gmt":"2020-03-26T13:00:14","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/coronavirus-altri-17-nuovi-contagiati-tra-catanzaro-crotone-e-vibo\/"},"modified":"2023-01-16T17:55:36","modified_gmt":"2023-01-16T16:55:36","slug":"346443-coronavirus-altri-17-nuovi-contagiati-tra-catanzaro-crotone-e-vibo","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/346443-coronavirus-altri-17-nuovi-contagiati-tra-catanzaro-crotone-e-vibo\/","title":{"rendered":"Coronavirus, altri 17 nuovi contagiati tra Catanzaro, Crotone e Vibo"},"content":{"rendered":"<h4>Tornano a salire i positivi al coronavirus nell&#8217;area centrale della Calabria dove nelle ultime 24 si contano 17 nuovi malati che portano a 156 i contagi tra le province di Catanzaro, Vibo Valentia e Crotone<!--more--><\/h4>\n<p>CATANZARO &#8211; Sono <strong>17 nuovi casi positivi<\/strong> riscontrati all\u2019ospedale Pugliese-Ciaccio. Questo il dato che emerge dal bollettino diramato dal nosocomio del capoluogo dove nelle ultime 24 ore sono stati effettuati <strong>158 tamponi<\/strong>. Di questi 88 sono stati fatti a pazienti provenienti dalla provincia di Catanzaro, 35 dalla provincia di Crotone e altrettanti da quella di Vibo Valentia. I nuovi positivi sono <strong>2 dalla provincia di Catanzaro<\/strong>,<strong> 9 dalla provincia di Crotone e 5 da Vibo<\/strong> dove un caso risulta dubbio e il tampone dovr\u00e0 essere ripetuto. Con il dato di oggi salgono a <strong>156 i contagiati nell&#8217;area centrale della Calabria<\/strong>. I ricoveri complessivi in malattie infettive sono 17 mentre sono<strong> 10 i pazienti in terapia intensiva<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tornano a salire i positivi al coronavirus nell&#8217;area centrale della Calabria dove nelle ultime 24 si contano 17 nuovi malati che portano a 156 i contagi tra le province di Catanzaro, Vibo Valentia e Crotone<\/p>\n","protected":false},"author":55,"featured_media":126919,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[681],"class_list":["post-126918","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","tag-coronavirus"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/126918","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=126918"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/126918\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/126919"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=126918"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=126918"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=126918"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}