{"id":127311,"date":"2020-04-02T08:54:19","date_gmt":"2020-04-02T06:54:19","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/coronavirus-calabrone-cgil-grave-chi-specula-la-richiesta-per-il-bonus-non-si-paga\/"},"modified":"2023-01-16T17:56:03","modified_gmt":"2023-01-16T16:56:03","slug":"347479-coronavirus-calabrone-cgil-grave-chi-specula-la-richiesta-per-il-bonus-non-si-paga","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/347479-coronavirus-calabrone-cgil-grave-chi-specula-la-richiesta-per-il-bonus-non-si-paga\/","title":{"rendered":"Coronavirus, Calabrone (Cgil): &#8220;Grave chi specula&#8221;. La richiesta per il bonus non si paga"},"content":{"rendered":"<h4>Lancia l&#8217;allarme il segretario della Cgil Cosenza, Umberto Calabrone, su Caf e patronati che chiedono soldi per inoltrare la domanda per il bonus da 600 a sostegno dei lavoratori e delle persone meno abbienti<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; La richiesta per il bonus di 600 euro previsto dal decreto &#8216;Cura Italia&#8217; <strong>\u00e8 gratuita e non ha alcun costo, per chiunque si rivolga a Caf o patronati<\/strong>. Di questi, chiunque chieda soldi per inoltrare la domanda, sta commettendo un abuso. A lanciare l&#8217;allarme \u00e8 Umberto Calabrone, segretario della Cgil Cosenza. &#8221; Ci hanno segnalato &#8211; ha dichiarato Calabrone ai <strong>microfoni di RLB<\/strong> &#8211; che <strong>alcuni caf e patronati<\/strong> <strong>si fanno pagare dalle 15 alle 25 euro per inoltrare la richiesta<\/strong> per ottenere il bonus a sostegno dei lavoratori o delle categorie deboli. Riteniamo che questo sia un gesto gravissimo, perch\u00e9 si specula sulla disperazione della gente in difficolt\u00e0. Il momento \u00e8 gi\u00e0 di per se assolutamente delicato, non abbiamo bisogno di aggravare la situazione con comportamenti da sciacalli. A tutti i cittadini dico di rivolgersi a patronati e Caf seri, gestiti da persone oneste e competenti&#8221;.<\/p>\n<h4><span style=\"color: #ff0000;\">ASCOLTA L&#8217;INTERVISTA<\/span><\/h4>\n<p><iframe loading=\"lazy\" src=\"https:\/\/w.soundcloud.com\/player\/?url=https%3A\/\/api.soundcloud.com\/tracks\/788998879&amp;color=%23ff5500&amp;auto_play=true&amp;hide_related=false&amp;show_comments=true&amp;show_user=true&amp;show_reposts=false&amp;show_teaser=true\" width=\"100%\" height=\"166\" frameborder=\"no\" scrolling=\"no\"><\/iframe><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-347491 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2020\/04\/Umberto-Calabrone-segretario-Cgil-Cosenza-440x264.jpg\" alt=\"\" width=\"440\" height=\"264\" title=\"\"><\/p>\n<p><strong>La pandemia ha acuito la grave situazione economica nella quale gi\u00e0 versava il sistema produttivo calabrese<\/strong>. A questo si aggiungono dei riardi burocratici che aggravano ulteriormente la situazione, le aziende calabresi , infatti, non posso ancora presentare le domande di cassa integrazione in deroga. \u201cMentre c\u2019\u00e8 un governo nazionale \u2013 ha aggiunto Calabrone \u2013 che prova a dare sollievo all\u2019economia, aiutando i cittadini, <strong>noi abbiamo una Regione che ha deciso che la presentazione delle domande avverr\u00e0 dal 6 aprile in poi<\/strong>. Tutto ci\u00f2 \u00e8 impensabile. Come sindacato, siamo al fianco della giunta regionale per porpore soluzioni che, alla fine della pandemia, possano rilanciare questa terra. Le segreterie regionali stanno gi\u00e0 interloquendo con gli assessorati, e quello che chiediamo \u00e8 di mettere in campo, appena l&#8217;emergenza sar\u00e0 passata,<strong> un piano per il lavoro reale,<\/strong> anche con la rimodulazione dei fondi europei non spesi. Dobbiamo essere pronti il giorno della ripartenza, perch\u00e9 al momento, purtroppo, non c&#8217;\u00e8 una categoria produttiva che si salva. Sicuramente il settore turistico e del commercio sono i comparti che maggiormente hanno risentito e risentiranno di questo periodo&#8221;.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lancia l&#8217;allarme il segretario della Cgil Cosenza, Umberto Calabrone, su Caf e patronati che chiedono soldi per inoltrare la domanda per il bonus da 600 a sostegno dei lavoratori e delle persone meno abbienti<\/p>\n","protected":false},"author":56,"featured_media":127312,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[42],"tags":[681],"class_list":["post-127311","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cosenza","tag-coronavirus"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/127311","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/56"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=127311"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/127311\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/127312"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=127311"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=127311"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=127311"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}