{"id":127401,"date":"2020-04-03T10:54:21","date_gmt":"2020-04-03T08:54:21","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/longobucco-allevatori-avvelenano-cani-randagi-denunciati-dai-carabinieri\/"},"modified":"2023-01-16T17:56:10","modified_gmt":"2023-01-16T16:56:10","slug":"347708-longobucco-allevatori-avvelenano-cani-randagi-denunciati-dai-carabinieri","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/347708-longobucco-allevatori-avvelenano-cani-randagi-denunciati-dai-carabinieri\/","title":{"rendered":"Longobucco: allevatori avvelenano cani randagi, denunciati dai carabinieri"},"content":{"rendered":"<h4>I due allevatori avrebbero compiuto il vile gesto perch\u00e9 nella zona interessata sono presenti alcuni allevamenti di ovini, per cui i cani randagi rappresenterebbero una potenziale minaccia<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>LONGOBUCCO (CS) &#8211; Due allevatori sono stati deferiti in stato di libert\u00e0, dai carabinieri, per il reato di uccisione di animali. Il <strong>fatto risale alla serata del 15 febbraio scorso<\/strong>, quando i due uomini avrebbero posizionato alcuni bocconi intrisi di veleno per cani, lungo una via del centro del paese. Gli uomini dell\u2019Arma sono stati contattati la mattina seguente da un cittadino, che segnalava la presenza di <strong>un cane privo di vita proprio nei pressi della zona ove erano stati posizionati i bocconi di cibo.<\/strong><\/p>\n<p>I carabinieri hanno riscontrato quanto segnalato, e notato che lungo la sede stradale erano ancora presenti vari bocconi di cibo, poi rivelatesi avvelenati grazie agli esami effettuati dal servizio veterinario dell\u2019A.S.P. di Cosenza. Le indagini sono state condotte con l\u2019attenta visione ed analisi degli impianti di videosorveglianza comunali, grazie ai quali \u00e8 stato possibile ricostruire i movimenti dei due uomini e giungere alla loro identificazione.<\/p>\n<p>Secondo una prima ricostruzione, <strong>i due allevatori sono giunti a tale vile gesto<\/strong> perch\u00e9 nella zona interessata sono presenti alcuni allevamenti di ovini, per cui i cani randagi rappresenterebbero una potenziale minaccia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>I due allevatori avrebbero compiuto il vile gesto perch\u00e9 nella zona interessata sono presenti alcuni allevamenti di ovini, per cui i cani randagi rappresenterebbero una potenziale minaccia<\/p>\n","protected":false},"author":56,"featured_media":127402,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[],"class_list":["post-127401","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/127401","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/56"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=127401"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/127401\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/127402"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=127401"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=127401"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=127401"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}