{"id":127476,"date":"2020-04-04T12:30:14","date_gmt":"2020-04-04T10:30:14","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/coronavirus-bimbo-lascia-striscione-davanti-la-caserma-di-bisignano\/"},"modified":"2023-01-16T17:56:14","modified_gmt":"2023-01-16T16:56:14","slug":"347894-coronavirus-bimbo-lascia-striscione-davanti-la-caserma-di-bisignano","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/347894-coronavirus-bimbo-lascia-striscione-davanti-la-caserma-di-bisignano\/","title":{"rendered":"Coronavirus, bimbo lascia striscione davanti la caserma di Bisignano"},"content":{"rendered":"<h4>Uno striscione con disegnato un arcobaleno, la bandiera d&#8217;Italia e una frase di incoraggiamento per i carabinieri<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>BISIGNANO (CS) &#8211; <strong>\u201cW i Carabinieri, W l\u2019Italia, andr\u00e0 tutto bene\u201d<\/strong>. E\u2019 questo il messaggio scritto su\u00a0 uno striscione che i carabinieri di Bisignano hanno trovato stamattina, davanti la porta della caserma. Sicuramente il dono di un bambino: un piccolo gesto, ma carico di un profondo significato, a dimostrazione della vicinanza della popolazione all\u2019Arma dei Carabinieri, sempre in prima linea <strong>al fianco dei cittadini,<\/strong> anche in questo periodo di emergenza.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uno striscione con disegnato un arcobaleno, la bandiera d&#8217;Italia e una frase di incoraggiamento per i carabinieri<\/p>\n","protected":false},"author":56,"featured_media":127477,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[681],"class_list":["post-127476","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia","tag-coronavirus"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/127476","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/56"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=127476"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/127476\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/127477"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=127476"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=127476"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=127476"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}