{"id":127656,"date":"2020-04-07T14:50:32","date_gmt":"2020-04-07T12:50:32","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/coronavirus-dalla-calabria-1600-uova-di-pasqua-per-bergamo\/"},"modified":"2023-01-16T17:56:26","modified_gmt":"2023-01-16T16:56:26","slug":"348374-coronavirus-dalla-calabria-1600-uova-di-pasqua-per-bergamo","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/348374-coronavirus-dalla-calabria-1600-uova-di-pasqua-per-bergamo\/","title":{"rendered":"Coronavirus, dalla Calabria 1600 uova di Pasqua per Bergamo"},"content":{"rendered":"<h4><strong>Le oltre 1600 uova sono un regalo della societ\u00e0 Dolciaria Alessandria, che nei giorni scorsi ha inviato una lettera al Sindaco di Bergamo Giorgio Gori<\/strong><!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>SORIANO CALABRO &#8211; Sono un regalo di una pasticceria di <strong>Soriano Calabro le 1600 uova di Pasqua<\/strong> che il Comune di Bergamo doner\u00e0 alle famiglie pi\u00f9 bisognose della citt\u00e0. Nelle prossime ore i volontari del Comune le distribuiranno tra le famiglie affidatarie dell&#8217;Ambito di Bergamo, le strutture di accoglienza per mamme, bambini e adolescenti, i progetti di housing sociale, al carcere, al Banco Alimentare (che gi\u00e0 consegna la spesa alle famiglie in difficolt\u00e0 della citt\u00e0) e ad altri ancora.<strong> Le oltre 1600 uova sono un regalo della societ\u00e0 Dolciaria Alessandria, che nei giorni scorsi ha inviato una lettera al Sindaco di Bergamo Giorgio Gori.<\/strong><\/p>\n<p>&#8220;Assieme ai miei fratelli &#8211; si legge nella lettera inviata da <strong>Francesco Alessandria<\/strong> &#8211; vorremmo in qualche modo far giungere loro <strong>il nostro sostegno e il nostro pensiero alleviando, seppur per pochi momenti, la tensione, l&#8217;angoscia e la tristezza<\/strong> che stanno vivendo anche le loro famiglie, i loro bambini, ai quali, e soprattutto, rivolgiamo questa iniziativa.&#8221;<\/p>\n<p>&#8220;Un grande grazie ai fratelli Alessandria &#8211; commenta il Sindaco <strong>Giorgio Gori<\/strong> &#8211; per questo gesto di <strong>grande sensibilit\u00e0<\/strong> nei confronti del nostro territorio. I gesti di solidariet\u00e0 nei confronti della nostra comunit\u00e0 si moltiplicano in queste ultime settimane, ma ognuno di questi rappresenta <strong>un&#8217;iniezione di energia e di fiducia<\/strong> nell&#8217;affrontare questo momento cos\u00ec complicato per la nostra citt\u00e0 e il nostro Paese.&#8221;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le oltre 1600 uova sono un regalo della societ\u00e0 Dolciaria Alessandria, che nei giorni scorsi ha inviato una lettera al Sindaco di Bergamo Giorgio Gori<\/p>\n","protected":false},"author":22,"featured_media":127657,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17,16],"tags":[],"class_list":["post-127656","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","category-italia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/127656","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=127656"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/127656\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/127657"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=127656"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=127656"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=127656"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}