{"id":127850,"date":"2020-04-10T11:05:21","date_gmt":"2020-04-10T09:05:21","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/covid-19-sindaco-stasi-denuncia-diffusione-di-dati-sensibili-gravissima-violazione\/"},"modified":"2023-01-16T17:56:40","modified_gmt":"2023-01-16T16:56:40","slug":"348867-covid-19-sindaco-stasi-denuncia-diffusione-di-dati-sensibili-gravissima-violazione","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/348867-covid-19-sindaco-stasi-denuncia-diffusione-di-dati-sensibili-gravissima-violazione\/","title":{"rendered":"Covid 19, sindaco Stasi denuncia &#8220;diffusione di dati sensibili, gravissima violazione&#8221;"},"content":{"rendered":"<h4>Il sindaco di Corigliano Rossano ha definito &#8216;gravissima e vergognosa&#8217; la vicenda sulla diffusione di presunti documenti che conterrebbero dati sensibili di persone sottoposte in regime di quarantena obbligatoria: &#8220;ho sporto formale denuncia&#8221;<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>CORIGLIANO ROSSANO (CS) &#8211; &#8220;La difesa della dignit\u00e0 della persone e dei cittadini, insieme all&#8217;immagine stessa della nostra comunit\u00e0 rappresentano principi, doveri e obiettivi di rango pari a quelli della necessit\u00e0 di prevenzione, di tutela della salute e della sicurezza pubblica. A nessuno di questi obblighi etici, prima ancora che giuridici, \u00e8 consentito sottrarsi per nessun motivo ed in nessuna circostanza, tanto pi\u00f9 in un momento delicato di grave emergenza sanitaria nazionale che impone a tutti, ciascuno nel proprio ruolo, un senso di responsabilit\u00e0 ancora maggiore&#8221;.<\/p>\n<p>\u00c8 quanto dichiara il sindaco di Corigliano Rossano, Flavio Stasi, informando di aver <strong>sporto formale denuncia<\/strong> <strong>contro ignoti<\/strong> rispetto alla <strong>diffusione illegittima ed illegale<\/strong> di presunti documenti che conterrebbero dati sensibili e comunque riservati relativi a persone eventualmente sottoposte in regime di quarantena obbligatoria nonch\u00e9 altri eventuali dati sanitari delle stesse.<\/p>\n<h3>&#8220;Tutto ci\u00f2 non \u00e8 affatto tollerabile&#8221;<\/h3>\n<p>&#8220;Siamo di fronte ad una <strong>gravissima e vergognosa violazione<\/strong> \u2013 aggiunge il sindaco \u2013 che <strong>calpesta i diritti delle persone e di tutta la citt\u00e0<\/strong>. Ho quindi chiesto alla Autorit\u00e0 Giudiziaria di non lesinare alcuno sforzo nell\u2019individuare con urgenza i responsabili di questa incivilt\u00e0 che \u2013 conclude Stasi \u2013 l\u2019Amministrazione Comunale condanna senza se e senza e sulla quale siamo certi si andr\u00e0 fino in fondo&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il sindaco di Corigliano Rossano ha definito &#8216;gravissima e vergognosa&#8217; la vicenda sulla diffusione di presunti documenti che conterrebbero dati sensibili di persone sottoposte in regime di quarantena obbligatoria: &#8220;ho sporto formale denuncia&#8221;<\/p>\n","protected":false},"author":42,"featured_media":127851,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[572,28],"tags":[681],"class_list":["post-127850","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ionio","category-provincia","tag-coronavirus"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/127850","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=127850"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/127850\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/127851"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=127850"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=127850"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=127850"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}