{"id":127922,"date":"2020-04-11T17:00:06","date_gmt":"2020-04-11T15:00:06","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/terra-di-piero-e-cri-acquistata-la-prima-camera-di-biocontenimento-in-calabria\/"},"modified":"2023-01-16T17:56:45","modified_gmt":"2023-01-16T16:56:45","slug":"349058-terra-di-piero-e-cri-acquistata-la-prima-camera-di-biocontenimento-in-calabria","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/349058-terra-di-piero-e-cri-acquistata-la-prima-camera-di-biocontenimento-in-calabria\/","title":{"rendered":"Terra di Piero e CRI, acquistata la prima camera di biocontenimento in Calabria"},"content":{"rendered":"<h4>Il Centro Commerciale Metropolis ha partecipato alla gara di solidariet\u00e0 che ha permesso l&#8217;acquisto anche di un ventilatore polmonare, un santificatore di ozono, u<strong>na barella autocaricante<\/strong> e dispositivi di protezione con una donazione da 50mila euro alla Croce Rossa Italiana e all&#8217;associazione Terra di Piero<!--more--><\/h4>\n<p><span style=\"color: #ffffff;\">.<\/span><\/p>\n<p>RENDE &#8211;\u00a0Acquistata la prima <strong>camera di trasporto (biocontenimento)<\/strong> in Calabria per i pazienti infetti, oltre a materiale sanitario e derrate alimentari per le famiglie bisognose.\u00a0 Il Centro Commerciale Metropolis di Rende (Cs) si schiera con il territorio, nell\u2019emergenza sanitaria e sociale causata dalla pandemia di Coronavirus, donando un totale di<strong> 50mila euro<\/strong> alla<strong> Croce Rossa Italiana <\/strong>e all\u2019associazione <strong>\u201cTerra di Piero\u201d<\/strong>, che opera localmente a sostegno di famiglie e persone disagiate.\u00a0La donazione, fortemente voluta dalla Propriet\u00e0 del Centro Commerciale \u2013 che fa capo agli investitori <strong>TPG RE<\/strong> e <strong>PARTNERS GROUP<\/strong> <strong>\u2013<\/strong> sar\u00e0 equamente divisa tra le due realt\u00e0, impegnate in prima fila nella gestione di una crisi senza precedenti, a livello locale e globale. In particolare, Croce Rossa Italiana si \u00e8 potuta dotare, grazie al contributo di Metropolis, di una <strong>camera di biocontenimento <\/strong>per il trasporto di pazienti infetti, di <strong>una barella autocaricante, <\/strong>di<strong> un ventilatore polmonare, di un sanificatore ad ozono <\/strong>e di una corposa <strong>scorta di dispositivi di protezione<\/strong>. L\u2019associazione \u201c<strong>La Terra di Piero<\/strong>\u201d, che fin dal principio dell\u2019emergenza ha attivato il carrello solidale e intensificato le raccolte, ha destinato la donazione all\u2019acquisto di <strong>derrate alimentari da distribuire alle famiglie bisognose <\/strong>e di alimenti utilizzati nella preparazione di<strong> cibi caldi serviti quotidianamente<\/strong>.<\/p>\n<p>Giuseppe Belmonte, Direttore del Centro Commerciale Metropolis, ha dichiarato: \u201c<em>La rete benefica delle donazioni a sostegno di chi ha bisogno<\/em>, \u00a0<em>in una crisi talmente grave ed estesa a livello mondiale, deve vederci in prima linea, pi\u00f9 che mai presenti al fianco delle istituzioni territoriali. Il nostro impegno vuole pertanto porsi a supporto e integrazione della preziosa azione del Comune di Rende e delle numerose associazioni, in aiuto agli operatori sanitari, che quotidianamente e strenuamente affrontano l\u2019emergenza, e alle fasce pi\u00f9 deboli della popolazione<\/em>\u201d.<\/p>\n<p><a href=\"https:\/\/quicosenza.it\/news\/10012\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-349060\" src=\"https:\/\/quicosenza.it\/news\/10012\" alt=\"\" width=\"609\" height=\"609\" title=\"\"><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Centro Commerciale Metropolis ha partecipato alla gara di solidariet\u00e0 che ha permesso l&#8217;acquisto anche di un ventilatore polmonare, un santificatore di ozono, una barella autocaricante e dispositivi di protezione con una donazione da 50mila euro alla Croce Rossa Italiana e all&#8217;associazione Terra di Piero<\/p>\n","protected":false},"author":55,"featured_media":127923,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[44],"tags":[],"class_list":["post-127922","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rende"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/127922","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=127922"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/127922\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/127923"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=127922"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=127922"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=127922"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}