{"id":128337,"date":"2020-04-20T08:55:35","date_gmt":"2020-04-20T06:55:35","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/castrolibero-aveva-50-piante-di-marijuana-in-casa-arrestato-47enne\/"},"modified":"2023-01-16T17:57:12","modified_gmt":"2023-01-16T16:57:12","slug":"350122-castrolibero-aveva-50-piante-di-marijuana-in-casa-arrestato-47enne","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/350122-castrolibero-aveva-50-piante-di-marijuana-in-casa-arrestato-47enne\/","title":{"rendered":"Castrolibero, aveva 50 piante di marijuana in casa. Arrestato 47enne"},"content":{"rendered":"<h4>Un uomo di 47 anni \u00e8 stato arrestato e posto ai domiciliari per coltivazione e detenzione di ai fini di spaccio di sostanze stupefacenti. I carabinieri scoprirono nella sua abitazione 50 piante di canapa e oltre un chilo di marijuana<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>CASTROLIBERO (CS) &#8211; I Carabinieri di Cosenza, nei giorni scorsi, hanno eseguito un\u2019ordinanza di custodia cautelare agli arresti domiciliari, emessa dal Gip del Tribunale di Cosenza su richiesta della Procura bruzia, nei confronti di un <strong>47enne ritenuto responsabile di coltivazione e detenzione ai fini di spaccio di sostanze stupefacenti e furto di energia elettrica.<\/strong><\/p>\n<p>I fatti risalgono allo scorso 27 gennaio, quando l&#8217;uomo era stato trovato in possesso di <strong>50 piante di canapa<\/strong> indiana, <strong>un chilo e 200 grammi di marijuana, 30 grammi di hashish<\/strong> nonch\u00e9 strumenti per la coltivazione.<\/p>\n<p>Per questo era stato denunciato alla Procura della Repubblica di Cosenza dai carabinieri. Il 47enne aveva sostenuto di coltivare cannabis sativa,<strong> sostenendo che le piante che stava coltivando rispettasse i limiti dei valori del THC determinati dalla legge<\/strong>, ma da mirati accertamenti, \u00e8 stato stabilito che quanto da lui affermato non fosse veritiero. La marijuana, all&#8217;esito dell\u2019esame dei laboratori, \u00e8 risultata con valore di THC di gran lunga superiore ai livelli consentiti. <strong>La serra allestita all\u2019interno del proprio appartamento,<\/strong> composta da un sofisticato impianto di irrigazione a tempo, con lampade di sodio ad alta pressione, ventilatore, prese elettriche con timer e bottiglie contenenti fertilizzanti, era alimentata tramite un allaccio abusivo alla rete elettrica che consentiva all\u2019indagato di impossessarsi di un quantitativo indeterminato di energia elettrica, sottraendolo impropriamente alla societ\u00e0 Enel distribuzione.<\/p>\n<p>In virt\u00f9 di quanto emerso in seguito ad approfonditi accertamenti, una volta espletate le formalit\u00e0 di rito, il <strong>47enne \u00e8 stato dunque posto agli arresti domiciliari<\/strong>, a disposizione dell\u2019Autorit\u00e0 Giudiziaria procedente.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un uomo di 47 anni \u00e8 stato arrestato e posto ai domiciliari per coltivazione e detenzione di ai fini di spaccio di sostanze stupefacenti. I carabinieri scoprirono nella sua abitazione 50 piante di canapa e oltre un chilo di marijuana<\/p>\n","protected":false},"author":42,"featured_media":128338,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[564,571],"tags":[],"class_list":["post-128337","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-castrolibero","category-in-evidenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/128337","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=128337"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/128337\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/128338"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=128337"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=128337"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=128337"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}