{"id":128351,"date":"2020-04-20T10:51:44","date_gmt":"2020-04-20T08:51:44","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/coronavirus-minasi-la-regione-lavora-per-far-rientrare-gli-emigrati\/"},"modified":"2023-01-16T17:57:13","modified_gmt":"2023-01-16T16:57:13","slug":"350145-coronavirus-minasi-la-regione-lavora-per-far-rientrare-gli-emigrati","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/350145-coronavirus-minasi-la-regione-lavora-per-far-rientrare-gli-emigrati\/","title":{"rendered":"Coronavirus, Minasi: &#8220;La Regione lavora per far rientrare gli emigrati&#8221;"},"content":{"rendered":"<h4>La consigliera regionale della Lega \u00e8 intervenuta sulla richiesta dei calabresi immigrati di poter far rientro in Calabria. &#8220;I<strong>l rientro &#8211; dice &#8211; dovr\u00e0 essere gestito nella massima sicurezza&#8221;<\/strong><\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>CATANZARO &#8211; &#8220;Non passano certo inosservati gli appelli di nostri numerosi corregionali che chiedono di poter rientrare in Calabria poich\u00e9, a causa di diversi motivi, si trovano a dover affrontare, in altre regioni, il periodo di quarantena imposto in tutta Italia senza poter avere, per\u00f2, i mezzi per sostentarsi in questa fase di stallo particolarmente gravosa soprattutto per lavoratori precari, stagionali, o in attesa di ammortizzatori sociali&#8221;. E&#8217; quanto dichiara<strong> Tilde Minasi, consigliere regionale della Lega<\/strong>.<br \/>\n&#8220;Un piano &#8211; prosegue &#8211; tra l\u2019altro, quello della gestione e del coordinamento dei cittadini calabresi domiciliati nelle regioni pi\u00f9 colpite dal Covid, che la Lega aveva gi\u00e0 approntato quasi un mese addietro e pensato proprio per evitare l&#8217;esodo indiscriminato da un lato, e non abbandonare i calabresi dall\u2019altro, gestendo in maniera ordinata i singoli casi. Il problema non \u00e8 assolutamente sottovalutato dagli uffici regionali e dalla politica, dal momento che il dibattito sulla questione \u00e8 vivo, cos\u00ec come il confronto, affinch\u00e9 si trovino soluzioni e si riesca a dare la giusta attenzione ai fuorisede. <strong>Il dramma dell\u2019emergenza sanitaria ha avuto un iter veloce<\/strong>, inaspettato e ha riguardato persone ed attivit\u00e0, motivo per il quale si sono dovute approntare azioni mirate a tutto tondo, in modo da non tralasciare le esigenze di ampissime fette di popolazione. La Regione sta lavorando, quindi &#8211; aggiunge &#8211; anche nei confronti di chi chiede, legittimamente, di poter rientrare in Calabria perch\u00e9 ormai allo stremo, in particolare dal punto di vista economico&#8221;.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-347873 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2020\/04\/tilde-minasi-440x249.jpg\" alt=\"\" width=\"440\" height=\"249\" title=\"\"><\/p>\n<p>La presidente Santelli, dice poi Minasi, &#8220;che ha gestito sino ad oggi con piglio deciso il contenimento del contagio da Covid, non \u00e8 insensibile alle richieste di aiuto che si sono fatte pi\u00f9 insistenti negli ultimi giorni, anche in considerazione del fatto che tanti di coloro che si stanno rivolgendo alle istituzioni regionali, hanno mantenuto saldo il principio di non allontanarsi dai luoghi dove si trovavano per non far viaggiare, insieme alle necessit\u00e0 espresse, il pericolo di una trasmissione verso i loro cari, come invece \u00e8 accaduto con le ormai note fughe dei primi weekend di marzo. Ma, anche a fronte di un comportamento irreprensibile e attento al bene comune, settimane senza lavoro o senza una remunerazione costante stanno minando ogni certezza. <strong>Ovviamente, il rientro &#8211; dice &#8211; dovr\u00e0 essere gestito nella massima sicurezza,<\/strong> con direttive precise, sia per i diretti interessati sia per le comunit\u00e0 che li accoglieranno, e sono sicura che la governatrice non si sottrarr\u00e0 (come ha fatto d\u2019altronde negli ultimi mesi lavorando su tutti i fronti di questa imponente emergenza sanitaria) nel rispondere, in modo esaustivo, ai bisogni di chi necessita aiuto a migliaia di chilometri da casa, favorendo i ricongiungimenti familiari che, in questo caso, non si configurano solo come una questione affettiva, bens\u00ec di sopravvivenza\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La consigliera regionale della Lega \u00e8 intervenuta sulla richiesta dei calabresi immigrati di poter far rientro in Calabria. &#8220;Il rientro &#8211; dice &#8211; dovr\u00e0 essere gestito nella massima sicurezza&#8221;<\/p>\n","protected":false},"author":56,"featured_media":128352,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[681],"class_list":["post-128351","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","tag-coronavirus"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/128351","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/56"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=128351"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/128351\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/128352"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=128351"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=128351"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=128351"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}