{"id":128413,"date":"2020-04-21T08:21:52","date_gmt":"2020-04-21T06:21:52","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/sorpresi-a-rubare-unauto-arrestati-due-ventenni\/"},"modified":"2023-01-16T17:57:17","modified_gmt":"2023-01-16T16:57:17","slug":"350292-sorpresi-a-rubare-unauto-arrestati-due-ventenni","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/350292-sorpresi-a-rubare-unauto-arrestati-due-ventenni\/","title":{"rendered":"Sorpresi a rubare un&#8217;auto, arrestati due ventenni"},"content":{"rendered":"<h4>I due giovani sono accusati di tentato furto. I carabinieri li hanno sorpresi uno a bordo di una Fiat Punto mentre spingeva la Smart Fortwo, con a bordo l&#8217;altro ragazzo, che era stata poco prima rubata in via Pio XI<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>REGGIO CALABRIA\u00a0 &#8211; Domenica pomeriggio, <strong>i carabinieri hanno arrestato Santino Passalacqua ventenne e Federico Bevilacqua 19enne<\/strong>, entrambi disoccupati e gravati da precedenti di polizia, quest\u2019ultimo anche sorvegliato speciale di P.S., responsabili del tentativo di furto di un\u2019autovettura.<br \/>\nI militari dell\u2019Arma, nel corso di un normale servizio di controllo del territorio, finalizzato anche alla prevenzione e repressione dei reati predatori, hanno notato in via Ciccarello una Fiat Punto che spingeva, con il paraurti anteriore, una Smart Fortwo a motore spento. Il controllo a distanza dei militari ha accertato, inoltre, che la Fiat Punto risultava sottoposta a fermo amministrativo mentre la Smart Fortwo, con a bordo l&#8217;altro ragazzo, era stata poco prima rubata in via Pio XI.<br \/>\nI due, prontamente bloccati,<strong> sono stati immediatamente arrestati e messi a disposizione dell\u2019autorit\u00e0 giudiziaria reggina<\/strong>. Federico Bevilacqua, contestualmente, \u00e8 stato deferito per la violazione colposa dei doveri inerenti alla custodia di cose sottoposte a sequestro nonch\u00e9 per la violazione degli obblighi della sorveglianza speciale.<br \/>\nLa situazione di attuale isolamento, avvertita soprattutto da chi rispetta le regole per se stesso e per il benessere del prossimo, non ferma i <strong>malintenzionati che tentano vigliaccamente di approfittarsene<\/strong> sentendosi i padroni della citt\u00e0.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>I due giovani sono accusati di tentato furto. I carabinieri li hanno sorpresi uno a bordo di una Fiat Punto mentre spingeva la Smart Fortwo, con a bordo l&#8217;altro ragazzo, che era stata poco prima rubata in via Pio XI<\/p>\n","protected":false},"author":56,"featured_media":128414,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-128413","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/128413","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/56"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=128413"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/128413\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/128414"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=128413"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=128413"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=128413"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}