{"id":128919,"date":"2020-04-29T14:19:41","date_gmt":"2020-04-29T12:19:41","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/coronavirus-due-nuovi-casi-nellarea-centrale-della-calabria\/"},"modified":"2023-01-16T17:57:51","modified_gmt":"2023-01-16T16:57:51","slug":"351556-coronavirus-due-nuovi-casi-nellarea-centrale-della-calabria","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/351556-coronavirus-due-nuovi-casi-nellarea-centrale-della-calabria\/","title":{"rendered":"Coronavirus, due nuovi casi nell&#8217;area centrale della Calabria"},"content":{"rendered":"<h4><strong>Uno \u00e8 stato segnalato a Catanzaro ed il secondo a Crotone. 333 sono stati i tamponi processati nelle ultime 24 ore<\/strong><!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>CATANZARO &#8211; Due nuovi casi di Covid-19 accertati tra ieri ed oggi nell\u2019area centrale della Calabria. <strong>Uno \u00e8 stato segnalato a Catanzaro ed il secondo a Crotone,<\/strong> territorio che da ben 17 giorni non aveva registrato contagi. E\u2019 quanto emerso dal bollettino diffuso dall\u2019Azienda Ospedaliera del Pugliese Ciaccio.<\/p>\n<p><strong>333 sono stati i tamponi<\/strong> processati nelle ultime 24 ore nei laboratori dell\u2019Azienda ospedaliera del nosocomio del capoluogo di regione, cos\u00ec distribuiti:<strong> 145 provenienti dalla provincia di Catanzaro, 35 dalla provincia di Crotone e 153 dalla provincia di Vibo Valentia.<\/strong> I tamponi complessivi Covid-19 sinora eseguiti sono stati <strong>9.733.<\/strong><\/p>\n<p>Negativi i <strong>70 tamponi processati al laboratorio del Policlinico Mater Domini.<\/strong> Nell\u2019ospedale Pugliese Ciaccio, intanto, restano <strong>14 i pazienti ricoverati<\/strong>, di cui uno solo nella terapia intensiva.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uno \u00e8 stato segnalato a Catanzaro ed il secondo a Crotone. 333 sono stati i tamponi processati nelle ultime 24 ore<\/p>\n","protected":false},"author":22,"featured_media":128920,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[681],"class_list":["post-128919","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","tag-coronavirus"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/128919","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=128919"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/128919\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/128920"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=128919"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=128919"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=128919"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}