{"id":129094,"date":"2020-05-02T12:20:19","date_gmt":"2020-05-02T10:20:19","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/coronavirus-anche-oggi-nessun-nuovo-contagio-nellarea-centrale-della-calabria\/"},"modified":"2023-01-16T17:58:03","modified_gmt":"2023-01-16T16:58:03","slug":"352011-coronavirus-anche-oggi-nessun-nuovo-contagio-nellarea-centrale-della-calabria","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/352011-coronavirus-anche-oggi-nessun-nuovo-contagio-nellarea-centrale-della-calabria\/","title":{"rendered":"Coronavirus, anche oggi nessun nuovo contagio nell&#8217;area centrale della Calabria"},"content":{"rendered":"<h4>Secondo giorno consecutivo senza nessun nuovo caso di coronavirus riscontrato tra le province di Catanzaro, Crotone e Vibo Valentia<!--more--><\/h4>\n<p><span style=\"color: #ffffff;\">.<\/span><\/p>\n<p>CATANZARO &#8211; Continua il dato positivo nell&#8217;area centrale della Calabria che anche oggi, per il secondo giorno consecutivo, registra <strong>zero nuovi contagi tra le province di Catanzaro, Crotone e Vibo Valentia<\/strong>. Lo comunica il bollettino quotidiano diffuso dall&#8217;azienda ospedaliera del Pugliese Ciaccio. Rispetto al dato di ieri sono stati<strong> analizzati 282 tamponi<\/strong>: 169 dalla provincia di Catanzaro, 31 da quella crotonese e 82 per quella di Vibo Valentia. Attualmente risultano <strong>ricoverate<\/strong> <strong>15 persone:<\/strong> 14 nel reparto di malattie infettive e 1 in terapia intensiva. Rispetto a venerd\u00ec <strong>non ci sono stati nuovi ricoveri<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Secondo giorno consecutivo senza nessun nuovo caso di coronavirus riscontrato tra le province di Catanzaro, Crotone e Vibo Valentia<\/p>\n","protected":false},"author":55,"featured_media":129095,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[681],"class_list":["post-129094","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","tag-coronavirus"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/129094","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=129094"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/129094\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/129095"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=129094"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=129094"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=129094"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}