{"id":129180,"date":"2020-05-04T12:00:38","date_gmt":"2020-05-04T10:00:38","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/fase-2-lappello-di-callipo-responsabilita-chi-torna-osservi-le-regole\/"},"modified":"2023-01-16T17:58:08","modified_gmt":"2023-01-16T16:58:08","slug":"352204-fase-2-lappello-di-callipo-responsabilita-chi-torna-osservi-le-regole","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/352204-fase-2-lappello-di-callipo-responsabilita-chi-torna-osservi-le-regole\/","title":{"rendered":"Fase 2, l\u2019appello di Callipo: \u00abresponsabilit\u00e0, chi torna osservi le regole\u00bb"},"content":{"rendered":"<h4>\u00abDa oggi si riparte, si apre la cosiddetta \u201cfase 2\u201d e dobbiamo per\u00f2 stare molto attenti. <strong>La politica ha il dovere di non seminare paure, creare caos o additare nemici\u00bb<\/strong><!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>CATANZARO &#8211; Sulla sua pagina Facebook <strong>Pippo Callipo<\/strong>, capogruppo di \u201cIo resto in Calabria\u201d in Consiglio regionale interviene sulla Fase 2: \u00abdopo un lungo periodo di rinunce e sacrifici, non vediamo l\u2019ora di tornare, sia pur gradualmente, alla routine quotidiana. La Calabria ha bisogno di ripartire, Il Governo e la Regione devono aiutare economicamente chi \u00e8 stato messo in ginocchio dalla crisi, ma \u00e8 vitale non vanificare gli sforzi fatti finora. Ne va della nostra salute\u00bb.<\/p>\n<p>\u00ab<strong>Da oggi anche molti calabresi, studenti, lavoratori, precari, potranno rientrare a casa.<\/strong> Bentornati, ragazzi. Sono sicuro \u2013 \u00e8 l\u2019appello di Callipo ai calabresi di ritorno dal Nord \u2013 che il vostro primo pensiero \u00e8 tutelare la salute dei vostri cari. Per farlo, come sapete, \u00e8 necessario che osserviate rigorosamente le regole e i protocolli predisposti per il vostro rientro. Se \u00e8 necessario so che andrete anche oltre ci\u00f2 che vi viene imposto per legge. Vi consiglio di farlo, nell\u2019interesse di tutti. Impedirvi di tornare, prendendo tutte le precauzioni del caso, sarebbe stata una grave ingiustizia. <strong>La politica ha il dovere di non seminare paure, creare caos o additare nemici.<\/strong> Deve, piuttosto, trovare le soluzioni affinch\u00e9 i nostri giovani non siano pi\u00f9 costretti a partire. Sappiate che la Calabria non dimentica i suoi figli. Per questa terra non sarete mai un problema ma sempre e solo una grande, inesauribile risorsa. Contiamo su di voi\u00bb.<\/p>\n<p>\u00abTutti da oggi \u2013 conclude Callipo \u2013 siamo chiamati a una grande prova di responsabilit\u00e0. La nostra terra ha bisogno dell\u2019amore e del rispetto di tutti noi per dimostrare anche al resto dell\u2019Italia che il nostro senso civico sta facendo la differenza in questa guerra contro un nemico subdolo e invisibile. Finora abbiamo dimostrato di potercela fare, <strong>non molliamo proprio adesso<\/strong>\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abDa oggi si riparte, si apre la cosiddetta \u201cfase 2\u201d e dobbiamo per\u00f2 stare molto attenti. La politica ha il dovere di non seminare paure, creare caos o additare nemici\u00bb<\/p>\n","protected":false},"author":42,"featured_media":129181,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-129180","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/129180","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=129180"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/129180\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/129181"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=129180"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=129180"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=129180"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}