{"id":129198,"date":"2020-05-04T13:06:02","date_gmt":"2020-05-04T11:06:02","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/controlli-sulla-a2-a-frascineto-e-sulla-106-a-roseto-un-centinaio-i-tamponi-effettuati\/"},"modified":"2023-01-16T17:58:10","modified_gmt":"2023-01-16T16:58:10","slug":"352254-controlli-sulla-a2-a-frascineto-e-sulla-106-a-roseto-un-centinaio-i-tamponi-effettuati","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/352254-controlli-sulla-a2-a-frascineto-e-sulla-106-a-roseto-un-centinaio-i-tamponi-effettuati\/","title":{"rendered":"Controlli sulla A2 a Frascineto e sulla 106 a Roseto. Un centinaio i tamponi effettuati"},"content":{"rendered":"<h4>Situazione sotto controllo e circa un centinaio i tamponi effettuati nei posti di controllo istituiti a Fransciento sulla A2 del Mediterraneo e a Roseto Capo Spulico sulla Statale 106. Controlli anche sulla Statale 18 nel territorio di Tortora<!--more--><\/h4>\n<p><span style=\"color: #ffffff;\">.<\/span><\/p>\n<p>COSENZA &#8211; <strong>Sono gi\u00e0 un centinaio di tamponi fatti nei posti di controllo allestiti sulla&#8217;autostrada A2 e sulla statale 106<\/strong> sui rientri dei calabresi bloccati in altre regioni dal lockdown e che da oggi possono fare rientro al proprio domicilio. Oltre ai controlli effettuati nelle stazioni ferroviarie (<span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/quicosenza.it\/news\/10154\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>qui la situazione a Paola<\/strong><\/a><\/span>), sotto controllo ci sono anche i due punti nevralgici della regione dal punto di vista delle strade. Situazione per ora assolutamente sotto controllo e poche le irregolarit\u00e0 riscontrate.<\/p>\n<p><a href=\"https:\/\/quicosenza.it\/news\/10155\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-352269\" src=\"https:\/\/quicosenza.it\/news\/10155\" alt=\"\" width=\"548\" height=\"308\" title=\"\"><\/a><\/p>\n<p>Le postazioni si trovano a<strong> Frascineto, nell&#8217;area di servizio &#8220;Frascineto Ovest&#8221; sulla A2 del Mediterraneo<\/strong>, dove sono attive sei squadre con medici e infermieri. La seconda \u00e8 a<strong> Roseto Capo Spulico sulla Statale 106 jonica, nei pressi del Castello<\/strong>, dove ci sono anche due pattuglie di carabinieri della compagnia di Corigliano e a due pattuglie della Guardia di finanza del Gruppo Sibar<strong>i. Controlli effettuati anche a Tortora lungo la statale 18 Tirrena inferiore<\/strong>.\u00a0Nelle prossime ore \u00e8 atteso un aumento del flusso di viaggiatori e di tamponi il cui esito verr\u00e0 comunicato nel giro di 24\/72 ore al diretto interessato e alle strutture preposte. Il tampone sar\u00e0 ripetuto nei prossimi giorni ed in caso di doppia negativit\u00e0 il soggetto interessato potr\u00e0 sospendere anzi tempo la quarantena.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Situazione sotto controllo e circa un centinaio i tamponi effettuati nei posti di controllo istituiti a Fransciento sulla A2 del Mediterraneo e a Roseto Capo Spulico sulla Statale 106. Controlli anche sulla Statale 18 nel territorio di Tortora<\/p>\n","protected":false},"author":55,"featured_media":129199,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[],"class_list":["post-129198","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/129198","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=129198"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/129198\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/129199"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=129198"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=129198"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=129198"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}