{"id":129206,"date":"2020-05-04T13:33:21","date_gmt":"2020-05-04T11:33:21","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/i-numeri-devastanti-della-pandemia-a-marzo-494-di-decessi-a-bergamo-568\/"},"modified":"2023-01-16T17:58:10","modified_gmt":"2023-01-16T16:58:10","slug":"352266-i-numeri-devastanti-della-pandemia-a-marzo-494-di-decessi-a-bergamo-568","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/352266-i-numeri-devastanti-della-pandemia-a-marzo-494-di-decessi-a-bergamo-568\/","title":{"rendered":"I numeri devastanti della pandemia. A marzo +49,4% di decessi, a Bergamo +568%"},"content":{"rendered":"<h4>Numeri impressionanti quelli legati ai decessi da coronavirus in Italia, in particolare in Lombardia e nella provincia di Bergamo che nel solo mese di marzo sono aumentati del 568%<!--more--><\/h4>\n<p><span style=\"color: #ffffff;\">.<\/span><\/p>\n<p>COSENZA &#8211; Nel mese di <strong>marzo 2020 si \u00e8 registrato un tasso di decessi pari al +568% a Bergamo,<\/strong> seguita da Cremona (391%), Lodi (371%), Brescia (291%), Piacenza (264%) e Parma (208%). Al contrario, nelle aree meno colpite dall&#8217;epidemia, soprattutto al Centro-Sud, <strong>i decessi del mese di marzo 2020 sono mediamente inferiori dell&#8217;1,8% alla media del quinquennio precedente <\/strong>e a Roma si \u00e8 registrato un dato pari al -9,4%. Emerge dal Rapporto Istat-Iss sull&#8217;impatto del Covid-19 sulla mortalit\u00e0. La grande maggioranza dei decessi si registra nelle province definite a diffusione alta (89%), laddove \u00e8 dell&#8217;8% nelle aree a diffusione media e del 3% in quelle a diffusione bassa. Il Rapporto evidenzia dunque l&#8217;esistenza di &#8220;tre Italie&#8221; rispetto all&#8217;epidemia da SarsCov2.<\/p>\n<p>Considerando il mese di marzo, si spiega nel Rapporto, si osserva a livello medio nazionale una crescita del 49,4% dei decessi per il complesso delle cause. Se si assume come riferimento il periodo che va dal primo decesso Covid-19 riportato al Sistema di Sorveglianza integrata (20 febbraio) fino al 31 marzo,<strong>i decessi passano da 65.592 (media periodo 2015-2019) a 90.946, nel 2020<\/strong>.\u00a0L&#8217;eccesso dei decessi \u00e8 di 25.354 unit\u00e0, di questi il 54% \u00e8 costituito dai morti diagnosticati Covid-19 (13.710).\u00a0La letalit\u00e0 per Covid-19 \u00e8 pi\u00f9 elevata in soggetti di sesso maschile in tutte le fasce di et\u00e0, ad eccezione della fascia 0-19 anni. Nel 34,7% dei casi segnalati viene riportata almeno una co-morbidit\u00e0 (una tra: patologie cardiovascolari, respiratorie, diabete, deficit immunitari, patologie metaboliche, oncologiche, obesit\u00e0, patologie renali).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Numeri impressionanti quelli legati ai decessi da coronavirus in Italia, in particolare in Lombardia e nella provincia di Bergamo che nel solo mese di marzo sono aumentati del 568%<\/p>\n","protected":false},"author":55,"featured_media":129207,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16],"tags":[681],"class_list":["post-129206","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-italia","tag-coronavirus"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/129206","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=129206"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/129206\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/129207"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=129206"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=129206"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=129206"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}