{"id":129810,"date":"2020-05-14T04:39:00","date_gmt":"2020-05-14T02:39:00","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/coronavirus-chiuso-lambulatorio-dopo-una-visita-ad-una-giovane-positiva\/"},"modified":"2023-01-16T17:58:51","modified_gmt":"2023-01-16T16:58:51","slug":"353851-coronavirus-chiuso-lambulatorio-dopo-una-visita-ad-una-giovane-positiva","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/353851-coronavirus-chiuso-lambulatorio-dopo-una-visita-ad-una-giovane-positiva\/","title":{"rendered":"Coronavirus, chiuso l&#8217;ambulatorio dopo una visita ad una giovane positiva"},"content":{"rendered":"<h4>E&#8217; stato subito disposto il tampone per i medici e gli infermieri che hanno avuto contatti con la ragazza<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>VIBO VALENTIA &#8211; E&#8217; accaduto a Vibo, nell&#8217;ambulatorio di otorino-laringoiatria dell&#8217;ospedale Jazzolino che \u00e8 stato sgomberato nel pomeriggio di ieri e poi sanificato dopo che nella struttura si era presentata una ragazza risultata positiva al coronavirus.<\/p>\n<p>La giovane si era sottoposta al test sierologico in una struttura privata della citt\u00e0. Quando ieri ha saputo il risultato di positivit\u00e0 ha subito avvertito le <strong>autorit\u00e0 sanitarie vibonesi<\/strong> che hanno immediatamente disposto lo <strong>sgombero<\/strong> e la <strong>sanificazione<\/strong> dell&#8217;ambulatorio dove la ragazza si era sottoposta ad accertamenti. I medici e gli infermieri venuti a contatto con la giovane sono stati messi in quarantena e sottoposti a tampone i cui esiti sono attesi nelle prossime ore.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>E&#8217; stato subito disposto il tampone per i medici e gli infermieri che hanno avuto contatti con la ragazza<\/p>\n","protected":false},"author":42,"featured_media":129811,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[681],"class_list":["post-129810","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","tag-coronavirus"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/129810","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=129810"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/129810\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/129811"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=129810"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=129810"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=129810"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}