{"id":129822,"date":"2020-05-14T09:27:24","date_gmt":"2020-05-14T07:27:24","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/bandiere-blu-2020-tra-le-new-entry-tropea-siderno-e-rocca-imperiale\/"},"modified":"2023-01-16T17:58:51","modified_gmt":"2023-01-16T16:58:51","slug":"353873-bandiere-blu-2020-tra-le-new-entry-tropea-siderno-e-rocca-imperiale","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/353873-bandiere-blu-2020-tra-le-new-entry-tropea-siderno-e-rocca-imperiale\/","title":{"rendered":"Bandiere Blu 2020, tra le new entry Tropea, Siderno e Rocca Imperiale"},"content":{"rendered":"<h4>Il riconoscimento per l&#8217;acqua pi\u00f9 pulita va a 195 comuni italiani e nell&#8217;edizione 2020 sono dodici in pi\u00f9 le Bandiere Blu assegnate. Sette le bandiere blu per la provincia di Cosenza <!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>ROMA &#8211; Sono aumentate per il 2020 in Italia le Bandiere Blu, i riconoscimenti ai comuni costieri e lacustri che hanno le acque pi\u00f9 pulite e che hanno maggior rispetto dell&#8217;ambiente. Sono 195 i Comuni italiani che le hanno ottenute nel 2020, 12 in pi\u00f9 rispetto ai 183 dell&#8217;anno scorso. <strong>I nuovi ingressi sono 12, e non c&#8217;\u00e8 nessuna uscita.<\/strong> Hanno ottenuto il riconoscimento anche 75 approdi turistici. Le <strong>Bandiere Blu<\/strong> sono attribuite ogni anno dalla Ong internazionale FEE (Foundation for Environmental Education, Fondazione per l&#8217;educazione ambientale), basandosi sui prelievi delle Arpa, le agenzie ambientali delle Regioni.<\/p>\n<h3>Le 12 new entry<\/h3>\n<p>I comuni sono Gozzano (Piemonte), Diano Marina (Liguria), Sestri Levante (Liguria), Montignoso (Toscana), Porto Tolle (Veneto), Vico Equense (Campania), Isole Tremiti (Puglia), Melendugno (Puglia), <strong>Rocca Imperiale<\/strong>, <strong>Tropea<\/strong> e <strong>Siderno<\/strong> (in Calabria), Al\u00ec Terme (Sicilia).<\/p>\n<p>Fra gli approdi arrivano quest&#8217;anno Cala Cravieu (Celle Ligure, Liguria), Vecchia Darsena Savona (Savona, Liguria), Cala Gavetta (La Maddalena, Sardegna), Marina Porto Azzurro (Porto Azzurro, Toscana), Porto degli Aragonesi (Casamicciola, Ischia, Campania). Perdono la Bandiera Blu nel 2020 il Porto turistico Marina di Policoro (Policoro, Basilicata) e la Marina del Nettuno (Messina, Sicilia).<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-292954 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/05\/bandiera-blu.jpg\" alt=\"trebisacce\" width=\"500\" height=\"343\" title=\"\"><\/p>\n<h4>In Calabria 14 bandiere blu<\/h4>\n<p>La <strong>Calabria va a quota 14 con tre nuovi ingressi. <\/strong>Nella provincia di\u00a0Catanzaro: Soverato, Sellia Marina. Per la provincia di <strong>Cosenza<\/strong> sono <strong>Rocca Imperiale, Roseto Capo Spulico, Trebisacce, San Nicola Arcella, Praia a Mare, Tortora, Villapiana<\/strong>. La provincia di Crotone: Cir\u00f2 Marina, Melissa. La provincia di Reggio Calabria oltre a Roccella Jonica vede Siderno mentre Tropea ha assegnato il riconoscimento per la provincia iVibo Valentia.<\/p>\n<h4>Le altre regioni<\/h4>\n<p>La <strong>Liguria<\/strong> con 32 localit\u00e0, e due nuovi ingressi, <strong>guida la classifica nazionale<\/strong>. Segue la Toscana con 20 localit\u00e0 (un nuovo ingresso). La Campania raggiunge le 19 Bandiere con un nuovo ingresso. Con 15 localit\u00e0 seguono le Marche. La Puglia conquista due nuove localit\u00e0 e raggiunge 15 Bandiere, mentre la Sardegna riconferma le sue 14 localit\u00e0. L&#8217;Abruzzo resta a 10. Il Lazio conferma le 9 bandiere, cos\u00ec come 9 sono quelle del Veneto, che segna un nuovo ingresso. L&#8217;Emilia Romagna conferma le sue 7 localit\u00e0, mentre la Sicilia ne guadagna una, passando a 8 Bandiere. La Basilicata conferma le sue 5 localit\u00e0, il Friuli Venezia Giulia conferma le 2 Bandiere dell&#8217;anno precedente. Il Molise rimane con 1 Bandiera. Quest&#8217;anno aumentano le Bandiere sui laghi, che premiano 18 localit\u00e0. Si registra un nuovo ingresso in Piemonte, che ottiene 4 bandiere. Rimangono invariati il Trentino Alto Adige, con 10 localit\u00e0, e la Lombardia, con 1. I 195 Comuni italiani premiati, per complessive 407 spiagge, corrispondono a circa il 10% delle spiagge premiate a livello mondiale.<\/p>\n<h4>&#8220;La Bandiera Blu strumento di ripresa e di rilancio dell&#8217;immagine del Paese&#8221;<\/h4>\n<p>Cos\u00ec il presidente della Fee Italia, <strong>Claudio Mazza<\/strong>, nella giornata di consegna del riconoscimento riferendosi all&#8217;estate in tempo di emergenza Covid: &#8220;Siamo certi che le localit\u00e0 Bandiera Blu dove il livello di qualit\u00e0 ambientale e del servizio al turista \u00e8 sempre stato al primo posto saranno in grado di garantire una gestione della stagione estiva efficiente e in sicurezza&#8221;, continua Mazza sottolineando che &#8220;insieme ai Comuni, gli stabilimenti balneari avranno un ruolo fondamentale in termini di presidio delle spiagge, saranno loro che avranno il compito di conciliare il rispetto delle regole e il piacere di una giornata al mare&#8221;.<\/p>\n<p>Secondo il presidente dell&#8217;Istituto superiore per la protezione ambientale (Ispra) e del Snpa, Stefano Laporta, &#8220;in un momento cos\u00ec delicato e particolare per il nostro Paese, questo riconoscimento acquista un valore aggiunto quale supporto al rilancio del turismo italiano e di tutta la nostra economia, perch\u00e9 la valorizzazione della risorsa &#8216;ambiente&#8217; rappresenta una delle chiavi di volta per ripensare il futuro del nostro Paese&#8221;.<\/p>\n<p>Una vigilia di <strong>stagione balneare &#8220;inconsueta<\/strong>&#8220;, sottolinea il comandante generale del Corpo delle Capitanerie di Porto-Guardia Costiera, ammiraglio Giovanni Pettorino, &#8220;che certamente ci vedr\u00e0 misurare con attenzione i nostri comportamenti. Sappiamo anche che la deantropizzazione delle coste e dei nostri mari ci sta consegnando una natura ancora pi\u00f9 bella. A voi, sindaci dei Comuni costieri, che ricevete oggi questo prestigioso riconoscimento &#8211; dice rivolgendosi ai premiati Bandiera Blu &#8211; il compito di assicurare con questa stagione la ripresa di un settore fondamentale per la nostra economia, un settore quello del turismo balneare e del turismo nautico che costituiscono dei valori economici di primo ordine per il nostro Paese&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il riconoscimento per l&#8217;acqua pi\u00f9 pulita va a 195 comuni italiani e nell&#8217;edizione 2020 sono dodici in pi\u00f9 le Bandiere Blu assegnate. Sette le bandiere blu per la provincia di Cosenza<\/p>\n","protected":false},"author":42,"featured_media":129823,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17,16],"tags":[],"class_list":["post-129822","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","category-italia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/129822","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=129822"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/129822\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/129823"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=129822"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=129822"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=129822"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}