{"id":130145,"date":"2020-05-20T04:35:03","date_gmt":"2020-05-20T02:35:03","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/piazza-pulita-maxi-blitz-antidroga-39-misure-cautelari-anche-in-calabria\/"},"modified":"2023-01-16T17:59:13","modified_gmt":"2023-01-16T16:59:13","slug":"354700-piazza-pulita-maxi-blitz-antidroga-39-misure-cautelari-anche-in-calabria","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/354700-piazza-pulita-maxi-blitz-antidroga-39-misure-cautelari-anche-in-calabria\/","title":{"rendered":"&#8220;Piazza Pulita&#8221;: maxi blitz antidroga, 39 misure cautelari anche in Calabria"},"content":{"rendered":"<h4>L&#8217;operazione coordinata dalla Direzione Distrettuale Antimafia di Campobasso viene eseguita dai carabinieri e dalla guardia di Finanza tra Molise, Campania, Puglia e Calabria <!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>CAMPOBASSO &#8211; L&#8217;operazione ribattezzata &#8220;Piazza Pulita&#8221; \u00e8 scattata nella notte. Carabinieri e Guardia di Finanza di Campobasso stanno eseguendo <strong>39 misure cautelari<\/strong> tra Molise, Campania, Puglia e <strong>Calabria<\/strong> su richiesta della DDA di Campobasso e il sequestro di beni per oltre un milione di euro.<\/p>\n<p>Colpite tre organizzazioni criminali che erano riuscite a costituire un solido e redditizio commercio di sostanze stupefacenti tra <strong>Campania e Molise<\/strong>. A capo di un sodalizio un pregiudicato napoletano vertice di un&#8217;associazione di stampo camorristico campana che reimpiegava i proventi illeciti della droga in attivit\u00e0 commerciali in provincia di Campobasso. L&#8217;operazione ha visto impegnati oltre <strong>250 carabinieri e finanzieri in 61 perquisizioni locali e personali.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;operazione coordinata dalla Direzione Distrettuale Antimafia di Campobasso viene eseguita dai carabinieri e dalla guardia di Finanza tra Molise, Campania, Puglia e Calabria<\/p>\n","protected":false},"author":42,"featured_media":130146,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17,16],"tags":[],"class_list":["post-130145","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","category-italia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/130145","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=130145"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/130145\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/130146"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=130145"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=130145"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=130145"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}