{"id":130169,"date":"2020-05-20T13:00:36","date_gmt":"2020-05-20T11:00:36","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/movida-selvaggia-conte-non-e-il-momento-dei-party-zaia-richiuso-con-il-silicone\/"},"modified":"2023-01-16T17:59:15","modified_gmt":"2023-01-16T16:59:15","slug":"354749-movida-selvaggia-conte-non-e-il-momento-dei-party-zaia-richiuso-con-il-silicone","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/354749-movida-selvaggia-conte-non-e-il-momento-dei-party-zaia-richiuso-con-il-silicone\/","title":{"rendered":"Movida selvaggia, Conte &#8220;non \u00e8 il momento dei party&#8221;. Zaia &#8220;chiudo tutto col silicone&#8221;"},"content":{"rendered":"<h4>Preoccupano gli assembramenti dei giovani nelle piazze italiane tra feste, movida e aperitivi selvaggi senza nessuna misura di sicurezza. Il monito del presidente Conte &#8220;non \u00e8 il momento delle feste o la curva del contagio risalir\u00e0&#8221;. La proposta del presidente dell&#8217;Anci De Caro &#8220;<strong>insieme al cocktail servite loro una mascherina&#8221;<\/strong><!--more--><\/h4>\n<p><span style=\"color: #ffffff;\">.<\/span><\/p>\n<p>COSENZA &#8211;\u00a0Dalla riapertura generalizzata dei negozi, quello che preoccupa maggiormente sindaci e governatori sono <strong>gli assembramenti selvaggi soprattutto di giovani, spesso senza mascherine, nelle zone pi\u00f9 calde della movida cittadina<\/strong>. Dalle Alpi alla Sicilia, hanno fatto il giro del Web ma anche di tutte le televisioni, le immagini che ritraggono <strong>centinaia e centinaia di ragazzi festeggiare con spitz, prosecco e aperitivo senza nessuna misura di sicurezza <\/strong>e con il distanziamento sociale annegato probabilmente insieme ai fumi dell&#8217;alcol. &#8220;Troppi video dalle nostre citt\u00e0 con movida e tutti senza mascherina &#8211; ha tuonato il governatore del Veneto Zaia. Se riparte il contagio siamo pronti a chiudere. In 10 giorni io li vedo i contagi: <strong>se aumentano richiuderemo bar, ristoranti, le spiagge, e torneremo a chiuderci in casa col silicone<\/strong>&#8220;. Zaia ha anche annunciato <strong>uno spot con le regole da seguire agli &#8216;happy hour&#8217;<\/strong>, ma anche per far capire quali potrebbero essere le conseguenze se non si portano le mascherine e se non si evitano gli assembramenti.\u00a0Di questo avviso anche il s<strong>indaco di Palermo Leoluca Orlando<\/strong> &#8220;non vorrei essere costretto a chiudere aree della citt\u00e0. Bisogna finirla con le passeggiate inutili, tutti nello stesso posto&#8221;.\u00a0Chi invece ha preso da subito decisioni immediate e drastiche \u00e8 il <strong>sindaco di Caserta Carlo Marino<\/strong> che ha con un&#8217;apposita ordinanza ha importo il divieto, dalle ore 23 in poi, di vendita al banco e l\u2019asporto di bevande alcoliche o analcoliche a tutti gli esercizi commerciali. Ordinanza in vigore da gioved\u00ec 21 maggio fino al 2 giugno.<\/p>\n<p><a href=\"https:\/\/quicosenza.it\/news\/10287\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-354755\" src=\"https:\/\/quicosenza.it\/news\/10287\" alt=\"\" width=\"522\" height=\"334\" title=\"\"><\/a><\/p>\n<p>&nbsp;<\/p>\n<h4>Conte &#8220;non \u00e8 il momento delle feste&#8221;<\/h4>\n<p>Sulla movida senza regole \u00e8 arrivato anche il monito del premier Giuseppe Conte &#8220;grazie a voi italiani, ma non \u00e8 finita, chiariamolo, <strong>non e&#8217; il tempo dei party e della movida, altrimenti la curva risale<\/strong>&#8221; ha detto Giuseppe Conte rispondendo ad un&#8217;anziana che lo ringraziava &#8220;a nome dell&#8217;Italia&#8221; per l&#8217;impegno di questi mesi. &#8220;<strong>Abbiamo tolto l&#8217;autocertificazione perch\u00e8 la curva era sotto controllo ma nessuno pensi che sono saltate le regole di precauzione<\/strong>&#8220;.<\/p>\n<h4>La proposta di Decaro &#8220;mascherine con i cocktail&#8221;<\/h4>\n<p>&#8220;Il nuovo decreto ha dato una sensazione di un liberi tutti. Ma da ora ciascuno di noi, a cominciare dai ragazzi, deve interpretare questa libert\u00e0 con senso di responsabilit\u00e0, applicando le regole sul distanziamento sociale e pensando al fatto che <strong>comportamenti irresponsabili mettono a rischio non solo la nostra salute individuale ma anche quella delle persone pi\u00f9 fragili che abbiamo care. <\/strong>Sicurezza oppure <strong>saremo costretti a chiudere di nuovo i locali, con il danno anche economico che questo comporterebbe<\/strong>&#8220;. Un monito ma anche un&#8217;eventualit\u00e0 da scongiurare con ogni mezzo ha sottolineato il presidente dell&#8217;ANCI e sindaco di Bari Antonio Decaro che chiama alla responsabilit\u00e0 anche gli operatori dei locali avanzando loro una proposta &#8220;<strong>mettete a disposizione dei clienti, insieme al cocktail che servite loro, una mascherina<\/strong>. E&#8217; illusorio pensare che possa essere esercitato un controllo da parte delle forze dell&#8217;ordine per ogni cittadino. Siamo in una nuova fase, c&#8217;\u00e8 una maggiore libert\u00e0 di movimento. <strong>La mascherina e il distanziamento sono le uniche difese dal contagio che ci permetteranno di evitare un nuovo pi\u00f9 doloroso e pericoloso lockdown<\/strong>&#8220;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Preoccupano gli assembramenti dei giovani nelle piazze italiane tra feste, movida e aperitivi selvaggi senza nessuna misura di sicurezza. Il monito del presidente Conte &#8220;non \u00e8 il momento delle feste o la curva del contagio risalir\u00e0&#8221;. La proposta del presidente dell&#8217;Anci De Caro &#8220;insieme al cocktail servite loro una mascherina&#8221;<\/p>\n","protected":false},"author":55,"featured_media":130170,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16],"tags":[],"class_list":["post-130169","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-italia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/130169","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=130169"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/130169\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/130170"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=130169"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=130169"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=130169"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}