{"id":130308,"date":"2020-05-22T10:20:50","date_gmt":"2020-05-22T08:20:50","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/ferrara-m5s-a-rischio-collegamento-ferroviario-tra-laeroporto-e-la-stazione\/"},"modified":"2023-01-16T17:59:23","modified_gmt":"2023-01-16T16:59:23","slug":"355110-ferrara-m5s-a-rischio-collegamento-ferroviario-tra-laeroporto-e-la-stazione","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/355110-ferrara-m5s-a-rischio-collegamento-ferroviario-tra-laeroporto-e-la-stazione\/","title":{"rendered":"Ferrara (M5S), &#8220;a rischio collegamento ferroviario tra l&#8217;aeroporto e la stazione&#8221;"},"content":{"rendered":"<h4>L&#8217;eurodeputata Laura Ferrara chiarisce il contenuto della risposta ad una sua interrogazione alla Commissione europea e che aveva come oggetto <strong>i finanziamenti destinati al progetto che collega l&#8217;aeroporto di Lamezia Terme a Catanzaro Lido<\/strong><!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p class=\"v1MsoNormal\">LAMEZIA TERME &#8211; \u00abLa realizzazione del collegamento ferroviario &#8220;di ultimo miglio&#8221; tra l&#8217;aeroporto e la stazione ferroviaria di Lamezia Terme \u00e8 a rischio\u00bb. L&#8217;eurodeputata Laura Ferrara chiarisce il contenuto della risposta ad una sua interrogazione alla Commissione europea e che aveva come oggetto, fra l&#8217;altro, <strong>i finanziamenti destinati al progetto che collega l&#8217;aeroporto di Lamezia Terme a Catanzaro Lido.<\/strong> Nel testo della risposta \u00e8 contenuta, inoltre, un&#8217;ulteriore e definitiva conferma dell&#8217;esclusione dal Por 7-13 del progetto della nuova aerostazione.<\/p>\n<p class=\"v1MsoNormal\">\u00abL&#8217;aeroporto internazionale di Lamezia Terme \u2013 afferma la Ferrara -, negli anni ha attirato a s\u00e9 numerosi progetti come quello della &#8220;Nuova aerostazione&#8221;: <strong>un investimento di circa 51 milioni di euro che avrebbe dovuto beneficiare<\/strong> di un finanziamento comunitario di circa 17 milioni. Un progetto strategico, non solo per la citt\u00e0 di Lamezia ma per l&#8217;intera regione, rimasto su carta e definitivamente cancellato dai finanziamenti del Por 7-13. Cancellazione di cui, gran parte della cittadinanza, non ha avuto mai notizia perch\u00e9 in Calabria si sa, la politica annuncia in pompa magna opere faraoniche, organizza convegni e conferenze ma poi si dimentica &#8211; o si vergogna &#8211; di raccontare ai cittadini la verit\u00e0: non siamo stati capaci di realizzarle quelle opere\u00bb.<\/p>\n<p class=\"v1MsoNormal\">\u00ab<strong>Nella Programmazione 14-20 non sono previsti finanziamenti per l&#8217;aeroporto di Lamezia Terme<\/strong>, il Fesr, infatti, sostiene investimenti in infrastrutture aeroportuali soltanto se connessi alla protezione dell&#8217;ambiente o accompagnati da investimenti necessari a mitigare o ridurre il loro impatto ambientale negativo. Ma la Regione aveva comunque previsto un intervento strategico per una migliore funzionalit\u00e0 del principale scalo aeroportuale calabrese. Fra i &#8220;grandi progetti&#8221; da avviare e concludere attraverso l&#8217;asse 7 del Por Calabria 2014-2020 vi \u00e8 il collegamento multimodale &#8220;Aeroporto \u2013 Stazione di Lamezia Terme Centrale \u2013 Germaneto \u2013 Catanzaro Lido&#8221; nel quale \u00e8 contemplato il collegamento ferroviario &#8220;di ultimo miglio&#8221; tra l&#8217;aeroporto e la stazione ferroviaria di Lamezia Terme. Tale progetto sta risentendo di notevoli ritardi, che mettono a rischio la sua attuazione nell&#8217;ambito del programma regionale 2014-2020\u00bb.<\/p>\n<p class=\"v1MsoNormal\">\u00abLa realizzazione dei Grandi Progetti, se conformi alle reali esigenze della Calabria &#8211; e un migliore collegamento dell&#8217;aeroporto di Lamezia lo \u00e8 \u2013 devono essere portati a compimento in tempi certi e senza spreco di denaro pubblico. <strong>Questo \u00e8 l&#8217;obiettivo che perseguo con il lavoro di monitoraggio sui fondi europei,<\/strong> in particolare quelli spesi in Calabria\u00bb conclude l&#8217;europarlamentare.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;eurodeputata Laura Ferrara chiarisce il contenuto della risposta ad una sua interrogazione alla Commissione europea e che aveva come oggetto i finanziamenti destinati al progetto che collega l&#8217;aeroporto di Lamezia Terme a Catanzaro Lido<\/p>\n","protected":false},"author":56,"featured_media":130309,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-130308","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/130308","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/56"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=130308"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/130308\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/130309"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=130308"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=130308"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=130308"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}