{"id":130382,"date":"2020-05-23T11:29:07","date_gmt":"2020-05-23T09:29:07","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/cocaina-e-marijuana-in-casa-tre-arresti-per-spaccio-a-corigliano-rossano\/"},"modified":"2023-01-16T17:59:28","modified_gmt":"2023-01-16T16:59:28","slug":"355290-cocaina-e-marijuana-in-casa-tre-arresti-per-spaccio-a-corigliano-rossano","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/355290-cocaina-e-marijuana-in-casa-tre-arresti-per-spaccio-a-corigliano-rossano\/","title":{"rendered":"Cocaina e marijuana in casa, tre arresti per spaccio. Due erano gi\u00e0 ai domiciliari"},"content":{"rendered":"<h4>Oltre alle tre persone finite in manette \u00e8 stata sequestrata anche la droga, in particolare 150 grammi tra cocaina e marijuana<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>CORIGLIANO ROSSANO (CS) &#8211; La Polizia ha arrestato ieri tre soggetti, in tre distinti episodi, nell&#8217;ambito di una serie di controlli straordinari del territorio volti a reprimere il fenomeno dello spaccio di stupefacenti nei luoghi ad alta frequentazione giovanile. Varie sono state le perquisizioni locali e personali, con l\u2019ausilio di Unit\u00e0 Cinofile della Polizia di Stato prima nell\u2019area urbana di Corigliano e successivamente in quella di Rossano.<\/p>\n<p>Nel primo episodio i poliziotti hanno arrestato G.A. di 25 anni. All\u2019interno della sua abitazione sono state rinvenute e sequestrate, 130 dosi gi\u00e0 preconfezionate e due bustine tutte contenenti <strong>cocaina <\/strong>per un totale di quasi <strong>50 grammi<\/strong>, inoltre venivano rinvenuti sostanza da taglio, 4 bilancini di precisione e ulteriori <strong>50 grammi circa di hashish<\/strong>.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-355292 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2020\/05\/cocaina-marijuana-polizia-corigliano-rossano-02.jpg\" alt=\"\" width=\"602\" height=\"888\" title=\"\"><\/p>\n<p>Il secondo soggetto arrestato \u00e8 un <strong>36enne, R.M.<\/strong> che si trovava gi\u00e0 agli arresti domiciliari per un altro reatoil quale, a seguito di una perquisizione domiciliare \u00e8 stato trovato in possesso di <strong>circa 10 dosi di cocaina<\/strong> sempre preconfezionate e pronte per essere cedute. Inoltre \u00e8 stato trovato materiale utile al confezionamento della droga.<\/p>\n<p>Infine il terzo arrestato \u00e8 A.D. di 27 anni, anche lui agli arresti domiciliari per un altro reato che, a seguito di un controllo domiciliare, era in possesso di <strong>2 grammi di cocaina e circa 25 grammi di marijuana<\/strong>, gi\u00e0 accuratamente suddivise in dosi e contenute in un borsello. Il giovane avrebbe tentato di disfarsene gettando il borsello dalla finestra dell\u2019appartamento, ma i poliziotti lo hanno recuperato.<\/p>\n<p>Tutti e tre sono tradotti presso la casa Circondariale di Castrovillari per come disposto dal P.M. di turno della Procura della Repubblica di Castrovillari.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Oltre alle tre persone finite in manette \u00e8 stata sequestrata anche la droga, in particolare 150 grammi tra cocaina e marijuana<\/p>\n","protected":false},"author":42,"featured_media":130383,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[572,28],"tags":[],"class_list":["post-130382","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ionio","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/130382","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=130382"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/130382\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/130383"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=130382"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=130382"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=130382"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}