{"id":130388,"date":"2020-05-23T15:33:40","date_gmt":"2020-05-23T13:33:40","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/coronavirus-da-ieri-zero-nuovi-contagi-in-calabria-e-i-positivi-scendono-sotto-i-300\/"},"modified":"2023-01-16T17:59:28","modified_gmt":"2023-01-16T16:59:28","slug":"355303-coronavirus-da-ieri-zero-nuovi-contagi-in-calabria-e-i-positivi-scendono-sotto-i-300","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/355303-coronavirus-da-ieri-zero-nuovi-contagi-in-calabria-e-i-positivi-scendono-sotto-i-300\/","title":{"rendered":"Coronavirus, da ieri zero nuovi contagi in Calabria. E i positivi scendono sotto i 300"},"content":{"rendered":"<h4>Nessun nuovo contagio in Calabria nelle ultime 24 ore a fronte di 1.045 tamponi analizzati. Gli attualmente positivi scendono sotto i 300 mentre i guariti salgono a 773<br \/>\n<!--more--><\/h4>\n<p><span style=\"color: #ffffff;\">.<\/span><br \/>\nCOSENZA &#8211; Nessun nuovo caso registrato nelle ultime 24 ore\u00a0 in Calabria che registra in totale <strong><strong>1.157 i contagi totali in Calabria <\/strong>comprese le vittime e i guariti. <\/strong>Il bollettino quotidiano del dipartimento salute della Regione con i dati sul contagio, ci dice che ad oggi sono stati <strong><strong>effettuati in totale 59.633 tamponi, 1.045 in pi\u00f9 rispetto a ieri<\/strong>. <\/strong>Nel numero dei tamponi complessivi, 5.114 sono quelli effettuati alle persone rientrate presso la propria residenza.<\/p>\n<p><a href=\"https:\/\/quicosenza.it\/news\/10333\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-355321\" src=\"https:\/\/quicosenza.it\/news\/10333\" alt=\"\" width=\"776\" height=\"456\" title=\"\"><\/a><\/p>\n<p><strong>Terzo giorno consecutivo senza nuove vittime <\/strong>con il numero totale dei decessi che \u00e8 di 96 persone<strong>.<\/strong> La diminuzione costante degli attualmente positivi porta il dato complessivo sotto quota 300. <strong>In Calabria ad oggi sono infatti 288 le persone ancora malate <\/strong>con un decremento rispetto a ieri di 14 persone. <strong>I<\/strong>\u00a0<strong>guariti nelle ultime 24 ore sono saliti complessivamente a 773 <\/strong>con un incremento rispetto a gioved\u00ec di 15 nuove persone che hanno sconfitto la malattia. Torna a scendere il numero dei pazienti ricoverati negli ospedali calabresi. <strong>Nei reparti si trovano attualmente 44 persone, con un decremento di 4 pazienti rispetto a ieri. <\/strong>Di questi <strong>1 si trovano in terapia intensiva<\/strong> (-1 da ieri) a Catanzaro. Infine le<strong> persone positive al Covid-19 che si trovano in isolamento domiciliare con sintomi lievi o asintomatiche sono scese a 244<\/strong> con un decremento da ieri di 10 persone.<\/p>\n<p><strong>I soggetti in quarantena volontaria sono 10.010<\/strong> cos\u00ec distribuiti: a Cosenza 1.866, a Crotone: 2.751, a Catanzaro 2.690, a Vibo Valentia 475 e a Reggio Calabria 2.278. Infine, rispetto a ieri le persone che si sono registrate sul portale della Regione Calabria per comunicare il rientro alla residenza sono 175 in pi\u00f9 mentre quelle che hanno comunicato il loro arrivo per motivi di lavoro, salute e attivit\u00e0 istituzionali sono 135, per un totale di <strong>310 nuove registrazioni<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n<h4><span style=\"color: #ff0000;\">Territorialmente, i casi positivi sono cos\u00ec distribuiti:<\/span><\/h4>\n<p><strong>Catanzaro<br \/>\n<\/strong>32 in reparto; 1 in rianimazione; 19 in isolamento domiciliare; 132 guariti; 33 deceduti<\/p>\n<p><strong>Cosenza<br \/>\n<\/strong>4 in reparto; 161 in isolamento domiciliare; 269 guariti; 34 deceduti<strong><br \/>\n<\/strong><\/p>\n<p><strong>Reggio Calabria<br \/>\n<\/strong>6 in reparto; 44 in isolamento domiciliare; 210 guariti; 18 deceduti<strong><br \/>\n<\/strong><\/p>\n<p><strong>Crotone<br \/>\n<\/strong>2 in reparto; 9 in isolamento domiciliare; 100 guariti; 6 deceduti<\/p>\n<p><strong>Vibo Valentia<br \/>\n<\/strong>14 in isolamento domiciliare; 62 guariti; 5 deceduti<strong><br \/>\n<\/strong><\/p>\n<h4><\/h4>\n<h4><span style=\"color: #0000ff;\">I numeri dei contagi in Calabria (dati Regione)<\/span><\/h4>\n<p><strong>Venerd\u00ec 1 maggio (+4)<br \/>\n<\/strong>1.112 contagiati in Calabria (108 ricoverati \u2013 619 isolamento \u2013 86 vittime \u2013 299 guariti)<\/p>\n<p><strong>Sabato 2 maggio (+0)<\/strong><br \/>\n1.112 contagiati in Calabria (104 ricoverati \u2013 609 isolamento \u2013 88 vittime \u2013 311 guariti)<\/p>\n<p><strong>Domenica 3 maggio (+2)<\/strong><br \/>\n1.114 contagiati in Calabria (99 ricoverati \u2013 603 isolamento \u2013 88 vittime \u2013 324 guariti)<\/p>\n<p><strong>Luned\u00ec 4 maggio (+4)<br \/>\n<\/strong>1.118 contagiati in Calabria (97 ricoverati \u2013 577 isolamento \u2013 88 vittime \u2013 356 guariti)<\/p>\n<p><strong>Marted\u00ec 5 maggio (+1)<br \/>\n<\/strong>1.119 contagiati in Calabria (96 ricoverati \u2013 554 isolamento \u2013 88 vittime \u2013 381 guariti)<\/p>\n<p><strong>Mercoled\u00ec 6 maggio (+3)<\/strong><br \/>\n1.122 contagiati in Calabria (90 ricoverati \u2013 554 isolamento \u2013 89 vittime \u2013 389 guariti)<\/p>\n<p><strong>Gioved\u00ec 7 maggio(+3)<\/strong><br \/>\n1.125 contagiati in Calabria (83 ricoverati \u2013 550 isolamento \u2013 89 vittime \u2013 403 guariti)<\/p>\n<p><strong>Venerd\u00ec 8 maggio (+1)<\/strong><br \/>\n1.126 contagiati in Calabria (75 ricoverati \u2013 544 isolamento \u2013 90 vittime \u2013 417 guariti)<\/p>\n<p><strong>Sabato 9 maggio (+3)<br \/>\n<\/strong>1.129 contagiati in Calabria (70 ricoverati \u2013 541 isolamento \u2013 90 vittime \u2013 427 guariti)<\/p>\n<p><strong>Domenica 10 maggio (+3)<br \/>\n<\/strong>1.132 contagiati in Calabria (68 ricoverati \u2013 528 isolamento \u2013 91 vittime \u2013 445 guariti)<\/p>\n<p><strong>Luned\u00ec 11 maggio (+2)<br \/>\n<\/strong>1.134 contagiati in Calabria (65 ricoverati \u2013 503 isolamento \u2013 93 vittime \u2013 473 guariti)<\/p>\n<p><strong>Marted\u00ec 12 maggio (+4)<br \/>\n<\/strong>1.138 contagiati in Calabria (66 ricoverati \u2013 502 isolamento \u2013 93 vittime \u2013 477 guariti)<\/p>\n<p><strong>Mercoled\u00ec 13 maggio (+2)<br \/>\n<\/strong>1.140 contagiati in Calabria (65 ricoverati \u2013 486 isolamento \u2013 93 vittime \u2013 496 guariti)<\/p>\n<p><strong>Gioved\u00ec 14 maggio (+3)<br \/>\n<\/strong>1.143 contagiati in Calabria (61 ricoverati \u2013 463 isolamento \u2013 95 vittime \u2013 524 guariti)<\/p>\n<p><strong>Venerd\u00ec 15 maggio (+1)<br \/>\n<\/strong>1.144 contagiati in Calabria (58 ricoverati \u2013 447 isolamento \u2013 95 vittime \u2013 544 guariti)<\/p>\n<p><strong>Sabato 16 maggio (+7)<br \/>\n<\/strong>1.151 contagiati in Calabria (58 ricoverati \u2013 416 isolamento \u2013 95 vittime \u2013 582 guariti<\/p>\n<p><strong>Domenica 17 maggio (+0)<br \/>\n<\/strong>1.151 contagiati in Calabria (58 ricoverati \u2013 364 isolamento \u2013 95 vittime \u2013 634 guariti)<\/p>\n<p><strong>Luned\u00ec 18 maggio (+0<\/strong><strong>)<br \/>\n<\/strong>1.151 contagiati in Calabria (55 ricoverati \u2013 346 isolamento \u2013 95 vittime \u2013 655 guariti)<\/p>\n<p><strong>Marted\u00ec 19 maggio (+2<\/strong><strong>)<br \/>\n<\/strong>1.153 contagiati in Calabria (52 ricoverati \u2013 330 isolamento \u2013 95 vittime \u2013 676 guariti)<\/p>\n<p><strong>Mercoled\u00ec 20 maggio (+<\/strong><strong>3)<br \/>\n<\/strong>1.156 contagiati in Calabria (50 ricoverati \u2013 303 isolamento \u2013 96 vittime \u2013 707 guariti)<\/p>\n<p><strong>Gioved\u00ec 21 maggio (+0)<br \/>\n<\/strong>1.156 contagiati in Calabria (48 ricoverati \u2013 278 isolamento \u2013 96 vittime \u2013 734 guariti)<\/p>\n<p><strong>Venerd\u00ec 22 maggio (+1)<br \/>\n<\/strong>1.157 contagiati in Calabria (48 ricoverati \u2013 254 isolamento \u2013 96 vittime \u2013759 guariti)<strong><br \/>\n<\/strong><\/p>\n<p><strong>Sabato 23 maggio (+0<\/strong><strong>)<\/strong><br \/>\n1.157 contagiati in Calabria (44 ricoverati \u2013 244 isolamento \u2013 96 vittime \u2013773 guariti)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nessun nuovo contagio in Calabria nelle ultime 24 ore a fronte di 1.045 tamponi analizzati. Gli attualmente positivi scendono sotto i 300 mentre i guariti salgono a 773<\/p>\n","protected":false},"author":55,"featured_media":130389,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[681],"class_list":["post-130388","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","tag-coronavirus"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/130388","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=130388"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/130388\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/130389"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=130388"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=130388"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=130388"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}