{"id":130496,"date":"2020-05-31T12:00:33","date_gmt":"2020-05-31T10:00:33","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/fase-2-e-agricoltura-creativa-dalladozione-delle-api-al-caciobond\/"},"modified":"2023-01-16T17:59:36","modified_gmt":"2023-01-16T16:59:36","slug":"355615-fase-2-e-agricoltura-creativa-dalladozione-delle-api-al-caciobond","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/355615-fase-2-e-agricoltura-creativa-dalladozione-delle-api-al-caciobond\/","title":{"rendered":"Fase 2 e agricoltura creativa: dall&#8217;adozione delle api al &#8220;caciobond&#8221;"},"content":{"rendered":"<h4>Dal disinfettante al rosmarino all&#8217;adozione delle arnie, dai caciobond ai kit per costruire il pranzo a domicilio, dalle cantine aperte sul web fino alle siepi anti contagio<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>ROMA &#8211; Sono tante le <strong>idee innovative degli agricoltori<\/strong> per far ripartire il Paese, in un mix di tradizione e tecnologia <strong>da nord a sud.<\/strong> A Monteaperti ad un passo da Siena, \u00e8 possibile <strong>adottare un&#8217;arnia<\/strong> a distanza per <strong>aiutare le api<\/strong> e contribuire alla difesa dell&#8217;ecosistema con la possibilit\u00e0 di scegliere il nome della propria Ape Regina, ricevere parte del miele e un certificato di adozione temporanea.<\/p>\n<p>In Campania invece, dove c&#8217;\u00e8 stato un <strong>crollo degli acquisti di mozzarella di bufala<\/strong>, il Caseificio Morese di Pontecagnano Faiano (Sa) con la Coldiretti ha lanciato i &#8216;<strong>caciobond<\/strong>&#8216;, attraverso i quali le persone comprano in anticipo i caciocavalli con latte di bufala per poi consumarlo quando \u00e8 pronto.<\/p>\n<p>In Toscana, invece per affrontare la crisi, vince <strong>l&#8217;agricosmetica<\/strong>, con il rosmarino che al posto di profumi ora serve per produrre gel disinfettante unito all&#8217;alcool alimentare di alcuni liquorifici.<\/p>\n<p>Molte aziende si sono dedicate alle consegne a domicilio dei prodotti freschi come in <strong>Piemonte<\/strong> dove si pu\u00f2 prenotare on line il menu da ritirare o ricevere a casa , con tanto di kit con le istruzioni per preparalo. In Toscana e Sicilia si sono inventati siepi anti contagio per bar, ristoranti, spiagge e locali pubblici con piante e fiori come barriere verdi per bloccare il droplet aereo portatore del virus.<\/p>\n<p>In Campania le cantine in collaborazione con Coldiretti hanno lanciato i <strong>&#8216;web wine tasting<\/strong>&#8216;, lezioni in diretta on line sulla <strong>degustazione del vino e dei formaggi<\/strong> in contemporanea dopo aver spedito a casa i campioni da assaggiare. Per i pi\u00f9 piccoli, infine, arrivano i tutorial sul web delle fattorie didattiche per raccontare il mondo che va dai pascoli ai fiori, dai frutti alle erbe.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dal disinfettante al rosmarino all&#8217;adozione delle arnie, dai caciobond ai kit per costruire il pranzo a domicilio, dalle cantine aperte sul web fino alle siepi anti contagio<\/p>\n","protected":false},"author":42,"featured_media":130497,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16],"tags":[],"class_list":["post-130496","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-italia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/130496","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=130496"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/130496\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/130497"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=130496"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=130496"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=130496"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}