{"id":130506,"date":"2020-05-26T08:16:54","date_gmt":"2020-05-26T06:16:54","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/occupazione-per-500-calabresi-tirocini-e-attivita-formative-innovative\/"},"modified":"2023-01-16T17:59:36","modified_gmt":"2023-01-16T16:59:36","slug":"355641-occupazione-per-500-calabresi-tirocini-e-attivita-formative-innovative","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/355641-occupazione-per-500-calabresi-tirocini-e-attivita-formative-innovative\/","title":{"rendered":"Occupazione, per 500 calabresi tirocini e attivit\u00e0 formative innovative"},"content":{"rendered":"<h4>Il progetto, coordinato dalla Regione Calabria, riguarda la promozione di politiche attive del lavoro e attivit\u00e0 formative innovative nel Mediterraneo<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>CATANZARO &#8211; Favorire l\u2019acquisizione di competenze utili all\u2019ingresso nel mercato del lavoro con particolare attenzione ai settori della economia verde e circolare. Questi gli obiettivi del progetto strategico coordinato dalla Regione Calabria <strong>\u201cGreen-skiLls for a sustAiNable Development \u2013 Greenland\u201d<\/strong> che \u00e8 stato approvato nell\u2019ambito della call del programma Eni Cbc Med, la pi\u00f9 grande iniziativa di cooperazione transfrontaliera (CBC) nel Mediterraneo attuata dall&#8217;UE.<\/p>\n<p>Greenland Si propone come strumento in grado di attivare una serie di azioni e di percorsi di formazione specifiche, rivolte ai Neet e alle donne disoccupate residenti in Calabria e Sicilia, per facilitare l\u2019inserimento lavorativo e l\u2019occupazione. La Regione Calabria si avvarr\u00e0, inoltre, della collaborazione di prestigiosissimi organismi pubblici rappresentanti di ben sette Paesi del Mediterraneo (Italia, Portogallo, Grecia, Libano, Giordania, Egitto e Palestina) che si occupano di <strong>istruzione e formazione professionale<\/strong> (IeFP), politiche attive del lavoro (PAL) e salvaguardia dell\u2019ambiente, per scambiare esperienze e metodologie finalizzate allo sviluppo di corsi di formazione (joint policy learning) per figure chiave nei suddetti settori. Si affianca al progetto anche il Parco Nazionale della Sila, in qualit\u00e0 di partner associato, che ha gi\u00e0 collaborato sul territorio con la Regione Calabria producendo riscontri significativi con i Piani Locali per il Lavoro, e nello specifico con il Pll Sila.<\/p>\n<p>\u201cL\u2019approvazione del progetto Greenland nell\u2019ambito del Programma Eni Cbc Med, un hub altamente strategico per la cooperazione nel Mediterraneo \u2013 ha dichiarato Jole Santelli, Presidente della Regione Calabria &#8211; rappresenta un grande risultato e conferma la capacit\u00e0 della Calabria di avere un ruolo di primo piano tra le regioni del bacino Mediterraneo per promuovere azioni che rendano quest\u2019area un laboratorio di innovazione e inclusivit\u00e0. Il Progetto Greenland, nello specifico, ci consente di intervenire a favore dell\u2019occupabilit\u00e0 di oltre <strong>1700 soggetti tra giovani e donne residenti nei territori dei Partner del Mediterraneo<\/strong>, <strong>di cui 500 tra Calabria e Sicilia<\/strong>, a cui saranno destinate iniziative di politica attiva del lavoro e beneficeranno di attivit\u00e0 formative innovative. Saranno realizzati percorsi di tirocinio, ospitati da imprese italiane o dei Paesi partner del Mediterraneo, e saranno attivati interventi di tutoraggio, e-learning, mentorship, coaching e creazione di alleanze di competenze settoriali tra piccole e medie imprese italiane, enti di formazione ed una vasta rete di istituzioni pubbliche e private. <strong>Sar\u00e0 cos\u00ec possibile produrre effetti di lunga durata sull&#8217;occupazione diretta e indiretta<\/strong> e sullo sviluppo dell&#8217;imprenditorialit\u00e0 anche a livello locale. \u00c8 fondamentale agire insieme per affrontare queste sfide e migliorare la vita di uomini e donne della nostra regione e dell\u2019intera area mediterranea\u201d.<\/p>\n<p>Il progetto strategico Greenlad prevede, inoltre,<strong> attivit\u00e0 di job shadowing e policy learning, cio\u00e8 almeno 3 visite all\u2019estero<\/strong> presso enti pubblici riservate al personale chiave delle istituzioni ed autorit\u00e0 politiche coinvolte nel progetto, e la elaborazione di un \u201cPiano di Azione per il Lavoro nel Mediterraneo\u201d contenente buone prassi e suggerimenti da parte dei Partner per innovare i PAL regionali, che serviranno ad aumentare l\u2019impatto atteso degli investimenti futuri sulla crescita e sull\u2019occupazione dei territori di cui la Calabria \u00e8 il baricentro di elezione.<\/p>\n<p>Greenlad \u00e8 stato approvato nell\u2019ambito dell&#8217;invito a presentare progetti strategici del programma Eni Cbc Med che ha selezionato complessivamente <strong>22 proposte progettuali per un valore di 78,8 milioni di euro<\/strong>, che hanno l&#8217;ambizione di produrre cambiamenti significativi di lunga durata e di vasta portata in settori tematici chiave dell\u2019area mediterranea per renderla pi\u00f9 competitiva, innovativa, inclusiva e sostenibile: tra questi lo sviluppo di start-up, il rafforzamento di cluster economici, il trasferimento di tecnologia, l\u2019occupabilit\u00e0 di giovani e donne, la gestione dei rifiuti e l\u2019efficienza energetica.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il progetto, coordinato dalla Regione Calabria, riguarda la promozione di politiche attive del lavoro e attivit\u00e0 formative innovative nel Mediterraneo<\/p>\n","protected":false},"author":56,"featured_media":130507,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-130506","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/130506","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/56"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=130506"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/130506\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/130507"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=130506"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=130506"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=130506"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}