{"id":130630,"date":"2020-05-27T18:00:45","date_gmt":"2020-05-27T16:00:45","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/scuola-alle-elementari-ritorna-il-giudizio-addio-ai-voti-numerici\/"},"modified":"2023-01-16T17:59:44","modified_gmt":"2023-01-16T16:59:44","slug":"355974-scuola-alle-elementari-ritorna-il-giudizio-addio-ai-voti-numerici","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/355974-scuola-alle-elementari-ritorna-il-giudizio-addio-ai-voti-numerici\/","title":{"rendered":"Scuola: alle elementari ritorna il giudizio, addio ai voti numerici"},"content":{"rendered":"<h4 class=\"news-stit\">Emendamento Pd in Commissione entra in vigore dal prossimo anno<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>ROMA &#8211; Dal prossimo anno scolastico la valutazione finale degli alunni nella scuola elementare non sar\u00e0 pi\u00f9 espressa con i voti numerici ma con un<strong> giudizio.<\/strong> E&#8217;quanto prevede un emendamento presentato dai senatori <strong>Verducci, Iori e Ramp<\/strong>i e approvato in Commissione Cultura e Istruzione. &#8220;<strong>L&#8217;emendamento prevede che nella scuola primaria i bambini non possano essere considerati dei numeri.<\/strong> Dare un 4 pu\u00f2 essere un macigno pesante da comprendere mentre una valutazione pi\u00f9 complessiva prende in considerazione le caratteristiche del bambino. Ovviamente vanno trovate le parole adeguate e <strong>la valutazione va fatta in termini di giudizio sintetico<\/strong>&#8220;, spiega la senatrice Vanna Iori. &#8220;Il giudizio tiene conto della specificit\u00e0 e della individualit\u00e0 di ogni singolo bambino &#8211; aggiunge &#8211; mentre il <strong>voto numerico livella e rende tutti uguali<\/strong>, anche se ci sono diverse motivazioni dietro a quel voto&#8221;.<\/p>\n<p>Intesa nella maggioranza sulle modifiche al dl sulla scuola. E&#8217; stato presentato l&#8217;emendamento a firma del relatore al dl, che sar\u00e0 messo ai voti in commissione al Senato questa mattina e che sintetizza l&#8217;accordo sul<strong> concorso straordinario per i precari.<\/strong> Il concorso con la prova scritta si terr\u00e0 nel corso dell&#8217;anno scolastico 2020-2021 &#8211; si legge nel testo &#8211; e prevede quesiti a risposta aperta. Rispetto alla prima formulazione respinta da Pd e LeU scompare la precisazione del numero dei quesiti. &#8220;<strong>Non \u00e8 soddisfacente al 100% ma \u00e8 un passo in avanti<\/strong>&#8220;, dice la senatrice di LeU <strong>Loredana De Petris<\/strong> confermando il s\u00ec all&#8217;emendamento sul concorso per i precari della scuola presentato in commissione a Palazzo Madama, e su cui c&#8217;\u00e8 dunque l&#8217;intesa all&#8217;interno della maggioranza, e che sar\u00e0 messo ai voti in mattinata. L&#8217;accordo per\u00f2 non convince Francesco Verducci (PD) che ha presentato 3 subemendamenti perch\u00e9, spiega, &#8220;la norma non assicura il <strong>giusto percorso per la stabilizzazione dei precari<\/strong>&#8220;.<\/p>\n<p>&#8220;Il ripensamento non c&#8217;\u00e8 stato. L&#8217;emendamento della relatrice in commissione Cultura del Senato sul concorso straordinario conferma che il governo non ha alcuna intenzione di tenere conto dell&#8217;emergenza epidemiologica, la quale consiglierebbe di<strong> puntare sul rafforzamento e la stabilizzazione dell&#8217;organico docenti.<\/strong> Se trover\u00e0 conferma &#8211; come sembra &#8211; la marcia indietro di Pd e Leu, nuovamente appiattiti sulle posizioni dei 5 Stelle, il prossimo anno scolastico partir\u00e0 con <strong>zero assunzioni a tempo indeterminato; anzi, 30 mila precari in pi\u00f9 a seguito dei pensionamenti<\/strong>, che porteranno il <strong>totale dei supplenti a 200 mila.<\/strong> Il contrario dell&#8217;impegno su nostra sollecitazione preso nelle ultime settimane &#8211; a parole &#8211; da esponenti della quasi totalit\u00e0 delle forze politiche di garantire tutti gli insegnanti titolari in cattedra il prossimo settembre, per affrontare con la dovuta efficacia la crisi pandemica, a partire dalla necessit\u00e0 di <strong>sdoppiare le classi per consentire i distanziamenti.<\/strong> Fa rabbia pensare che la soluzione ci sarebbe e sta nella nostra proposta di assunzione da graduatorie, gi\u00e0 utilizzata per le Gae&#8221;. Lo dichiara il senatore <strong>Mario Pittoni,<\/strong> presidente della commissione Cultura a palazzo Madama e responsabile Istruzione della Lega.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Emendamento Pd in Commissione entra in vigore dal prossimo anno<\/p>\n","protected":false},"author":22,"featured_media":130631,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16,53],"tags":[],"class_list":["post-130630","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-italia","category-ck20-scuola"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/130630","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=130630"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/130630\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/130631"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=130630"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=130630"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=130630"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}