{"id":130752,"date":"2020-05-29T15:45:26","date_gmt":"2020-05-29T13:45:26","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/marche-da-bollo-clonate-e-titoli-falsi-tra-bologna-e-catanzaro-16-persone-nei-guai\/"},"modified":"2023-01-16T17:59:52","modified_gmt":"2023-01-16T16:59:52","slug":"356325-marche-da-bollo-clonate-e-titoli-falsi-tra-bologna-e-catanzaro-16-persone-nei-guai","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/356325-marche-da-bollo-clonate-e-titoli-falsi-tra-bologna-e-catanzaro-16-persone-nei-guai\/","title":{"rendered":"Marche da bollo clonate e titoli falsi tra Bologna e Catanzaro: 16 persone nei guai"},"content":{"rendered":"<h4>Per 5 persone anche l&#8217;ipotesi di associazione a delinquere finalizzata alla falsificazione o messa in circolazione di valori bollati contraffatti, uso di titoli di credito falsificati e indebito utilizzo di carte di credito<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>BOLOGNA &#8211; La Procura di Bologna ha chiuso le indagini per <strong>16 persone, di cui cinque accusate di associazione a delinquere<\/strong> finalizzata alla falsificazione o messa in circolazione di valori bollati contraffatti, uso di titoli di credito falsificati e indebito utilizzo di carte di credito. L&#8217;inchiesta del pm Bruno Fedeli contesta <strong>episodi commessi tra gennaio 2016 e marzo 2019, tra Bologna e Catanzaro.<\/strong> Gli indagati, difesi tra l&#8217;altro dagli avvocati Matteo Murgo, Massimo Fuzzi, Ercole Cavarretta, Bruno Salernitano, ora hanno 20 giorni di tempo per presentare memorie o chiedere di essere interrogati.<\/p>\n<p>In particolare alcuni di loro avrebbero <strong>acquistato circa 7.500 marche da bollo in Calabria, le avrebbero quindi portate a Bologna e clonate<\/strong>, cos\u00ec da distribuirne<strong> circa duemila ad alcune agenzie di pratiche auto<\/strong>: anche quattro, tra dipendenti e titolari, sono indagati per l&#8217;utilizzo delle marche. In un altro capo di imputazione si contesta invece <strong>l&#8217;utilizzo di titoli di credito contraffatti: un indagato ne avrebbe ricevuti per 100mila euro e poi consegnati altri due, per portarli all&#8217;incasso.<\/strong> Infine \u00e8 contestato un <strong>indebito utilizzo di carte<\/strong>: attraverso un indirizzo email avrebbero fatto <strong>prenotazioni alberghiere per almeno 74mila euro,<\/strong> con carte clonate. Poi avrebbero annullato le prenotazioni, chiedendo la restituzione della caparra e <strong>incassando circa 16mila euro.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Per 5 persone anche l&#8217;ipotesi di associazione a delinquere finalizzata alla falsificazione o messa in circolazione di valori bollati contraffatti, uso di titoli di credito falsificati e indebito utilizzo di carte di credito<\/p>\n","protected":false},"author":22,"featured_media":130753,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17,16],"tags":[],"class_list":["post-130752","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","category-italia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/130752","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=130752"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/130752\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/130753"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=130752"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=130752"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=130752"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}